{"id":35112,"date":"2020-08-25T19:34:52","date_gmt":"2020-08-25T23:34:52","guid":{"rendered":"http:\/\/www.jdx.info\/lutte\/?p=35112"},"modified":"2020-08-25T19:34:56","modified_gmt":"2020-08-25T23:34:56","slug":"cest-officiel-wade-barrett-de-retour-a-la-wwe-mais-une-mauvaise-nouvelle-vient-avec","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2020\/08\/25\/cest-officiel-wade-barrett-de-retour-a-la-wwe-mais-une-mauvaise-nouvelle-vient-avec\/","title":{"rendered":"C&rsquo;est Officiel: Wade Barrett De Retour \u00e0 La WWE! Mais Une Mauvaise Nouvelle Vient Avec!"},"content":{"rendered":"\n<p>Wade Barrett est parti de la WWE en 2016. Son contrat avec la WWE avait pris fin et avait d\u00e9cid\u00e9 de lui m\u00eame de ne pas le prolonger avec une offre de plusieurs centaines de milliers de dollars sur la table. Et bien il fera un court retour aux sources avec la f\u00e9d\u00e9ration cette semaine.<\/p>\n\n\n\n<p>Ryan Satin PWS qui nous apprend que Stu Benett de son vrai nom,viendra pour une soir\u00e9e seulement.\u00a0On pourra en effet le revoir \u00e0 NXT, plus pr\u00e9cis\u00e9ment l&rsquo;entendre aux commentaires du show\u00a0puisqu&rsquo;il sera dans l&rsquo;\u00e9quipe des commentateurs.<\/p>\n\n\n\n<p>Rien ne dit qu&rsquo;il sera ou pas impliqu\u00e9 physiquement pour un d\u00e9veloppement d&rsquo;une histoire ou pas. Mais ceux qui r\u00eavaient de le revoir avec NEXUS en d\u00e9but d&rsquo;ann\u00e9e peuvent toujours esp\u00e9rer. <\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Wade Barrett est parti de la WWE en 2016. Son contrat avec la WWE avait pris fin et avait d\u00e9cid\u00e9 de lui m\u00eame de ne pas le prolonger avec une offre de plusieurs centaines de milliers de dollars sur la table. Et bien il fera un court retour aux sources avec la f\u00e9d\u00e9ration cette semaine&#8230;.<\/p>\n","protected":false},"author":4,"featured_media":35113,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,23],"tags":[],"ppma_author":[292],"class_list":["post-35112","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-wwe"],"authors":[{"term_id":292,"user_id":4,"is_guest":0,"slug":"jean","display_name":"Jean Vinnier","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/33aba0263fd870a0b487e0e079ff407e10e3997c9d2987cbcc0db0db2c5c75a9?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/35112","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=35112"}],"version-history":[{"count":1,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/35112\/revisions"}],"predecessor-version":[{"id":35114,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/35112\/revisions\/35114"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/35113"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=35112"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=35112"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=35112"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=35112"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}