{"id":34158,"date":"2020-08-15T14:38:41","date_gmt":"2020-08-15T18:38:41","guid":{"rendered":"http:\/\/www.jdx.info\/lutte\/?p=34158"},"modified":"2020-08-15T14:38:46","modified_gmt":"2020-08-15T18:38:46","slug":"booker-t-explique-pourquoi-il-a-refuse-de-travailler-avec-matt-morgan-a-tna","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2020\/08\/15\/booker-t-explique-pourquoi-il-a-refuse-de-travailler-avec-matt-morgan-a-tna\/","title":{"rendered":"Booker T explique pourquoi il a refus\u00e9 de travailler avec Matt Morgan \u00e0 TNA!"},"content":{"rendered":"\n<p>Lors d&rsquo;un \u00e9pisode r\u00e9cent de son podcast Hall of Fame, Booker T a expliqu\u00e9 en d\u00e9tail pourquoi il avait refus\u00e9 de faire un travail pour Matt Morgan \u00e0 l&rsquo;\u00e9poque de la TNA. Voici ce qu\u2019il avait \u00e0 dire :<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>Moi et Matt, nous nous sommes toujours entendus. Nous avons toujours eu de la camaraderie. Nous avons toujours eu une sorte de communion lorsque nous \u00e9tions ensemble aussi. Cela n&rsquo;avait rien \u00e0 voir avec Matt Morgan \u00e0 part le fait que je travaillais avec Matt Morgan et on m&rsquo;a dit que vous alliez travailler avec Matt Morgan. En m\u00eame temps, Kurt Angle et moi avons eu des frictions avec la mafia du Main Event. . Par cons\u00e9quent, nous allions injecter Kurt Angle dans cet angle pour travailler Matt Morgan, Kurt Angle sortait, distraction, Matt vous frappe avec le boom, le gros gimmick, 1-2-3-, boom, nous faisons passer Matt Morgan. J&rsquo;\u00e9tais comme, \u00ab\u00a0Ouais, d&rsquo;accord, je suis cool avec \u00e7a, pas grand-chose.\u00a0\u00bb<\/p><p>Quand nous sommes revenus \u00e0 la t\u00e9l\u00e9, en fait pour faire le match avec Matt Morgan apr\u00e8s le fiasco qui s&rsquo;est produit et que je suis sorti. Je suppose qu&rsquo;ils allaient me punir, et pas seulement me punir, mais me faire mal para\u00eetre en m\u00eame temps. Je ne me souviens pas de qui c&rsquo;\u00e9tait, c&rsquo;\u00e9tait peut-\u00eatre Pat Buck ou quelqu&rsquo;un comme \u00e7a, je ne me souviens pas de qui c&rsquo;\u00e9tait, mais je me souviens qu&rsquo;ils sont venus me voir et m&rsquo;ont dit : Hey Book, nous avons chang\u00e9 la finition du Match de Matt Morgan, Kurt Angle ne va pas sortir maintenant et faire quoi que ce soit. Matt va juste te battre en plein milieu du ring, peut-\u00eatre un match de six minutes et nous allons simplement avancer \u00e0 partir de l\u00e0. \u00a0\u00bb Et je l&rsquo;ai regard\u00e9, et je me suis dit: OK, laissez-moi y r\u00e9fl\u00e9chir pendant une seconde&rsquo;.&rsquo; Et litt\u00e9ralement, j&rsquo;y ai pens\u00e9 pendant une seconde, et je me suis dit : &lsquo;J&rsquo;y ai pens\u00e9, \u00e7a n&rsquo;arrivera pas, d&rsquo;accord?&rsquo; &lsquo;Qu&rsquo;est-ce qui ne va pas?&rsquo;  J&rsquo;ai dit :  Cela n&rsquo;arrivera pas. Cela m&rsquo;a boulevers\u00e9 parce que c&rsquo;\u00e9tait comme si c&rsquo;\u00e9tait une punition.<\/p><p>J&rsquo;\u00e9tais pr\u00eat \u00e0 aller l\u00e0-bas et \u00e0 le faire comme nous l&rsquo;avions d\u00e9j\u00e0 pr\u00e9vu avec Kurt et cela aurait \u00e9t\u00e9 parfaitement bien, il aurait obtenu ce dont il avait besoin, ils auraient obtenu ce dont ils avaient besoin . Et puis je me souviens que Terry Taylor est revenu et il a dit: \u00abHey Book, qu&rsquo;est-ce qui se passe? J&rsquo;ai entendu dire que tu n&rsquo;allais pas mettre Matt dessus. J&rsquo;ai dit: Non, je ne fais pas \u00e7a, c&rsquo;est ridicule, maintenant, tout d&rsquo;un coup, je mets un mec en cinq minutes alors que c&rsquo;\u00e9tait d&rsquo;une certaine mani\u00e8re il n&rsquo;y a m\u00eame pas quelques semaines. Et puis il dit: \u00a0\u00bbD&rsquo;accord, laisse-moi aller parler \u00e0 quelqu&rsquo;un\u00a0\u00bb. Alors il est parti, est all\u00e9 parler \u00e0 quelqu&rsquo;un, et est revenu et a dit: D&rsquo;accord, nous allons faire C&rsquo;est la fa\u00e7on dont nous nous \u00e9tions arrang\u00e9s avec Kurt Angle faisant l&rsquo;affaire.  Et puis je dis : Apr\u00e8s y avoir r\u00e9fl\u00e9chi, je ne peux m\u00eame pas faire \u00e7a maintenant parce que vous m&rsquo;avez manqu\u00e9 de respect. J&rsquo;ai dit : &lsquo;Ma derni\u00e8re nuit va \u00eatre au PPV et puis je vais aller au coucher au soleil et vous irez o\u00f9 que vous alliez&rsquo;<\/p><p>Matt Morgan est venu me voir et il a dit : Booker, nous avons de la tension ou quoi que ce soit?  J&rsquo;ai dit:  Naw Matt, cela n&rsquo;a rien \u00e0 voir avec toi, aucune autre circonstance, cela ne serait arriv\u00e9, mais crois-moi, cela a rien \u00e0 voir avec toi. Donc, Matt Morgan et moi, nous n&rsquo;avons jamais eu de friction ou quoi que ce soit du genre, mais je pensais juste que la soci\u00e9t\u00e9 avait d\u00e9finitivement laiss\u00e9 tomber la balle et essay\u00e9 de me faire mal para\u00eetre en m\u00eame temps.<\/p><\/blockquote>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Lors d&rsquo;un \u00e9pisode r\u00e9cent de son podcast Hall of Fame, Booker T a expliqu\u00e9 en d\u00e9tail pourquoi il avait refus\u00e9 de faire un travail pour Matt Morgan \u00e0 l&rsquo;\u00e9poque de la TNA. Voici ce qu\u2019il avait \u00e0 dire : Moi et Matt, nous nous sommes toujours entendus. Nous avons toujours eu de la camaraderie. Nous&#8230;<\/p>\n","protected":false},"author":665,"featured_media":34367,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[30,4,41],"tags":[],"ppma_author":[289],"class_list":["post-34158","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ex-wwe","category-news","category-tna-impact"],"authors":[{"term_id":289,"user_id":665,"is_guest":0,"slug":"line","display_name":"Line Edmond","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/852de09636413c90cdaa278312f9ea5bc4396768745424755cb63d99a05989d0?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/34158","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/665"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=34158"}],"version-history":[{"count":2,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/34158\/revisions"}],"predecessor-version":[{"id":34368,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/34158\/revisions\/34368"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/34367"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=34158"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=34158"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=34158"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=34158"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}