{"id":33241,"date":"2020-07-31T17:43:28","date_gmt":"2020-07-31T21:43:28","guid":{"rendered":"http:\/\/www.jdx.info\/lutte\/?p=33241"},"modified":"2020-07-31T17:43:31","modified_gmt":"2020-07-31T21:43:31","slug":"vince-mcmahon-parle-de-la-aew-et-de-nxt-un-rafraichissement-pour-raw-et-smackdown-et-plus","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2020\/07\/31\/vince-mcmahon-parle-de-la-aew-et-de-nxt-un-rafraichissement-pour-raw-et-smackdown-et-plus\/","title":{"rendered":"Vince McMahon Parle De La AEW et de NXT! Un Rafra\u00eechissement Pour RAW et Smackdown, et Plus!"},"content":{"rendered":"\n<p>Les audiences de RAW et de SmackDown sont en chute depuis la le d\u00e9but de la pand\u00e9mie de la COVID-19 et l&rsquo;aurait \u00e9t\u00e9 de toute fa\u00e7on poste WrestleMania et en \u00e9t\u00e9 mais c&rsquo;est encore pire cette ann\u00e9e.  Sauf pour NXT donc la baisse est moindre. <\/p>\n\n\n\n<p>Du c\u00f4t\u00e9 de la AEW, les choses vont bien puisque l&rsquo;audience reste stable plus ou moins chaque semaine  mais nous n&rsquo;avons pas de comparatifs des ann\u00e9es pr\u00e9c\u00e9dentes.<\/p>\n\n\n\n<p>Vince McMahon avait expliqu\u00e9 que\u00a0le manque de spectateurs faisait tr\u00e8s mal et cela commence \u00e0 se faire sentir dans les autres sports qui reprennent petit \u00e0 petit avec les fans qui se plaignent du manque d&rsquo;ambiance eut aussi. Le chairman avait parl\u00e9 de cette cons\u00e9quence lors d&rsquo;une conf\u00e9rence t\u00e9l\u00e9phonique avec les actionnaires le 30 juillet dernier o\u00f9 il pr\u00e9sentait les \u00e9tats financiers pour le deuxi\u00e8me trimestre. <\/p>\n\n\n\n<p>Lors de la s\u00e9ance de questions, la premi\u00e8re question a encore une fois \u00e9t\u00e9 port\u00e9e sur les audiences. On lui a demand\u00e9 plus de d\u00e9tails sur sa strat\u00e9gie pour remonter les audiences alors que le produit est toujours en chute, \u00e0 comparer \u00e0 NXT et la AEW qui gardent leur succ\u00e8s. Vince McMahon a expliqu\u00e9 que selon lui, le produit nouveau de NXT et de la AEW permet de garder leur audience stable :<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u00a0\u00bbJe pense que d\u00fb au fait qu&rsquo;ils sont nouveaux. C&rsquo;est quelque chose de neuf, c&rsquo;est \u00e0 nous de faire en sorte que RAW et SmackDown donnent une sensation de nouveaut\u00e9s. C&rsquo;est vers l\u00e0 que nous allons.\u00a0\u00bb<\/p><\/blockquote>\n\n\n\n<p>Vince McMahon a ajout\u00e9 plus tard qu&rsquo;ils avaient pour intention de rajeunir le produit en cr\u00e9ant des stars plus convaincantes et se concentrer sur les personnages, en racontant de meilleures histoires sur le ring et hors du ring,  comme il n&rsquo;y a pas de spectateurs. <\/p>\n\n\n\n<p>Rappelons \u00e9galement qu&rsquo;il est plus facile pour la AEW et NXT de se maintenir entre 700 000 et 1 millions de personnes \u00e0 l&rsquo;\u00e9coutes que du 3 millions pour RAW et Smackdown surtout avec l&rsquo;\u00e9t\u00e9 et le super beau temps qu&rsquo;il fait depuis le mois de juin en Am\u00e9rique. Qui reste \u00e0 regarder la t\u00e9l\u00e9 en direct par du tr\u00e8s beau temps? <\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Les audiences de RAW et de SmackDown sont en chute depuis la le d\u00e9but de la pand\u00e9mie de la COVID-19 et l&rsquo;aurait \u00e9t\u00e9 de toute fa\u00e7on poste WrestleMania et en \u00e9t\u00e9 mais c&rsquo;est encore pire cette ann\u00e9e. Sauf pour NXT donc la baisse est moindre. Du c\u00f4t\u00e9 de la AEW, les choses vont bien puisque&#8230;<\/p>\n","protected":false},"author":2,"featured_media":33242,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38,50,4,23],"tags":[],"ppma_author":[287],"class_list":["post-33241","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aew","category-dynamite","category-news","category-wwe"],"authors":[{"term_id":287,"user_id":2,"is_guest":0,"slug":"jason","display_name":"Jason Desc\u00f4teaux","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/f64adf6d13198c3a532c061cecd8672089a1e9a3d07c702dffe886a7e55a15eb?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/33241","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=33241"}],"version-history":[{"count":1,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/33241\/revisions"}],"predecessor-version":[{"id":33243,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/33241\/revisions\/33243"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/33242"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=33241"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=33241"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=33241"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=33241"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}