{"id":32555,"date":"2020-07-22T14:17:51","date_gmt":"2020-07-22T18:17:51","guid":{"rendered":"http:\/\/www.jdx.info\/lutte\/?p=32555"},"modified":"2020-07-22T15:00:26","modified_gmt":"2020-07-22T19:00:26","slug":"impact-annonce-que-slammiversary-a-battu-des-records-de-medias-sociaux","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2020\/07\/22\/impact-annonce-que-slammiversary-a-battu-des-records-de-medias-sociaux\/","title":{"rendered":"IMPACT annonce que Slammiversary a battu des records de m\u00e9dias sociaux!"},"content":{"rendered":"\n<p>IMPACT Wrestling a publi\u00e9 le communiqu\u00e9 de presse annon\u00e7ant que  le PPV Slammiversary de samedi dernier a battu des records de m\u00e9dias sociaux pour l&rsquo;entreprise avec des engagements record. <\/p>\n\n\n\n<p> <strong><a href=\"https:\/\/www.jdx.info\/lutte\/2020\/07\/18\/resultats-video-ppv-slammiversary-2020-encore\/\">Pour les r\u00e9sultats ou voir Slammiversary, cliquez ici.<\/a><\/strong> <\/p>\n\n\n\n<p><strong>Les d\u00e9tails :<\/strong><\/p>\n\n\n\n<p>Nashville &#8211; (21 juillet 2020) &#8211; IMPACT Wrestling tirait \u00e0 tous les cylindres samedi soir alors que Slammiversary 2020 est devenu le plus grand \u00e9v\u00e9nement en direct de la soci\u00e9t\u00e9 depuis des ann\u00e9es, comme le montrent les statistiques des m\u00e9dias sociaux publi\u00e9es. L&rsquo;\u00e9v\u00e9nement \u00e0 la carte du 18 juillet a domin\u00e9 les conversations sur les r\u00e9seaux sociaux, avec #Slammiversary toujours en t\u00eate des \u00c9tats-Unis sur Twitter.<\/p>\n\n\n\n<p>Les r\u00e9v\u00e9lations tant attendues des superstars de la lutte d&rsquo;agent libre rejoignant la liste d&rsquo;IMPACT Wrestling ont aliment\u00e9 la conversation et l&rsquo;engagement sur les plates-formes num\u00e9riques: les \u00e9quipes de tags populaires The Good Brothers (Doc Gallows et Karl Anderson) et les Motor City Machine Guns (Alex Shelley et Chris Sabin) ), d&rsquo;anciens champions du monde EC3 et Eric Young, et l&rsquo;autoproclam\u00e9 \u00abagent libre le plus chaud du march\u00e9\u00bb Heath. De nombreuses apparitions dans les \u00e9missions ont \u00e9galement suscit\u00e9 des sujets de tendance sur Twitter aux \u00c9tats-Unis.<\/p>\n\n\n\n<p>Avec chaque titre IMPACT en jeu, Slammiversary 2020 a vu trois nouveaux champions couronn\u00e9s dans des matchs qui sont instantan\u00e9ment devenus des pr\u00e9tendants au match de l&rsquo;ann\u00e9e: Eddie Edwards remportant la bataille de l&rsquo;\u00e9v\u00e9nement principal pour le championnat du monde IMPACT vacant, la nouvelle venue Deonna Purrazzo battant Jordynne Grace \u00e0 capturer le championnat Knockouts et Chris Bey remportant le championnat X-Division avec sa victoire sur Willie Mack.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u00abIMPACT Wrestling a attir\u00e9 l\u2019attention du monde samedi soir\u00bb, a d\u00e9clar\u00e9 Scott D\u2019Amore, vice-pr\u00e9sident ex\u00e9cutif d\u2019IMPACT Wrestling. \u00abSlammiversary 2020 est le r\u00e9sultat de deux ans et demi de travail acharn\u00e9 de notre \u00e9quipe incroyable et de notre talentueux alignement, ainsi que de nouveaux ajouts qui ont d\u00e9cid\u00e9 de parier sur IMPACT.\u00bb<\/p><\/blockquote>\n\n\n\n<p>Sur Twitter, Slammiversary 2020 a battu le record d&rsquo;IMPACT d&rsquo;impressions totales sur une seule journ\u00e9e (Slammiversary 2018), doublant presque le record pr\u00e9c\u00e9dent de 97%. En t\u00eate de la journ\u00e9e, l\u2019annonce vid\u00e9o exclusive \u00e0 minuit de The Good Brothers, qui est rapidement devenu le tweet le plus performant d\u2019IMPACT de tous les temps, tandis que les tweets mettant en vedette le retour de Motor City Machine Gun et la victoire de Purrazzo se classent d\u00e9sormais comme leurs cinqui\u00e8me et sixi\u00e8me meilleurs, respectivement.<\/p>\n\n\n\n<p>L&rsquo;engagement d&rsquo;Instagram pour Slammiversary 2020 a vu une augmentation de 172% du nombre total de likes en une journ\u00e9e par rapport au record pr\u00e9c\u00e9dent (Hard To Kill 2020), alors que les publications vid\u00e9o sur le retour d&rsquo;EY et les d\u00e9buts de Heath sont devenues les deux publications les plus appr\u00e9ci\u00e9es d&rsquo;IMPACT.<\/p>\n\n\n\n<p>Au cours du mois pr\u00e9c\u00e9dant le Slammiversary 2020, la cha\u00eene YouTube d&rsquo;IMPACT a vu son nombre total de vues augmenter de 26,5% et la dur\u00e9e totale de visionnage de 32%. La cha\u00eene, qui se classe d\u00e9j\u00e0 comme le deuxi\u00e8me compte de lutte le plus abonn\u00e9 sur la plate-forme, a ajout\u00e9 plus de 100000 nouveaux abonn\u00e9s, marquant une augmentation de 20% du taux d&rsquo;abonnement mensuel.<\/p>\n\n\n\n<p>IMPACT Wrestling pr\u00e9sente chaque semaine des actions percutantes et de haut vol aux \u00c9tats-Unis avec IMPACT! sur AXS TV et Twitch, premi\u00e8re de la s\u00e9rie phare de deux heures les mardis \u00e0 20 h. HE \/ 17 h PT. Lors de la diffusion du Slammiversary, IMPACT a annonc\u00e9 la date de son prochain \u00e9v\u00e9nement en direct Bound For Glory 2020, fix\u00e9 pour le samedi 24 octobre \u00e0 la carte.<\/p>\n\n\n\n<p>Les t\u00e9l\u00e9spectateurs du monde entier peuvent regarder le contenu IMPACT Wrestling sur une vari\u00e9t\u00e9 de plates-formes et d&rsquo;appareils, y compris le service IMPACT<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong><a href=\"https:\/\/www.jdx.info\/lutte\/2020\/07\/18\/resultats-video-ppv-slammiversary-2020-encore\/\">Pour les r\u00e9sultats ou voir Slammiversary, cliquez ici.<\/a><\/strong><\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>IMPACT Wrestling a publi\u00e9 le communiqu\u00e9 de presse annon\u00e7ant que le PPV Slammiversary de samedi dernier a battu des records de m\u00e9dias sociaux pour l&rsquo;entreprise avec des engagements record. Pour les r\u00e9sultats ou voir Slammiversary, cliquez ici. Les d\u00e9tails : Nashville &#8211; (21 juillet 2020) &#8211; IMPACT Wrestling tirait \u00e0 tous les cylindres samedi soir&#8230;<\/p>\n","protected":false},"author":665,"featured_media":32587,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,63,41],"tags":[],"ppma_author":[289],"class_list":["post-32555","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-slammiversary-impact","category-tna-impact"],"authors":[{"term_id":289,"user_id":665,"is_guest":0,"slug":"line","display_name":"Line Edmond","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/852de09636413c90cdaa278312f9ea5bc4396768745424755cb63d99a05989d0?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/32555","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/665"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=32555"}],"version-history":[{"count":4,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/32555\/revisions"}],"predecessor-version":[{"id":32603,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/32555\/revisions\/32603"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/32587"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=32555"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=32555"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=32555"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=32555"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}