{"id":32040,"date":"2020-07-17T20:44:06","date_gmt":"2020-07-18T00:44:06","guid":{"rendered":"http:\/\/www.jdx.info\/lutte\/?p=32040"},"modified":"2020-07-18T23:37:17","modified_gmt":"2020-07-19T03:37:17","slug":"deuxieme-heure-du-wwe-friday-night-smackdow-17-juillet-2020","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2020\/07\/17\/deuxieme-heure-du-wwe-friday-night-smackdow-17-juillet-2020\/","title":{"rendered":"Deuxi\u00e8me Heure du WWE Friday Night Smackdow 17 Juillet 2020!"},"content":{"rendered":"\n<p><a href=\"https:\/\/www.jdx.info\/lutte\/2020\/07\/17\/regardez-le-wwe-friday-night-smackdown-17-juillet-2020\/\"><strong>Pour revenir \u00e0 la premier heure de Smackdown, cliquez ici.<\/strong><\/a><\/p>\n\n\n\n<p>&#8211; C&rsquo;est le moment de la Firefly Fun House. Bray Wyatt est dans les mar\u00e9cages et chantonne sa musique. Wyatt dit que c&rsquo;est beau, le serpent est de la m\u00eame couleur que les feuilles. Quand Braun Strowman a pos\u00e9 le pied pour la premi\u00e8re fois ici, c&rsquo;\u00e9tait un mouton perdu \u00e0 la recherche d&rsquo;une maison. Il l&rsquo;a trouv\u00e9e. Il lui a donn\u00e9 la v\u00e9rit\u00e9. Il lui a donn\u00e9 un but. Il a cr\u00e9\u00e9 un monstre. Puis il est parti, enfin&#8230; c&rsquo;est ce qu&rsquo;il pensait. Ici, c&rsquo;est l&rsquo;endroit o\u00f9 l&rsquo;obscurit\u00e9 vient \u00e0 la lumi\u00e8re, l\u00e0 o\u00f9 le diable vient danser et toutes les horreurs dans le monde se sentent \u00e0 la maison. C&rsquo;est un endroit sp\u00e9cial, le lieu du mal. Une fois entr\u00e9, tu ne peux plus partir. Une partir de toi restera ici pour toujours. Il connait Strowman. Il n&rsquo;a pas aim\u00e9 le mosntre qu&rsquo;il \u00e9tait destin\u00e9 \u00eatre, alors il doit tuer le monstre qu&rsquo;il est devenu. Strowman sait o\u00f9 le trouver. Qu&rsquo;il revienne \u00e0 la maison&#8230; RUN.<\/p>\n\n\n\n<p><strong>Braun Strowman vs John Morrison acc par le Miz<\/strong><\/p>\n\n\n\n<p>En fin de match, Strowman porte son Running PowerSlam sur Morrison pour le compte de trois.<\/p>\n\n\n\n<p><em>Gagnant: Braun Strowman<\/em><\/p>\n\n\n\n<p>pr\u00e8s le match, Braun Strowman prend le micro et dit qu&rsquo;il esp\u00e8re que Bray Wyatt regarde et il revient \u00e0 la maison.<\/p>\n\n\n\n<p> Le Miz veut une aide m\u00e9dicale pour John Morrison mais ce dernier refuse toute aide. Lacey Evans fait son entr\u00e9e pendant que les para-m\u00e9diques aides Morrison \u00e0 sortir et on part \u00e0 la pause.<\/p>\n\n\n\n<p><strong>Lacey Evans vs Naomi<\/strong><\/p>\n\n\n\n<p>En fin de match, Lacey Evans attache les cheveux de Naomi entre les cordes. Naomi arrive \u00e0 s&rsquo;en d\u00e9prendre mais  Evans sort sa Women&rsquo;s Right de nul part et \u00e9tampe Naomi pour le compte de trois.<\/p>\n\n\n\n<p><em>Gagnante: Lacey Evans<\/em><\/p>\n\n\n\n<p> &#8211; Dans les coulisses, Kayla Braxton est avec Jeff Hardy. Ce dernier dit que se batttre contre ce connard de Sheamus est comme se battre contre l&rsquo;addiction. On ne peut pas s&rsquo;en cacher. Tu dois te battre chaque jour jusqu&rsquo;\u00e0 ce qu&rsquo;il s&rsquo;arr\u00eate. Braxton lui demande un pronostic pour le match de championnat entre Matt Riddle vs AJ Styles. Hardy dit qu&rsquo;il aurait pu \u00eatre dans le match ce soir mais Sheamus l&rsquo;attaque et s&rsquo;assoie \u00e0 c\u00f4t\u00e9 de lui. Il lui dit qu&rsquo;il ne peut ni s&rsquo;enfuir ni se cacher. Il le verra la semaine prochaine. <\/p>\n\n\n\n<p>&#8211; Au retour de la pause en coulisses, Kayla Braxton croise Bayley et Sasha Banks. Elle les f\u00e9licite pour leur victoire de ce soir. Leur momentum continuera-t-il ce dimanche ? Bayley r\u00e9pond qu&rsquo;elle a plus de momentum que n&rsquo;importe qui. Lorsqu&rsquo;elle porte ces titres, elle a plus de masse que Nikki Cross. Sa meilleure amie Sasha Banks va d\u00e9truire Asuka et devenir une double championne. Sasha Banks dit que leur destin est d&rsquo;avoir tout l&rsquo;or.<\/p>\n\n\n\n<p>&#8211; Dans les coulisses, Alexa Bliss et Nikki Cross regardent un \u00e9cran. Cross dit qu&rsquo;elle a perdu ce soir et elle va tout g\u00e2cher ce dimanche. Bliss dit qu&rsquo;elle va rien g\u00e2cher. Cross dit que sa famille et ses amis \u00e0 \u00c9cosse la regardent perdre et elle perd confiance. Bliss lui dit qu&rsquo;elle gagnera \u00e0 Extreme Rules.<\/p>\n\n\n\n<p>Bayley et Sasha Banks se trouvent derri\u00e8re elles et Cross les attaque dans le dos, puis Bliss la retire.<\/p>\n\n\n\n<p><strong>Championnat Intercontinental: Aj Styles \u00a9 vs Matt Riddle<\/strong><\/p>\n\n\n\n<p>En fin de match,  AJ Styles fait un Calf Crusher sur Matt Riddle et ce dernier essaye d&rsquo;atteindre les cordes. Styles maintient la soumission. Riddle tente de renverser la soumission par son BroMission mais Styles lui fait un roll up pour la victoire. <\/p>\n\n\n\n<p><em>Gagnant et toujours champion: Aj Styles<\/em><\/p>\n\n\n\n<p>&nbsp;Apr\u00e8s le match, AJ Styles c\u00e9l\u00e8bre sa victoire et tend sa main \u00e0 Matt Riddle que ce dernier accepte, mais il se fait frapper par King Corbin ! Styles s&rsquo;en va du ring. Corbin fait son End of Days sur Riddle et le show se termine ainsi.<br><\/p>\n\n\n\n<p class=\"has-medium-font-size\"><a href=\"https:\/\/www.jdx.info\/lutte\/2020\/07\/17\/regardez-le-wwe-friday-night-smackdown-du-17-juillet-2020\/\"><strong>Pour voir ce Smackdown, cliquez ici.<\/strong><\/a><\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Pour revenir \u00e0 la premier heure de Smackdown, cliquez ici. &#8211; C&rsquo;est le moment de la Firefly Fun House. Bray Wyatt est dans les mar\u00e9cages et chantonne sa musique. Wyatt dit que c&rsquo;est beau, le serpent est de la m\u00eame couleur que les feuilles. Quand Braun Strowman a pos\u00e9 le pied pour la premi\u00e8re fois&#8230;<\/p>\n","protected":false},"author":4,"featured_media":32077,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[36],"tags":[],"ppma_author":[292],"class_list":["post-32040","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-smackdown"],"authors":[{"term_id":292,"user_id":4,"is_guest":0,"slug":"jean","display_name":"Jean Vinnier","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/33aba0263fd870a0b487e0e079ff407e10e3997c9d2987cbcc0db0db2c5c75a9?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/32040","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=32040"}],"version-history":[{"count":17,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/32040\/revisions"}],"predecessor-version":[{"id":32174,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/32040\/revisions\/32174"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/32077"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=32040"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=32040"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=32040"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=32040"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}