{"id":30331,"date":"2020-06-22T21:03:49","date_gmt":"2020-06-23T01:03:49","guid":{"rendered":"http:\/\/www.jdx.info\/lutte\/?p=30331"},"modified":"2020-06-22T22:16:49","modified_gmt":"2020-06-23T02:16:49","slug":"deuxieme-heure-du-wwe-raw-22-juin-2020","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2020\/06\/22\/deuxieme-heure-du-wwe-raw-22-juin-2020\/","title":{"rendered":"Deuxi\u00e8me Heure du WWE RAW 22 Juin 2020!"},"content":{"rendered":"\n<p><a href=\"https:\/\/www.jdx.info\/lutte\/2020\/06\/22\/resultats-le-wwe-monday-night-raw-22-juin-2020\/\">Pour revenir \u00e0 la premi\u00e8re heure de RAW, cliquez ici.<\/a><\/p>\n\n\n\n<p><strong>Championnat F\u00e9minin de RAW<\/strong><br><em> Asuka (c) vs Charlotte Flair <\/em><\/p>\n\n\n\n<p>En fin de match, Charlotte fait un Spear \u00e0 Asuka et la couvre, mais elle attrape un c\u00e2ble. Ensuite elle fait une Powerbomb \u00e0 Asuka, mais Asuka la surprend avec un Asuka Lock pour la faire taper.<\/p>\n\n\n\n<p><em>Gagnante : Asuka\u00a0<\/em><\/p>\n\n\n\n<p>&#8211; En coulisse, Nia Jax regardait le combat et Charly lui demande si sa confrontation avec Charlotte a influenc\u00e9 le r\u00e9sultat du combat. Nia dit que ce serait une honte si quelqu&rsquo;un frappe la reine pendant qu&rsquo;elle est au sol.<\/p>\n\n\n\n<p>&#8211; En coulisse, Nia Jax regardait le combat et Charly lui demande si sa confrontation avec Charlotte a influenc\u00e9 le r\u00e9sultat du combat. Nia dit que ce serait une honte si quelqu&rsquo;un frappe la reine pendant qu&rsquo;elle est au sol.<\/p>\n\n\n\n<p>&#8211; De retour, on pr\u00e9sente une vid\u00e9o du combat entre Randy Orton et Christian lundi dernier.<\/p>\n\n\n\n<p>&#8211; De retour, on pr\u00e9sente une vid\u00e9o du combat entre Randy Orton et Christian lundi dernier. En coulisse, on retrouve\u00a0<strong>Edge<\/strong>. Edge dit qu&rsquo;Orton a gagn\u00e9 \u00e0 Backlash, mais il ne semble pas avoir le titre du meilleur catcheur. Orton l&rsquo;a frapp\u00e9 avec un RKO et lui a d\u00e9chir\u00e9 le tricep, mais il a continu\u00e9 de se battre. Il a vu la panique dans les yeux d&rsquo;Orton et il l&rsquo;a frapp\u00e9 avec un Low Blow \u00a0\u00bbaccidentel\u00a0\u00bb. Il a vu RAW lundi dernier, il peut se faire des tee-shirts et autres items en disant qu&rsquo;il l&rsquo;a battu s&rsquo;il le veut. Edge dit qu&rsquo;il est d\u00e9\u00e7u d&rsquo;avoir perdu, d\u00e9\u00e7u de ne pas avoir vu le Low Blow arriv\u00e9, d\u00e9\u00e7u de ne pas l&rsquo;avoir fait avant lui. Il a rappel\u00e9 \u00e0 Orton qu&rsquo;il est le Legend Killer. <\/p>\n\n\n\n<p>Cette blessure au bras, qui l&#8217;emp\u00eache de lever sa fille le jour de la f\u00eate des p\u00e8res, \u00e7a lui a fait r\u00e9aliser quelque chose. En plus de le voir faire un Punt Kick \u00e0 Christian qui ne peut plus combatte, son meilleur ami. Avec ces gestes le catcheur PG est disparu pour de bon. Orton a \u00e9veill\u00e9 un c\u00f4t\u00e9 de lui qui veut tout avoir ce qu&rsquo;il veut. Ce n&rsquo;est pas important pour lui de gagner, il veut humilier Orton \u00e0 un point o\u00f9 son p\u00e8re aurait pr\u00e9f\u00e9r\u00e9 tir\u00e9 \u00e0 blanc le soir o\u00f9 il a \u00e9t\u00e9 con\u00e7u. Lorsqu&rsquo;Orton va revenir \u00e0 la maison ses enfants vont lui demander s&rsquo;il va bien, mais la r\u00e9ponse sera non. Orton a des voix dans sa t\u00eate, mais il va crier encore plus fort. Il va briser la vie d&rsquo;Orton morceaux par morceaux. Orton n&rsquo;a aucune id\u00e9e ce qu&rsquo;il a fait.\u00a0Orton a r\u00e9veill\u00e9 le diable, il a r\u00e9veill\u00e9 la Rated R Superstar.\u00a0Edge lui dit de bien dormir pendant qu&rsquo;il le peut.<\/p>\n\n\n\n<p>&#8211; En coulisse, Charly demande \u00e0 Randy Orton ses commentaires. Orton demande si Charly sait ce qu&rsquo;un serpent fait lorsqu&rsquo;il se sent la menace ? Il va mordre, il va attaquer. Il va faire ce qui faut pour survivre. Edge et Christian sont revenus \u00e0 son d\u00e9triment. Alors quand il est contre le coin il va mordre. Il va tout faire ce qui faut pour se d\u00e9fendre, d\u00e9fendre sa famille, pour survivre. Il souhaite vraiment qu&rsquo;Edge et Christian se r\u00e9tablissent et qu&rsquo;ils puissent vivre en sant\u00e9 pour longtemps tant qu&rsquo;ils le font tr\u00e8s tr\u00e8s loin de lui.<\/p>\n\n\n\n<p>&#8211; De retour, en coulisse, Charlotte dit qu&rsquo;elle est n&rsquo;est pas heureuse par le r\u00e9sultat, mais elle doit donner le cr\u00e9dit \u00e0 Asuka. Nia Jax arrive et attaque Charlotte ! Nia lui cogne le bras sous un couvercle.<\/p>\n\n\n\n<p>&#8211; R-Truthn arrive sur le ring pour affronter Akira Tozawa pour le titre 24\/7, mais Bobby Lashley arrive avec MVP et ils attaquent tous les ninjas. Lashley termine avec sa Full Nelson sur Truth pour le sonner et ils s&rsquo;en vont.&nbsp;<strong>Tozawa se rel\u00e8ve fait le compte de trois sur Truth pour devenir le nouveau champion 24\/7<\/strong>&nbsp;!<\/p>\n\n\n\n<p> &#8211; En coulisse, Sarah attend pour avoir une mise \u00e0 jour sur Charlotte, mais Natalya arrive. Natalya dit qu&rsquo;elle se sent si mal pour Charlotte. La division de RAW a besoin de sa poigne afin de mieux se comporter. Asuka n&rsquo;est pas la meilleure pour motiver les gens. Elle a une annonce importante pour nous plus tard ! <\/p>\n\n\n\n<p><strong>Liv Morgan vs Natalya\u00a0acc de Lana<\/strong><\/p>\n\n\n\n<p>En fin de match, Natalya profite d&rsquo;une distraction de Lana pour frapper Morgan sur la jambe et lui applique son Sharpshooter pour la faire taper.<\/p>\n\n\n\n<p><em>Gagnante : Natalya\u00a0<\/em><\/p>\n\n\n\n<p>&#8211; Apr\u00e8s le combat, Natalya et Lana c\u00e9l\u00e8brent ensemble.<\/p>\n\n\n\n<p>&#8211; En coulisse, Charly arr\u00eate Big Show pour lui demande s&rsquo;il croyait affronter des ninjas. Big Show dit qu&rsquo;il y en avait beaucoup, il voulait seulement dire bonjour \u00e0 ses amis. Il a profit\u00e9 de l&rsquo;occasion pour frapper les ninjas. Big Show dit que lorsqu&rsquo;il devient le g\u00e9ant f\u00e2ch\u00e9 rien ne peut l&rsquo;arr\u00eater et c&rsquo;est ce que nous aurons ce soir.<\/p>\n\n\n\n<p>&#8211; On nous annonce le match de championnat de la WWE entre Drew McIntyre contre l&rsquo;aspirant Dolph Ziggler pour Extreme Rules.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p class=\"has-medium-font-size\"> <a href=\"https:\/\/www.jdx.info\/lutte\/2020\/06\/22\/troisieme-heure-du-wwe-raw-22-juin-2020\/\"><strong>Pour la suite de RAW et actualiser la page, cliquez ici.<\/strong> <\/a><\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Pour revenir \u00e0 la premi\u00e8re heure de RAW, cliquez ici. Championnat F\u00e9minin de RAW Asuka (c) vs Charlotte Flair En fin de match, Charlotte fait un Spear \u00e0 Asuka et la couvre, mais elle attrape un c\u00e2ble. Ensuite elle fait une Powerbomb \u00e0 Asuka, mais Asuka la surprend avec un Asuka Lock pour la faire&#8230;<\/p>\n","protected":false},"author":4,"featured_media":30344,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[43],"tags":[],"ppma_author":[292],"class_list":["post-30331","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-raw-wwe"],"authors":[{"term_id":292,"user_id":4,"is_guest":0,"slug":"jean","display_name":"Jean Vinnier","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/33aba0263fd870a0b487e0e079ff407e10e3997c9d2987cbcc0db0db2c5c75a9?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/30331","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=30331"}],"version-history":[{"count":12,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/30331\/revisions"}],"predecessor-version":[{"id":30365,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/30331\/revisions\/30365"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/30344"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=30331"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=30331"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=30331"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=30331"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}