{"id":29984,"date":"2020-06-16T18:48:00","date_gmt":"2020-06-16T22:48:00","guid":{"rendered":"http:\/\/www.jdx.info\/lutte\/?p=29984"},"modified":"2020-06-16T19:19:14","modified_gmt":"2020-06-16T23:19:14","slug":"le-possible-retour-de-christian-pour-un-match-a-extreme-rules-face-a-randy-orton-selon-le-5-fois-champion-de-la-wcw-booker-t","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2020\/06\/16\/le-possible-retour-de-christian-pour-un-match-a-extreme-rules-face-a-randy-orton-selon-le-5-fois-champion-de-la-wcw-booker-t\/","title":{"rendered":"Le Possible Retour De Christian Pour Un Match \u00e0 Extreme Rules, Face \u00e0 Randy Orton, Selon le 5 Fois Champion de la WCW, Booker T!"},"content":{"rendered":"\n<p>Dans ce bulletin je vous explique pourquoi on parle d&rsquo;un match possible \u00e0 Extreme Rules entre Christian et Randy Orton. <\/p>\n\n\n\n<p>Nous avons tous eut la surprise cette semaine lors du Monday Night RAW alors que Christian Cage a fait son retour pour affronter Randy Orton dans un combat non sanctionn\u00e9. Ce qui indique que la WWE a autoris\u00e9 Christian \u00e0 reprendre l&rsquo;action alors que le m\u00e9decin WWE lui avait interdit de subir n&rsquo;importe quelle prise comme il \u00e9tait susceptible de subir une autre commotion c\u00e9r\u00e9brale importante.<\/p>\n\n\n\n<p>Ce mardi, Booker T a discut\u00e9 de ce sujet sur son podcast \u00a0\u00bbHall of Fame\u00a0\u00bb et il explique que selon lui Christian a retrouv\u00e9 la piq\u00fbre pour le sport et qu&rsquo;il sera de retour en action pour Extreme Rules le 19 juillet :<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u00a0\u00bbTu as directement la piq\u00fbre lorsque tu reviens, directement quand tu as un petit avant-go\u00fbt. [&#8230;] Je ne crois pas que c&rsquo;\u00e9tait un coup d&rsquo;un soir, je crois que Christian va revenir et je crois qu&rsquo;il aura cette piq\u00fbre. Je pense que Christian sera \u00e0 Extreme Rules sur le ring et il aura la chance de se pr\u00e9parer pour \u00e7a.\u00a0\u00bb<\/p><\/blockquote>\n\n\n\n<p>Nous ne savons pas en ce moment quels sont les plans de la WWE pour Christian mais il est claire qu&rsquo;il est venu en renfort pour ajouter du Star Power \u00e0 <a href=\"https:\/\/www.jdx.info\/lutte\/2020\/06\/15\/resultats-video-wwe-monday-night-raw-15-juin-2020\/\"><strong>RAW que vous pouvez voir ou lire les r\u00e9sultats complet en cliquant ici. <\/strong><\/a><\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Dans ce bulletin je vous explique pourquoi on parle d&rsquo;un match possible \u00e0 Extreme Rules entre Christian et Randy Orton. Nous avons tous eut la surprise cette semaine lors du Monday Night RAW alors que Christian Cage a fait son retour pour affronter Randy Orton dans un combat non sanctionn\u00e9. Ce qui indique que la&#8230;<\/p>\n","protected":false},"author":609,"featured_media":29986,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[30,4,43,23],"tags":[],"ppma_author":[295],"class_list":["post-29984","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ex-wwe","category-news","category-raw-wwe","category-wwe"],"authors":[{"term_id":295,"user_id":609,"is_guest":0,"slug":"rodrigo","display_name":"Rodrigue Tousignant","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/51fe284bb6dbe8a6b4c2bf998ad658f4a9cd24b7e58f15ec85888070c7340ce6?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/29984","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/609"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=29984"}],"version-history":[{"count":1,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/29984\/revisions"}],"predecessor-version":[{"id":29985,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/29984\/revisions\/29985"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/29986"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=29984"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=29984"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=29984"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=29984"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}