{"id":29896,"date":"2020-06-15T21:53:36","date_gmt":"2020-06-16T01:53:36","guid":{"rendered":"http:\/\/www.jdx.info\/lutte\/?p=29896"},"modified":"2020-06-15T23:42:36","modified_gmt":"2020-06-16T03:42:36","slug":"troisieme-heure-du-wwe-raw-15-2020","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2020\/06\/15\/troisieme-heure-du-wwe-raw-15-2020\/","title":{"rendered":"Troisi\u00e8me Heure du WWE RAW, 15 2020!"},"content":{"rendered":"\n<p><a href=\"https:\/\/www.jdx.info\/lutte\/2020\/06\/15\/deuxieme-heure-de-wwe-raw-15-juin-2020\/\"><strong>Pour revenir \u00e0 la deuxi\u00e8me heure de RAW, cliquez ici.<\/strong><\/a><\/p>\n\n\n\n<p><strong> Bobby Lashley et MVP vs R-Truth et Drew McIntyre (c) <\/strong><\/p>\n\n\n\n<p>En fin de match, McIntyre fait son Future Shock DDT sur MVP et le couvre, mais Lashley brise le compte. Truth veut intervenir, mais Lashley le sort du ring et veut lui faire un Spear, mais Truth le repousse sur la marche d&rsquo;acier. McIntyre enchaine avec un Claymore sur MVP et donne la tag \u00e0 Truth. McIntyre lance Truth sur MVP et Truth le couvre pour la victoire.<\/p>\n\n\n\n<p><em>Gagnants : R-Truth et Drew McIntyre<\/em><\/p>\n\n\n\n<p>&#8211; En coulisse, Christian se pr\u00e9pare pour son combat et Ric Flair arrive. Flair dit qu&rsquo;il sait que Christian n&rsquo;est pas pr\u00eat pour \u00e7a. Orton est au top de son niveau, il est sadique et il veut prouver qu&rsquo;il est intouchable. Christian dit qu&rsquo;il appr\u00e9cie ce que Flair veut lui dire. Flair dit qu&rsquo;il ne doit pas se blesser. Christian dit qu&rsquo;il doit faire regretter Orton pour ses paroles.<\/p>\n\n\n\n<p> &#8211; De retour, Sasha Banks et Bayley 2 Belts  arrivent sur le ring. Bayley dit que hier soir \u00e0 Backlash elles ont d\u00e9fendu avec succ\u00e8s les titres par \u00e9quipe. Elles sont d&rsquo;humeur pour c\u00e9l\u00e9brer, en plus c&rsquo;est son anniversaire. Une semaine de c\u00e9l\u00e9brations en plus elles vont battre Shotzi Blackheart et Tegan Nox \u00e0 NXT pour ensuite terminer la semaine en force \u00e0 SmackDown. Sasha dit qu&rsquo;elle n&rsquo;aime pas les Iiconics qui veulent d\u00e9cider de la journ\u00e9e de la d\u00e9fense des titres. Les Iiconics arrivent. <\/p>\n\n\n\n<p>Billie Kay dit que personne ne veut encore attendre leur palmar\u00e8s. Les gens veulent une r\u00e9ponse \u00e0 leur challenge, oui ou non. Bayley demande si elles ont oubli\u00e9s ce qui est arriv\u00e9 \u00e0 Backlash ? Une d\u00e9faite. Peu importe qui sera l&rsquo;\u00e9quipe, le r\u00e9sultat sera le m\u00eame avec elles comme les championnes. Billie dit qu&rsquo;elles ont gagn\u00e9 \u00e0 WrestleMania l&rsquo;an dernier. Peyton dit que \u00e7a l&rsquo;a fait tellement mal qu&rsquo;elles se sont effondr\u00e9es. Billie dit qu&rsquo;elles ne pouvaient pas endurer la pression et pas encore. Sasha demande si elle veut parler de pression. Peyton la gifle !&nbsp;Bayley commence \u00e0 hurler et dit qu&rsquo;elles ne peuvent pas ruiner sa f\u00eate ainsi. Le challenge est accept\u00e9. <\/p>\n\n\n\n<p>&#8211; On annonce que Rey Mysterio sera de retour \u00e0 RAW lundi prochain.<\/p>\n\n\n\n<p><strong>Championnat F\u00e9minin de RAW:<\/strong><br>Asuka vs Nia Jax (c)<\/p>\n\n\n\n<p>Nia d\u00e9cide de pousser l&rsquo;arbitre car elle n&rsquo;a pas d&rsquo;accord de sa d\u00e9cision. L&rsquo;arbitre voulait peut-\u00eatre la disqualifier, mais Asuka en profite pour lui faire un Roll Up et l&rsquo;arbitre fait un compte rapide pour la victoire.<\/p>\n\n\n\n<p><em>Gagnante : Asuka<\/em><\/p>\n\n\n\n<p>&#8211; En coulisse, Charly demande \u00e0 Randy Orton ses commentaires avant son combat. Orton demande si elle croit que Christian est une l\u00e9gende. Charly approuve. Orton dit qu&rsquo;il le pense aussi. Est-ce qu&rsquo;elle sait ce que veut dire non sanctionn\u00e9 ? \u00c7a veut dire aucun r\u00e8glement. Dans quelques minutes on va voir la l\u00e9gende de Christian se faire d\u00e9truire par les trois lettres les plus destructives du sport, RKO !<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<p>&#8211; De retour, on confirme que le combat pour les titres f\u00e9minin aura lieu lundi prochain. Aussi, les Street Profits vont d\u00e9fendre les titres face aux Viking Raiders.<\/p>\n\n\n\n<p><strong> Unsanctioned Match<\/strong>: <strong>Christian vs Randy Orton<\/strong><\/p>\n\n\n\n<p>mais Ric Flair arrive. Flair fait signe que non \u00e0 Christian. Il vient de parler avec Edge et il ne veut pas. Christian doit passer \u00e0 autre chose. Christian prend le micro et dit qu&rsquo;il doit le faire. Le combat commence et Flair lui fait un Low Blow ! Orton enchaine avec un Punt Kick et le couvre pour la victoire.<\/p>\n\n\n\n<p><em>Gagnant : Randy Orton<\/em><\/p>\n\n\n\n<p>Apr\u00e8s le combat, Orton dit qu&rsquo;il est d\u00e9sol\u00e9 que Christian n&rsquo;ait pas r\u00e9ussi \u00e0 aider son ami. Tout ce qui est arriv\u00e9 est de sa faute, Christian n&rsquo;aurait jamais d\u00fb \u00eatre ici. Les m\u00e9decins arrivent pour s&rsquo;occuper de Christian. Orton dit qu&rsquo;il ne voulait pas faire \u00e7a, il ne voulait pas \u00eatre le dernier chapitre de Christian, mais il devait le faire. C&rsquo;est de la faute de Christian. Le show se termine ainsi.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><a href=\"https:\/\/www.jdx.info\/lutte\/2020\/06\/15\/regardez-le-wwe-monday-night-raw-du-15-juin-2020\/\"><strong>Pour voir ce WWE Monday Night RAW, cliquez ici.<\/strong><\/a><\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Pour revenir \u00e0 la deuxi\u00e8me heure de RAW, cliquez ici. Bobby Lashley et MVP vs R-Truth et Drew McIntyre (c) En fin de match, McIntyre fait son Future Shock DDT sur MVP et le couvre, mais Lashley brise le compte. Truth veut intervenir, mais Lashley le sort du ring et veut lui faire un Spear,&#8230;<\/p>\n","protected":false},"author":4,"featured_media":29909,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[36],"tags":[],"ppma_author":[292],"class_list":["post-29896","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-smackdown"],"authors":[{"term_id":292,"user_id":4,"is_guest":0,"slug":"jean","display_name":"Jean Vinnier","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/33aba0263fd870a0b487e0e079ff407e10e3997c9d2987cbcc0db0db2c5c75a9?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/29896","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=29896"}],"version-history":[{"count":12,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/29896\/revisions"}],"predecessor-version":[{"id":29929,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/29896\/revisions\/29929"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/29909"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=29896"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=29896"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=29896"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=29896"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}