{"id":29800,"date":"2020-06-15T11:48:15","date_gmt":"2020-06-15T15:48:15","guid":{"rendered":"http:\/\/www.jdx.info\/lutte\/?p=29800"},"modified":"2020-06-15T12:23:58","modified_gmt":"2020-06-15T16:23:58","slug":"aj-styles-celebre-la-victoire-du-titre-sur-smackdown-daniel-bryan-apparait","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2020\/06\/15\/aj-styles-celebre-la-victoire-du-titre-sur-smackdown-daniel-bryan-apparait\/","title":{"rendered":"AJ Styles C\u00e9l\u00e9bre la Victoire du Titre sur SmackDown, Daniel Bryan Viendra?"},"content":{"rendered":"\n<p>Le nouveau champion intercontinental de la WWE, AJ Styles, est apparu lors du pay-per-view WWE Backlash dimanche soir dans les coulisses avec Kayla Braxton, parlant de la querelle en cours avec Daniel Bryan.<\/p>\n\n\n\n<p>AJ a annonc\u00e9 qu&rsquo;il sera sur SmackDown de ce vendredi pour une pr\u00e9sentation sp\u00e9ciale de sa victoire. Il veut que Daniel Bryan soit l\u00e0 pour la c\u00e9l\u00e9bration, ajoutant que Bryan est bon mais qu&rsquo;il n&rsquo;est tout simplement pas \u00a0\u00bbph\u00e9nom\u00e9nal\u00a0\u00bb. <\/p>\n\n\n\n<p>Il semble que la rivalit\u00e9 entre Bryan et Styles est bien partie apr\u00e8s que le Phenomenal a battu le chef du Yes Mouvement en finale du tournoi pour remporter le titre Intercontinental, laiss\u00e9 vacant par Sami Zayn.<\/p>\n\n\n\n<p>Comme indiquer \u00e0 SmackDown de vendredi dernier, on verra \u00e9galement Matt Riddle faire ses d\u00e9buts officiels. Nous vous donnerons d&rsquo;autres d\u00e9tails au courant de la semaine.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><a href=\"https:\/\/www.jdx.info\/lutte\/2020\/06\/14\/resultats-video-wwe-backlash-2020\/\"><strong>Pour les r\u00e9sultats ou voir le WWE BackLash, cliquez ici.<\/strong><\/a><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><a href=\"https:\/\/www.jdx.info\/lutte\/2020\/06\/14\/resultats-video-wwe-backlash-2020\/\"><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"540\" src=\"https:\/\/www.jdx.info\/lutte\/wp-content\/uploads\/2020\/06\/EagUFcyWoAAV00i.jpg\" alt=\"\" class=\"wp-image-29780\" srcset=\"https:\/\/www.jdx.info\/lutte\/wp-content\/uploads\/2020\/06\/EagUFcyWoAAV00i.jpg 960w, https:\/\/www.jdx.info\/lutte\/wp-content\/uploads\/2020\/06\/EagUFcyWoAAV00i-300x169.jpg 300w, https:\/\/www.jdx.info\/lutte\/wp-content\/uploads\/2020\/06\/EagUFcyWoAAV00i-768x432.jpg 768w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\" \/><\/a><figcaption>R\u00e9sultats et Vid\u00e9os de BackLash 2020<\/figcaption><\/figure><\/div>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Le nouveau champion intercontinental de la WWE, AJ Styles, est apparu lors du pay-per-view WWE Backlash dimanche soir dans les coulisses avec Kayla Braxton, parlant de la querelle en cours avec Daniel Bryan. AJ a annonc\u00e9 qu&rsquo;il sera sur SmackDown de ce vendredi pour une pr\u00e9sentation sp\u00e9ciale de sa victoire. Il veut que Daniel Bryan&#8230;<\/p>\n","protected":false},"author":665,"featured_media":29804,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[52,4,36,23],"tags":[],"ppma_author":[289],"class_list":["post-29800","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-backlash","category-news","category-smackdown","category-wwe"],"authors":[{"term_id":289,"user_id":665,"is_guest":0,"slug":"line","display_name":"Line Edmond","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/852de09636413c90cdaa278312f9ea5bc4396768745424755cb63d99a05989d0?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/29800","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/665"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=29800"}],"version-history":[{"count":4,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/29800\/revisions"}],"predecessor-version":[{"id":29810,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/29800\/revisions\/29810"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/29804"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=29800"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=29800"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=29800"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=29800"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}