{"id":29701,"date":"2020-06-14T19:52:00","date_gmt":"2020-06-14T23:52:00","guid":{"rendered":"http:\/\/www.jdx.info\/lutte\/?p=29701"},"modified":"2020-06-14T20:58:54","modified_gmt":"2020-06-15T00:58:54","slug":"deuxieme-heure-du-wwe-backlash-2020","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2020\/06\/14\/deuxieme-heure-du-wwe-backlash-2020\/","title":{"rendered":"Deuxi\u00e8me Heure du WWE BackLash 2020!"},"content":{"rendered":"\n<p><a href=\"https:\/\/www.jdx.info\/lutte\/2020\/06\/14\/premiere-heure-du-wwe-backlash-2020\/\"><strong>Pour revenir \u00e0 la premi\u00e8re heure du WWE BackLash, cliquez ici<\/strong><\/a><\/p>\n\n\n\n<p> &#8211; On pr\u00e9sente une vid\u00e9o sur la rivalit\u00e9 entre Nia et Asuka qui a remport\u00e9 la ceinture dans sa mallette du Money in the Bank puis qued Becky a d\u00e9cid\u00e9 de la laisser vacante. <\/p>\n\n\n\n<p><strong>Championnat F\u00e9minin de RAW:<\/strong><br>Nia Jax vs Asuka<\/p>\n\n\n\n<p>En fin de match, Asuka et Jax \u00e9changent les coups en bas du ring. L&rsquo;arbitre compte jusqu&rsquo;\u00e0 dix.<\/p>\n\n\n\n<p><em>Pas de Gagnante:<\/em> <em>Double d\u00e9compte ext\u00e9rieur<\/em><\/p>\n\n\n\n<p>&#8211; Apr\u00e8s le combat, Asuka porte un coup de hanches \u00e0 Nia et va c\u00e9l\u00e9brer sur la sc\u00e8ne.<\/p>\n\n\n\n<p>&#8211; On voit MVP  au t\u00e9l\u00e9phone pour r\u00e9server la meilleure bouteille de champagne pour la victoire de Lashley. Lana arrive et dit que MVP doit comprendre que c&rsquo;est la plus grande soir\u00e9e de Lashley. S&rsquo;il connait du succ\u00e8s c&rsquo;est gr\u00e2ce \u00e0 elle. Elle veut lui donner un conseil. MVP dit que c&rsquo;est son mari qui d\u00e9cid\u00e9 de la garder en coulisse, alors elle devrait aller parler \u00e0 Lashley, mais elle ne fera pas car elle a trop peur de la r\u00e9ponse.<\/p>\n\n\n\n<p>&#8211; On revoir l&rsquo;histoire entre The Miz &amp; Morrison avec Braun Strowman.<\/p>\n\n\n\n<p> &#8211;  Miz dit qu&rsquo;il a besoin de quelque chose pour l&rsquo;exciter avant de devenir champion. Morrison dit que c&rsquo;est le moment d&rsquo;offrir leur nouveau single musical. Miz et Morrison pr\u00e9sente leur vid\u00e9o Hey Hey Oh Oh \u266a\u266a<\/p>\n\n\n\n<p><strong>Championnat Universal:<\/strong><br>Miz &amp; Morrison vs Braun Sttroman \u00a9<br><em>Celui qui fait le tomb\u00e9 gagne la ceinture<\/em><\/p>\n\n\n\n<p>En fin de match,  Miz fait un Skull Crushing Finale et Morrison compl\u00e8te avec un Springboard Kick. Morrison le couvre, mais Miz arr\u00eate le compte. Strowman reprend l&rsquo;avantage apr\u00e8s ce conflit dans l&rsquo;\u00e9quipe. Il fait un Choke Slam \u00e0 Miz et bloque un saut de Morrison. Il fait sa Running PowerSlam sur Morrison pour le compte de trois. <\/p>\n\n\n\n<p><em>Gagnant et toujours champion: Braun Strowman<\/em><\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<p>&#8211; En coulisse, Kayla est avec le nouveau champion Intercontinental AJ Styles pour une annonce. AJ dit que le champion ne prend pas cong\u00e9. Apr\u00e8s sa performance, il veut lancer une invitation. Il est le meilleur champion de l&rsquo;histoire, alors pourquoi ne pas avoir une pr\u00e9sentation du champion. Incluant Daniel Bryan pour inviter qu&rsquo;il s&rsquo;est battu pour ses r\u00eaves, mais lui il r\u00e9alise ses r\u00eaves. Bryan n&rsquo;est simplement pas ph\u00e9nom\u00e9nal.<\/p>\n\n\n\n<p>&#8211; On pr\u00e9sente l&rsquo;histoire entre Lashley, Lana, MVP et Drew McIntyre\u00e9<\/p>\n\n\n\n<p><strong>Championnat WWE: Bobby Lashley acc MVP vs Drew McIntyre \u00a9<\/strong><\/p>\n\n\n\n<p>Le combat n&rsquo;est pas officiellement d\u00e9but\u00e9 que MVP distrait McIntyre et Lashley le prend dans un Full Nelson. Les Arbitres viennent en grand nombre pour les s\u00e9parer et McIntyre est en douleur et n&rsquo;a m\u00eame pas le temps d&rsquo;enlever ses v\u00eatement que Lashley saute dessus d\u00e8s que la cloche sonne. <\/p>\n\n\n\n<p>En fin de match,  McIntyre se lance pour son Claymore, mais Lashley le bloque avec un Spear et il r\u00e9siste \u00e0 deux ! Lana arrive et monte sur le tablier pour parler avec l&rsquo;arbitre ce qui distrait Lashley. McIntyre lui rentre dedans d&rsquo;un coup d&rsquo;\u00e9paule et envoie son rival sur la russe qui tombe sur MVP. Drew fait le Klaymore \u00e0 Lashley puis le compte de trois!<\/p>\n\n\n\n<p><em>Gagnant et toujours champion: Drew McIntyre<\/em><\/p>\n\n\n\n<p class=\"has-large-font-size\"><a href=\"https:\/\/www.jdx.info\/lutte\/2020\/06\/14\/troisieme-heure-du-wwe-backlash-2020\/\"><strong>Pour la troisi\u00e8me heure de BackLash, cliquez ici.<\/strong><\/a><\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Pour revenir \u00e0 la premi\u00e8re heure du WWE BackLash, cliquez ici &#8211; On pr\u00e9sente une vid\u00e9o sur la rivalit\u00e9 entre Nia et Asuka qui a remport\u00e9 la ceinture dans sa mallette du Money in the Bank puis qued Becky a d\u00e9cid\u00e9 de la laisser vacante. Championnat F\u00e9minin de RAW:Nia Jax vs Asuka En fin de&#8230;<\/p>\n","protected":false},"author":4,"featured_media":29718,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[52],"tags":[],"ppma_author":[292],"class_list":["post-29701","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-backlash"],"authors":[{"term_id":292,"user_id":4,"is_guest":0,"slug":"jean","display_name":"Jean Vinnier","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/33aba0263fd870a0b487e0e079ff407e10e3997c9d2987cbcc0db0db2c5c75a9?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/29701","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=29701"}],"version-history":[{"count":17,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/29701\/revisions"}],"predecessor-version":[{"id":29754,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/29701\/revisions\/29754"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/29718"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=29701"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=29701"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=29701"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=29701"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}