{"id":29658,"date":"2020-06-16T13:00:00","date_gmt":"2020-06-16T17:00:00","guid":{"rendered":"http:\/\/www.jdx.info\/lutte\/?p=29658"},"modified":"2020-06-16T15:04:09","modified_gmt":"2020-06-16T19:04:09","slug":"plus-de-detaile-et-spoilers-sur-lenregistrement-secret-de-la-njpw-a-los-angeles","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2020\/06\/16\/plus-de-detaile-et-spoilers-sur-lenregistrement-secret-de-la-njpw-a-los-angeles\/","title":{"rendered":"Plus De D\u00e9taile et Spoilers Sur L&rsquo;enregistrement Secret De La NJPW \u00e0 Los Angeles!"},"content":{"rendered":"\n<p>Lors du dernier week-end, nous avons annonc\u00e9 que la New Japan Pro Wrestling avait tenu un enregistrement secret \u00e0 Los Angeles qui comprennait jusqu&rsquo;\u00e0 10 matchs et les d\u00e9buts promotionnels de la superstar MLW \u00ab\u00a0Filthy\u00a0\u00bb Tom Lawlor.<\/p>\n\n\n\n<p>Dans une mise \u00e0 jour du PW Insider, nous savons maintenant que Lawlor a travaill\u00e9 deux \u00e9pisodes en simple pendant l&rsquo;enregistrement. L&rsquo;un contre Rocky Romero et l&rsquo;autre contre Alex Coughlin. <\/p>\n\n\n\n<p>La MLW a \u00e9galement fait la promotion de l&rsquo;apparition de Lawlor sur leur site Web en mettant en avant une confrontation \u00abinter-promotionnelle\u00bb.<\/p>\n\n\n\n<p>Un nouveau rapport indique que le lieu de l&rsquo;enregistrement est situ\u00e9 au Pavillon Oceanville \u00e0 Port Hueneme, avec une production provenant de la Championship Wrestling de Dave Marquez \u00e0 Hollywood.<\/p>\n\n\n\n<p>Un autre affrontement est confirm\u00e9: Tyler Bateman contre Brody King de la ROH. <\/p>\n\n\n\n<p>La photo de l&rsquo;article n&rsquo;est pas un de cet \u00e9v\u00e9nement mais de la salle o\u00f9 le tout a \u00e9t\u00e9 film\u00e9 pour vous donner une id\u00e9e de l&rsquo;endroit. <\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Lors du dernier week-end, nous avons annonc\u00e9 que la New Japan Pro Wrestling avait tenu un enregistrement secret \u00e0 Los Angeles qui comprennait jusqu&rsquo;\u00e0 10 matchs et les d\u00e9buts promotionnels de la superstar MLW \u00ab\u00a0Filthy\u00a0\u00bb Tom Lawlor. Dans une mise \u00e0 jour du PW Insider, nous savons maintenant que Lawlor a travaill\u00e9 deux \u00e9pisodes en&#8230;<\/p>\n","protected":false},"author":665,"featured_media":29960,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24,22,55,4,49],"tags":[],"ppma_author":[289],"class_list":["post-29658","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aew-impact-njpw-roh","category-indy","category-njpw","category-news","category-roh"],"authors":[{"term_id":289,"user_id":665,"is_guest":0,"slug":"line","display_name":"Line Edmond","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/852de09636413c90cdaa278312f9ea5bc4396768745424755cb63d99a05989d0?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/29658","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/665"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=29658"}],"version-history":[{"count":4,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/29658\/revisions"}],"predecessor-version":[{"id":29961,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/29658\/revisions\/29961"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/29960"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=29658"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=29658"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=29658"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=29658"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}