{"id":29632,"date":"2020-06-14T13:46:07","date_gmt":"2020-06-14T17:46:07","guid":{"rendered":"http:\/\/www.jdx.info\/lutte\/?p=29632"},"modified":"2020-06-14T13:46:11","modified_gmt":"2020-06-14T17:46:11","slug":"drew-mcintyre-aime-travailler-avec-heyman-au-micro-avoir-ete-a-impact-la-aider-a-etre-meilleur-il-fait-la-lecon-en-ligne-aux-enfants-ddp-yoga-meme-pour-le-champion-wwe","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2020\/06\/14\/drew-mcintyre-aime-travailler-avec-heyman-au-micro-avoir-ete-a-impact-la-aider-a-etre-meilleur-il-fait-la-lecon-en-ligne-aux-enfants-ddp-yoga-meme-pour-le-champion-wwe\/","title":{"rendered":"Drew McIntyre Aime Travailler Avec Heyman Au Micro! Avoir \u00c9t\u00e9 \u00e0 Impact L&rsquo;a  Aider \u00e0 \u00catre Meilleur! Il Fait La Le\u00e7on En Ligne Aux Enfants! DDP Yoga M\u00eame Pour Le Champion WWE!"},"content":{"rendered":"\n<p>Le champion de la WWE, Drew McIntyre, s&rsquo;est entretenu avec TV Insider pour promouvoir ppv de la Backlash de ce soir, o\u00f9 le psychopathe \u00e9cossais d\u00e9fendra l&rsquo;or contre Bobby Lashley. Vous trouverez ci-dessous les faits saillants de l&rsquo;entrevue.<\/p>\n\n\n\n<p><strong>Ses r\u00e9flexions sur Paul Heyman perdant son poste de directeur ex\u00e9cutif de RAW:<\/strong><\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>Je ne connais pas les tenants et aboutissants de la cr\u00e9ation. Je re\u00e7ois ma se que j&rsquo;ai \u00e0 faire et je pars de l\u00e0. Je trouve ce qui est le mieux qui fonctionne pour Drew McIntyre et le sc\u00e9nario. Concernant le personnage de Paul Heyman, c&rsquo;est tr\u00e8s int\u00e9ressant pour moi. La derni\u00e8re fois que nous avons interagi, j&rsquo;allais \u00e0 WrestleMania contre Brock Lesnar avant de le vaincre en cinq minutes dans le main event. Il se peut que des choses se produisent en cours de route. Brock se cache dans l&rsquo;ombre. S&rsquo;il veut se faire battre en trois et 23 secondes cette fois. Ou peut-\u00eatre que Paul Heyman a les yeux riv\u00e9s sur d&rsquo;autres superstars qu&rsquo;il veut amener \u00e0 Drew McIntyre. Quoi qu&rsquo;il en soit, j&rsquo;aime toujours une petite blague avec Paul Heyman au micro. Il n&rsquo;y a personne de mieux que lui. Cela vous oblige \u00e0 am\u00e9liorer votre jeu. J&rsquo;esp\u00e8re que nous le verrons assez t\u00f4t.<\/p><\/blockquote>\n\n\n\n<p><strong> Ce qu&rsquo;il pense de son titre actuel:<\/strong><\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>C&rsquo;est tout ce que j&rsquo;imaginais \u00eatre dans les limites d&rsquo;une pand\u00e9mie. Je connais mon parcours unique de tous les hauts et les bas, \u00eatre lib\u00e9r\u00e9 avant et me retrouver en tant que personne et interpr\u00e8te (\u00e0 Impact Wrestling). Cela m&rsquo;a pr\u00e9par\u00e9 \u00e0 \u00eatre non seulement l&rsquo;un des meilleurs gars, mais le meilleur gars de l&rsquo;entreprise qui peut g\u00e9rer toute situation qui lui est pr\u00e9sent\u00e9e.<\/p><\/blockquote>\n\n\n\n<p><strong>Un moment fort pour lui en dehors du ring:<\/strong><\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>Il y a tellement de choses dont je suis fier en ce moment. Je pense que j&rsquo;ai film\u00e9 du contenu pour BBC Bitesize [ressource d&rsquo;\u00e9tude pour les \u00e9tudiants] au Royaume-Uni. C&rsquo;est des le\u00e7ons amusantes pour les enfants. Puisqu&rsquo;ils font beaucoup de d&rsquo;\u00e9tudes via webcam, j&rsquo;ai particip\u00e9 \u00e0 une vid\u00e9o tr\u00e8s divertissante sur la ponctuation. C&rsquo;est moi qui expliquais la ponctuation. Quelques copains m&rsquo;ont d\u00e9j\u00e0 envoy\u00e9 un message: \u00abOh mon Dieu. Je suis surpris d&rsquo;avoir entendu ta voix dans l&rsquo;autre pi\u00e8ce. Je n&rsquo;ai jamais vu mes enfants pr\u00eater autant d&rsquo;attention \u00e0 leurs le\u00e7ons. \u00a0\u00bb Mis \u00e0 part toutes les responsabilit\u00e9s de champion, se quereller avec Tyson Fury et Colby Covington en ligne. Le truc de la BBC est un exemple de la fa\u00e7on dont je peux vraiment faire une diff\u00e9rence pour les enfants et leur apprentissage.<\/p><\/blockquote>\n\n\n\n<p><strong>Prendre soin de lui pour \u00e9viter les blessures:<\/strong><\/p>\n\n\n\n<p>Je ne pense pas avoir tellement chang\u00e9, \u00e0 part la fermeture du gymnase. Ma femme et moi avons finalement commenc\u00e9 \u00e0 ajouter du mat\u00e9riel de gym dans le garage. Je m&rsquo;entra\u00eene l\u00e0. Je m&rsquo;y suis entra\u00een\u00e9 avant WrestleMania un peu comme Scottish Rocky. Le temps suppl\u00e9mentaire pour la r\u00e9cup\u00e9ration fait d\u00e9finitivement la diff\u00e9rence. Nous avons un peu de temps suppl\u00e9mentaire en raison de l&rsquo;enregistrement du contenu. Je suis toujours conscient de mon alimentation, de ma consommation d&rsquo;eau. Je fais beaucoup d&rsquo;\u00e9tirements. Je fais beaucoup de yoga DDP. Le programme de Diamond Dallas Page qui n&rsquo;implique pas seulement le yoga mais la r\u00e9\u00e9ducation et les mouvements. En tant que champion, je ne veux vraiment pas me blesser. Je suis extr\u00eamement prudent.<\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Le champion de la WWE, Drew McIntyre, s&rsquo;est entretenu avec TV Insider pour promouvoir ppv de la Backlash de ce soir, o\u00f9 le psychopathe \u00e9cossais d\u00e9fendra l&rsquo;or contre Bobby Lashley. Vous trouverez ci-dessous les faits saillants de l&rsquo;entrevue. Ses r\u00e9flexions sur Paul Heyman perdant son poste de directeur ex\u00e9cutif de RAW: Je ne connais pas&#8230;<\/p>\n","protected":false},"author":609,"featured_media":29644,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[52,4,45,23],"tags":[],"ppma_author":[295],"class_list":["post-29632","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-backlash","category-news","category-ppv-wwe","category-wwe"],"authors":[{"term_id":295,"user_id":609,"is_guest":0,"slug":"rodrigo","display_name":"Rodrigue Tousignant","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/51fe284bb6dbe8a6b4c2bf998ad658f4a9cd24b7e58f15ec85888070c7340ce6?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/29632","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/609"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=29632"}],"version-history":[{"count":1,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/29632\/revisions"}],"predecessor-version":[{"id":29645,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/29632\/revisions\/29645"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/29644"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=29632"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=29632"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=29632"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=29632"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}