{"id":29587,"date":"2020-06-14T02:36:05","date_gmt":"2020-06-14T06:36:05","guid":{"rendered":"http:\/\/www.jdx.info\/lutte\/?p=29587"},"modified":"2020-06-14T02:39:12","modified_gmt":"2020-06-14T06:39:12","slug":"drew-mcintyre-pense-quun-match-contre-undertaker-serait-absolument-efficace","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2020\/06\/14\/drew-mcintyre-pense-quun-match-contre-undertaker-serait-absolument-efficace\/","title":{"rendered":"Drew McIntyre Pense Qu&rsquo;un Match Contre Undertaker Serait \u00abAbsolument Efficace\u00bb!"},"content":{"rendered":"\n<p>Le champion de la WWE Drew McIntyre a r\u00e9cemment discut\u00e9 avec le Daily Star pour discuter d&rsquo;une \u00e9ventuelle confrontation avec The Undertaker. Le psychopathe \u00e9cossais estime que lui et l&rsquo;histoire commune du Deadman ensemble, en feraient une bonne, et pense qu&rsquo;un futur combat entre les deux serait \u00ababsolument parfait\u00bb.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>Il y a plus de dix ans, nous allions organiser un grand match en simple avec The Undertaker et moi. Nous avons eu le match juste avant le sien avec Shawn Michaels lorqu&rsquo;il a pris sa retraite. C&rsquo;\u00e9tait ma premi\u00e8re d\u00e9faite officielle. Nous avons \u00e9galement eu un match par \u00e9quipe dans lequel  nous nous sommes affront\u00e9s,  quelques instants.<br><br>La foule a commenc\u00e9 \u00e0 gronder quand il a commenc\u00e9 \u00e0 couper sa gorge. Je me suis lev\u00e9 derri\u00e8re lui et Roman l&rsquo;a sauv\u00e9 du Claymore. Apr\u00e8s il a sembl\u00e9 assez content. Je pense vraiment, \u00e9tant donn\u00e9 les circonstances et compte tenu de notre histoire et du fait qu&rsquo;il m&rsquo;a donn\u00e9 ma premi\u00e8re d\u00e9faite officielle, qu&rsquo;il y a une bonne histoire l\u00e0-dedans. Je sais que le match pourrait \u00eatre livrer. <\/p><\/blockquote>\n\n\n\n<p>McIntyre a d\u00e9clar\u00e9 que dans le pass\u00e9,  lui et Taker \u00e9taient cens\u00e9s avoir une \u00e9norme rivalit\u00e9 en simple \u00e0 WrestleMania, mais les plans ont chang\u00e9s comme c&rsquo;est souvent le cas.<\/p>\n\n\n\n<p><strong><a href=\"https:\/\/www.facebook.com\/InfoLutte\/posts\/603068576985485\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"Vous aimeriez que ce match arrive un jour, venez en discuter avec nous en cliquant ici. (s\u2019ouvre dans un nouvel onglet)\">Vous aimeriez que ce match arrive un jour, venez en discuter avec nous en cliquant ici.<\/a><\/strong><\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Le champion de la WWE Drew McIntyre a r\u00e9cemment discut\u00e9 avec le Daily Star pour discuter d&rsquo;une \u00e9ventuelle confrontation avec The Undertaker. Le psychopathe \u00e9cossais estime que lui et l&rsquo;histoire commune du Deadman ensemble, en feraient une bonne, et pense qu&rsquo;un futur combat entre les deux serait \u00ababsolument parfait\u00bb. Il y a plus de dix&#8230;<\/p>\n","protected":false},"author":665,"featured_media":29605,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,23],"tags":[],"ppma_author":[289],"class_list":["post-29587","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-wwe"],"authors":[{"term_id":289,"user_id":665,"is_guest":0,"slug":"line","display_name":"Line Edmond","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/852de09636413c90cdaa278312f9ea5bc4396768745424755cb63d99a05989d0?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/29587","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/665"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=29587"}],"version-history":[{"count":3,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/29587\/revisions"}],"predecessor-version":[{"id":29606,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/29587\/revisions\/29606"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/29605"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=29587"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=29587"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=29587"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=29587"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}