{"id":29579,"date":"2020-06-13T15:24:27","date_gmt":"2020-06-13T19:24:27","guid":{"rendered":"http:\/\/www.jdx.info\/lutte\/?p=29579"},"modified":"2020-06-13T15:24:32","modified_gmt":"2020-06-13T19:24:32","slug":"edge-a-mit-tout-son-coeur-et-son-ame-sur-le-greatest-wrestling-match-ever","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2020\/06\/13\/edge-a-mit-tout-son-coeur-et-son-ame-sur-le-greatest-wrestling-match-ever\/","title":{"rendered":"Edge A Mit Tout Son Coeur Et Son \u00c2me Sur Le \u00ab\u00a0Greatest Wrestling Match Ever\u00a0\u00bb!"},"content":{"rendered":"\n<p>Une fois de plus retournons en d\u00e9but de semaine o\u00f9 Edge expliquait que selon lui son combat \u00e0\u00a0WWE Backlash face \u00e0 Randy Orton serait une promesse impossible\u00a0tandis que la compagnie annonce leur combat comme \u00e9tant \u00a0\u00bble plus grand combat de tous les temps\u00a0\u00bb.<\/p>\n\n\n\n<p>Aujourd&rsquo;hui Edge a publi\u00e9 un long message sur Twitter o\u00f9 il explique que son combat de dimanche face \u00e0 Randy Orton n&rsquo;est pas un challenge facile, il s&rsquo;agira de son premier combat de catch en solo en neuf ans et demi apr\u00e8s une op\u00e9ration au cou. Sans oublier qu&rsquo;il a pr\u00e9sentement 46 ans, c\u2019est un combat pendant une pand\u00e9mie avec un public restreint. Il dit que c&rsquo;est un \u00e9norme challenge pour lui et qu&rsquo;il a mis tout son coeur et son \u00e2me dans ce match :<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u00a0\u00bbJ&rsquo;ai mis tout mon coeur et mon \u00e2me dans ce match. J&rsquo;ai \u00e9tudi\u00e9. Je n&rsquo;ai pas beaucoup dormi. Car pour moi c&rsquo;est important. Mon \u00e9thique de travail est importante. Mes capacit\u00e9s sont importantes. Cette forme d&rsquo;art est importante et je l&rsquo;aime plus que tout. Rien n&rsquo;est comparable. C&rsquo;est mon r\u00eave de jeunesse.\u00a0\u00bb<\/p><\/blockquote>\n\n\n\n<p>Edge termine en disant que dimanche \u00e0 Backlash nous allons voir deux hommes qui vont tout donner ce qu&rsquo;ils ont lors d&rsquo;une soir\u00e9e. Il veut s&rsquo;assurer de nous divertir pendant cette p\u00e9riode et le meilleur combat de tous les temps restera un sujet subjectif.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><a href=\"https:\/\/www.jdx.info\/lutte\/2020\/06\/11\/mise-a-jour-du-wwe-backlash-et-renseignement-pour-le-streaming\/\"><strong>Pour la carte compl\u00e8te et savoir comment voir le WWE BackLash, cliquez ici.<\/strong><\/a><\/p>\n\n\n\n<center><blockquote class=\"twitter-tweet\"><p lang=\"und\" dir=\"ltr\"><a href=\"https:\/\/twitter.com\/hashtag\/Backlash?src=hash&amp;ref_src=twsrc%5Etfw\">#Backlash<\/a> <a href=\"https:\/\/t.co\/XmEky6TJab\">pic.twitter.com\/XmEky6TJab<\/a><\/p>&mdash; Adam (Edge) Copeland (@EdgeRatedR) <a href=\"https:\/\/twitter.com\/EdgeRatedR\/status\/1271802489206120450?ref_src=twsrc%5Etfw\">June 13, 2020<\/a><\/blockquote> <script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/center>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Une fois de plus retournons en d\u00e9but de semaine o\u00f9 Edge expliquait que selon lui son combat \u00e0\u00a0WWE Backlash face \u00e0 Randy Orton serait une promesse impossible\u00a0tandis que la compagnie annonce leur combat comme \u00e9tant \u00a0\u00bble plus grand combat de tous les temps\u00a0\u00bb. Aujourd&rsquo;hui Edge a publi\u00e9 un long message sur Twitter o\u00f9 il explique&#8230;<\/p>\n","protected":false},"author":665,"featured_media":29580,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,43,23],"tags":[],"ppma_author":[289],"class_list":["post-29579","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-raw-wwe","category-wwe"],"authors":[{"term_id":289,"user_id":665,"is_guest":0,"slug":"line","display_name":"Line Edmond","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/852de09636413c90cdaa278312f9ea5bc4396768745424755cb63d99a05989d0?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/29579","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/665"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=29579"}],"version-history":[{"count":1,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/29579\/revisions"}],"predecessor-version":[{"id":29581,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/29579\/revisions\/29581"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/29580"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=29579"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=29579"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=29579"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=29579"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}