{"id":29162,"date":"2020-06-09T01:00:00","date_gmt":"2020-06-09T05:00:00","guid":{"rendered":"http:\/\/www.jdx.info\/lutte\/?p=29162"},"modified":"2020-06-09T02:43:27","modified_gmt":"2020-06-09T06:43:27","slug":"randy-orton-riposte-a-tommaso-ciampa-appelle-fan-une-putin-de-mark","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2020\/06\/09\/randy-orton-riposte-a-tommaso-ciampa-appelle-fan-une-putin-de-mark\/","title":{"rendered":"Randy Orton riposte \u00e0 Tommaso Ciampa, Appelle un Fan \u00abUn Putin de Mark\u00bb"},"content":{"rendered":"\n<p>La guerre des tweets entre les superstars de la NXT Tommaso Ciampa et de RAW Randy Orton c&rsquo;est poursuivie sur Twitter ce soir.<\/p>\n\n\n\n<p>Orton est all\u00e9 sur Twitter apr\u00e8s l&rsquo;\u00e9mission NXT \u00ab\u00a0Takeover: In Your House\u00a0\u00bb pour plaisanter sur les gifles aux jambes, quelque chose qui a r\u00e9cemment \u00e9t\u00e9 un sujet de discussion sur les m\u00e9dias sociaux de lutte professionnelle. Les claques sur les cuisses pour faire un bruit lors des coups.<\/p>\n\n\n\n<p>Orton a \u00e9crit: <\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u00abEntendu #WWENXT #TakeoverInYourHouse \u00e9tait super! Gifl\u00e9 ma jambe pour vous les gars. Cordialement #legslap <\/p><\/blockquote>\n\n\n\n<p>Ciampa a ripost\u00e9 cet apr\u00e8s-midi. Il a \u00e9crit:<\/p>\n\n\n\n<p> \u00abMa fille a du mal \u00e0 dormir. Heureusement, j&rsquo;ai trouv\u00e9 un rem\u00e8de. Matchs de Randy Orton. Mieux que NyQuil. Cordialement #AnEntireLockerRoomWhoBustedTheirAsses \u00bb<\/p>\n\n\n\n<p>Dans une mise \u00e0 jour, Orton est all\u00e9 sur Twitter cet apr\u00e8s-midi et a r\u00e9pondu \u00e0 Ciampa, <\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u00abOn dirait que j&rsquo;ai bless\u00e9 les sentiments du chef de vestiaire autoproclam\u00e9 d&rsquo;une \u00e9cole de lutte. Faites-moi savoir \u00e0 quelle heure commence le cours #legslap pour que je puisse amener mon jeu au niveau sup\u00e9rieur \u00bb<\/p><\/blockquote>\n\n\n\n<p>Orton a \u00e9galement r\u00e9pondu \u00e0 un fan et l&rsquo;a qualifi\u00e9 de \u00abputain de mark\u00bb en r\u00e9ponse \u00e0 un tweet. Le fan a r\u00e9pondu au tweet original d&rsquo;Orton \u00e0 propos des \u00abgifles aux jambes\u00bb lors de TakeOver et a \u00e9crit: <\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u00abJ&rsquo;ai entendu que Backlash sera mauvais\u00bb<\/p><\/blockquote>\n\n\n\n<p>Orton, qui affrontera le WWE Hall of Famer Edge \u00e0 Backlash dans un match enregistr\u00e9 dimanche dernier, a ripost\u00e9 contre le fan.<\/p>\n\n\n\n<p>\u00abOuais? Qui a dit? C&rsquo;est dans une semaine, putain de mark #greatestwrestlingmatchever \u00ab\u00a0<\/p>\n\n\n\n<p>Ciampa n&rsquo;a pas r\u00e9pondu au dernier tweet d&rsquo;Orton \u00e0 ce jour, mais nous vous tiendrons au courant. <\/p>\n\n\n\n<p>Vous pouvez voir les messages originaux ci-dessous:<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p>\n<blockquote class=\"twitter-tweet\"><p lang=\"en\" dir=\"ltr\">My daughter has been having trouble sleeping. Luckily I found a remedy. Randy Orton matches. Better than NyQuil. Sincerely <a href=\"https:\/\/twitter.com\/hashtag\/AnEntireLockerRoomWhoBustedTheirAsses?src=hash&amp;ref_src=twsrc%5Etfw\">#AnEntireLockerRoomWhoBustedTheirAsses<\/a> <a href=\"https:\/\/t.co\/r2HN5TjwOY\">https:\/\/t.co\/r2HN5TjwOY<\/a><\/p>\u2014 BLACKHEART (@NXTCiampa) <a href=\"https:\/\/twitter.com\/NXTCiampa\/status\/1270055616355205120?ref_src=twsrc%5Etfw\">June 8, 2020<\/a><\/blockquote> <script async=\"\" src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/center>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>La guerre des tweets entre les superstars de la NXT Tommaso Ciampa et de RAW Randy Orton c&rsquo;est poursuivie sur Twitter ce soir. Orton est all\u00e9 sur Twitter apr\u00e8s l&rsquo;\u00e9mission NXT \u00ab\u00a0Takeover: In Your House\u00a0\u00bb pour plaisanter sur les gifles aux jambes, quelque chose qui a r\u00e9cemment \u00e9t\u00e9 un sujet de discussion sur les m\u00e9dias&#8230;<\/p>\n","protected":false},"author":665,"featured_media":29167,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,43,23],"tags":[],"ppma_author":[289],"class_list":["post-29162","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-raw-wwe","category-wwe"],"authors":[{"term_id":289,"user_id":665,"is_guest":0,"slug":"line","display_name":"Line Edmond","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/852de09636413c90cdaa278312f9ea5bc4396768745424755cb63d99a05989d0?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/29162","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/665"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=29162"}],"version-history":[{"count":8,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/29162\/revisions"}],"predecessor-version":[{"id":29175,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/29162\/revisions\/29175"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/29167"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=29162"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=29162"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=29162"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=29162"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}