{"id":28924,"date":"2020-06-07T21:43:12","date_gmt":"2020-06-08T01:43:12","guid":{"rendered":"http:\/\/www.jdx.info\/lutte\/?p=28924"},"modified":"2020-06-07T21:45:43","modified_gmt":"2020-06-08T01:45:43","slug":"charlotte-flair-dit-quelle-est-fiere-de-ce-que-tessa-blanchard-a-accompli-dans-impact-et-veut-defier-pour-le-championnat-masculin-sur-toute-la-ligne","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2020\/06\/07\/charlotte-flair-dit-quelle-est-fiere-de-ce-que-tessa-blanchard-a-accompli-dans-impact-et-veut-defier-pour-le-championnat-masculin-sur-toute-la-ligne\/","title":{"rendered":"Charlotte Flair dit qu&rsquo;elle est fi\u00e8re de ce que Tessa Blanchard a accompli \u00e0 IMPACT, et veut un match pour un championnat masculin !"},"content":{"rendered":"\n<p>La superstar de la WWE, Charlotte Flair, s&rsquo;est entretenue avec Sportskeeda o\u00f9 la championne f\u00e9minine NXT a rendu hommage \u00e0 l&rsquo;actuelle championne du monde IMPACT (hommes) Tessa Blanchard. La Reine d\u00e9clare qu&rsquo;elle est fi\u00e8re de tout ce que Blanchard a accompli depuis qu&rsquo;elle a rejoint la soci\u00e9t\u00e9 rivale, puis affirme qu&rsquo;elle esp\u00e8re suivre son chemin et d\u00e9fier un titre masculin sur toute la ligne \u00e0 la WWE. <\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>C\u2019est quelque chose que je veux poursuivre, mais si vous regardez la situation dans son ensemble, lorsque les femmes r\u00e9ussissent dans diff\u00e9rentes organisations \u00e0 travers le monde, nous r\u00e9ussissons toutes et nous gagnons toutes gr\u00e2ce \u00e0 cela \u00bb, dirait Charlotte. \u00abDonc, pour elle, tenir cette distinction est juste, nous devons soutenir et \u00eatre extr\u00eamement fiers, en tant que femme, de la voir faire cela parce que quand on se porte bien, nous nous portons tous bien. C\u2019est ce qui a \u00e0 peu pr\u00e8s motiv\u00e9 l\u2019\u00e9volution des femmes, c\u2019est que nous travaillons mieux en nombre, donc ce n\u2019est pas quelque chose auquel je pense en ce moment, mais je ne pourrais pas \u00eatre plus fi\u00e8re et heureuse de ce qu\u2019elle fait pour les femmes du monde entier. <\/p><\/blockquote>\n\n\n\n<p>Flair est pr\u00eat \u00e0 d\u00e9fendre le titre f\u00e9minin NXT contre Rhea Ripley et Io Shirai lors de la prise de contr\u00f4le de ce soir \u00e0 la maison par Full Sail University.<\/p>\n\n\n\n<p><a href=\"https:\/\/www.jdx.info\/lutte\/2020\/06\/07\/resultats-du-nxt-takeover-in-your-house-2020\/\">L&rsquo;entrevue a \u00e9t\u00e9 faite avant TakeOver mais si vous voulez savoir ce qui c&rsquo;est pass\u00e9 ou voir ce PPV de la NXT, cliquez sur ce lien ici.<\/a><\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>La superstar de la WWE, Charlotte Flair, s&rsquo;est entretenue avec Sportskeeda o\u00f9 la championne f\u00e9minine NXT a rendu hommage \u00e0 l&rsquo;actuelle championne du monde IMPACT (hommes) Tessa Blanchard. La Reine d\u00e9clare qu&rsquo;elle est fi\u00e8re de tout ce que Blanchard a accompli depuis qu&rsquo;elle a rejoint la soci\u00e9t\u00e9 rivale, puis affirme qu&rsquo;elle esp\u00e8re suivre son chemin&#8230;<\/p>\n","protected":false},"author":665,"featured_media":28999,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,23],"tags":[],"ppma_author":[289],"class_list":["post-28924","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-wwe"],"authors":[{"term_id":289,"user_id":665,"is_guest":0,"slug":"line","display_name":"Line Edmond","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/852de09636413c90cdaa278312f9ea5bc4396768745424755cb63d99a05989d0?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/28924","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/665"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=28924"}],"version-history":[{"count":5,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/28924\/revisions"}],"predecessor-version":[{"id":29002,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/28924\/revisions\/29002"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/28999"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=28924"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=28924"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=28924"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=28924"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}