{"id":28663,"date":"2020-06-03T15:40:54","date_gmt":"2020-06-03T19:40:54","guid":{"rendered":"http:\/\/www.jdx.info\/lutte\/?p=28663"},"modified":"2020-06-03T15:40:59","modified_gmt":"2020-06-03T19:40:59","slug":"cm-punk-donne-un-conseil-aux-blancs-vis-a-vis-des-noirs","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2020\/06\/03\/cm-punk-donne-un-conseil-aux-blancs-vis-a-vis-des-noirs\/","title":{"rendered":"CM Punk Donne Un Conseil Aux Blancs Vis \u00e0 Vis Des Noirs!"},"content":{"rendered":"\n<p>Dans l&rsquo;\u00e9pisode de mardi soir, l&rsquo;ancienne superstar de la WWE et analyste de WWE Backstage, CM Punk, a parl\u00e9 des manifestations en cours dans le monde au nom de George Floyd, qui a \u00e9t\u00e9 brutalement \u00e9t\u00e9 assassin\u00e9 par un policier de Minneapolis qui est pour cet acte, accus\u00e9 de meurtre. Apr\u00e8s que le Hall of Famer de la WWE Mark Henry ait parl\u00e9 d&rsquo;assister \u00e0 une manifestation pacifique avec ses enfants, Punk a \u00e9t\u00e9 invit\u00e9 \u00e0 donner son avis.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>Je suis un Blanc. Je ne suis pas ici pour pr\u00e9tendre comprendre ce que ressentent les noirs. Je ne pense pas que ce soit \u00e0 moi de leur dire comment ils doivent r\u00e9agir. Ce pays a un probl\u00e8me. \u00c7a, je le sais. Je suis ici pour dire aux blancs\u2026 vous devez \u00e9couter vos fr\u00e8res et s\u0153urs noirs et vous devez comprendre d&rsquo;o\u00f9 ils viennent. Il est difficile d&rsquo;essayer de marcher dans la peau de quelqu&rsquo;un.<\/p><\/blockquote>\n\n\n\n<p>Punk mentionne la lutte contre l&rsquo;intol\u00e9rance par l&rsquo;intol\u00e9rance et dit aux Blancs d&rsquo;utiliser leur privil\u00e8ge pour prot\u00e9ger leurs fr\u00e8res et s\u0153urs noirs.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p> Ce pays\u2026 il y a pr\u00e8s de deux Am\u00e9riques. Quand je serai arr\u00eat\u00e9, je suis nerveux, je vais obtenir un billet. Je ne veux pas vivre quelque part o\u00f9\u2026 Mark si ton fils se fait arr\u00eater, il a peur d&rsquo;\u00eatre assassin\u00e9. Je suis juste ici pour dire aux Blancs que vous devez probablement vous taire davantage et que vous devez certainement \u00e9couter davantage. Il ya un probl\u00e8me. Le paradoxe est que la seule fa\u00e7on de traiter l&rsquo;intol\u00e9rance est l&rsquo;intol\u00e9rance. Si vous \u00eates une personne blanche, vous \u00eates plus que probablement privil\u00e9gi\u00e9. Utilisez ce privil\u00e8ge et soutenez vos fr\u00e8res et s\u0153urs noirs, surtout maintenant.<\/p><\/blockquote>\n\n\n\n<p>L&rsquo;ancien champion de la WWE se souvient alors des commentaires du pr\u00e9sident Donald Trump sur les marcheurs n\u00e9onazis de Charlottesville, les qualifiant de \u00abbraves gens\u00bb. Punk profite de ce moment pour se souvenir de son grand-p\u00e8re qui a combattu les nazis pendant la Seconde Guerre mondiale avant de rappeler \u00e0 nouveau \u00e0 ceux-ci de se prot\u00e9ger mutuellement.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>Le premier tatouage que j&rsquo;ai vu de ma vie \u00e9tait un num\u00e9ro sur le bras de mon grand-p\u00e8re \u2026 et il est mont\u00e9 \u00e0 cheval vers les chars nazis et maintenant nous sommes en 2020 et nous vivons dans un monde o\u00f9 le pr\u00e9sident dit que \u00ab\u00a0les nazis sont des gens tr\u00e8s bien\u00a0\u00bb, et vous ne pouvez pas revenir en arri\u00e8re et vous ne pouvez pas me dire qu&rsquo;il voulait dire quelque chose de diff\u00e9rent. Si vous \u00eates blancs\u2026 utilisez votre voix, prot\u00e9gez vos fr\u00e8res et s\u0153urs noirs et prot\u00e9gez les gens pour qui ce pays n&rsquo;a pas \u00e9t\u00e9 construit.<\/p><\/blockquote>\n\n\n\n<p class=\"has-medium-font-size\"><a href=\"https:\/\/www.jdx.info\/lutte\/2020\/06\/03\/regardez-le-wwe-backstage-du-2-juin-2020\/\"><strong>Pour voir ce WWE Backstage en entier, cliquez ici.<\/strong><\/a><\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<p>Vous \u00eates libre  de suivre d\u00e8s maintenant Info-Lutte via notre <a href=\"https:\/\/www.facebook.com\/InfoLutte\/\">page Facebook <\/a>ou <a href=\"https:\/\/twitter.com\/InfoLutte\">Twitter @INFOLUTTE<\/a>. Et merci ne ne pas quitter sans visiter ce qui est autour du site  pour nous aider \u00e0 vous en offrir toujours plus, ici m\u00eame sur votre site pr\u00e9f\u00e9r\u00e9<\/p>\n\n\n\n<p><br>\nVous voulez faire parti de l&rsquo;\u00e9quipe, contactez moi via Facebook en <a href=\"https:\/\/www.facebook.com\/JasonDarkCashDescoteaux\/\">cliquant ici<\/a><\/p>\n\n\n\n<figure><iframe loading=\"lazy\" src=\"https:\/\/www.facebook.com\/plugins\/post.php?href=https%3A%2F%2Fwww.facebook.com%2FJasonDarkCashDescoteaux%2Fposts%2F2928607343839111&amp;width=500\" width=\"500\" height=\"287\"><\/iframe><\/figure>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Dans l&rsquo;\u00e9pisode de mardi soir, l&rsquo;ancienne superstar de la WWE et analyste de WWE Backstage, CM Punk, a parl\u00e9 des manifestations en cours dans le monde au nom de George Floyd, qui a \u00e9t\u00e9 brutalement \u00e9t\u00e9 assassin\u00e9 par un policier de Minneapolis qui est pour cet acte, accus\u00e9 de meurtre. Apr\u00e8s que le Hall of&#8230;<\/p>\n","protected":false},"author":2,"featured_media":28664,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[30,4,23],"tags":[],"ppma_author":[287],"class_list":["post-28663","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ex-wwe","category-news","category-wwe"],"authors":[{"term_id":287,"user_id":2,"is_guest":0,"slug":"jason","display_name":"Jason Desc\u00f4teaux","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/f64adf6d13198c3a532c061cecd8672089a1e9a3d07c702dffe886a7e55a15eb?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/28663","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=28663"}],"version-history":[{"count":1,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/28663\/revisions"}],"predecessor-version":[{"id":28665,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/28663\/revisions\/28665"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/28664"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=28663"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=28663"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=28663"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=28663"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}