{"id":28215,"date":"2020-05-26T15:55:39","date_gmt":"2020-05-26T19:55:39","guid":{"rendered":"http:\/\/www.jdx.info\/lutte\/?p=28215"},"modified":"2020-05-26T16:01:50","modified_gmt":"2020-05-26T20:01:50","slug":"adam-cole-pourrait-quitter-la-wwe","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2020\/05\/26\/adam-cole-pourrait-quitter-la-wwe\/","title":{"rendered":"Adam Cole Pourrait Quitter La WWE!"},"content":{"rendered":"\n<p>Bienvenue pour ce bulletin qui concerne qu&rsquo;une rumeur pour le moment mais qui pourrait vite changer si le principal int\u00e9ress\u00e9 suit son coeur et non sa t\u00eate. <\/p>\n\n\n\n<p>Si cette rumeur devient nouvelle, le monde du catch\/Lutte pourrait \u00eatre sous le choc.<\/p>\n\n\n\n<p>Bien qui&rsquo;il soit actuellement le champion de NXT et tr\u00e8s important du c\u00f4t\u00e9 de NXT, en plus d&rsquo;\u00eatre le leader du clan Undisputed Era, l&rsquo;avenir d&rsquo;Adam Cole pourrait se poursuivre ailleurs qu&rsquo;\u00e0 la WWE.<\/p>\n\n\n\n<p>Un source quand m\u00eame bien inform\u00e9 rapporte que le contrat du champion Jaune et Noir se termine vraiment prochainement. La p\u00e9riode concern\u00e9 serait cet \u00e9t\u00e9 ou d\u00e9but septembre. S&rsquo;il se retrouvait libre contractuellement. <\/p>\n\n\n\n<p>Il se dit m\u00eame que la AEW o\u00f9 se trouvent sa petite amie Britt Baker et ses amis de The Elite, parlerait d\u00e9j\u00e0 non officiellement avec lui de faire le saut \u00e0 Jacksonville. Car techniquement tant qu&rsquo;il est sous contrat ils n&rsquo;ont pas le droit de tenter de le n\u00e9gocier mais nous ne sommes plus du temps de la guerre froide entre Moscou et Washington et les soldats se parlent quand m\u00eame entre eux.<\/p>\n\n\n\n<p>La WWE a rat\u00e9 l&rsquo;opportunit\u00e9 de le rendre heureux et n&rsquo;a pas sign\u00e9 Britt Baker du temps qu&rsquo;elle \u00e9tait libre comme l&rsquo;aire, cela pourrait bien entr\u00e9e celui qui a prit la d\u00e9cision de ne pas le faire.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><a href=\"https:\/\/www.facebook.com\/InfoLutte\/posts\/591555504803459?\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"Vous pouvez venir en discuter avec nous sur notre page Facebook, suffit de cliquer l\u00e0. (s\u2019ouvre dans un nouvel onglet)\"><strong>Vous pouvez venir en discuter avec nous sur notre page Facebook, suffit de cliquer l\u00e0.<\/strong><\/a><\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Bienvenue pour ce bulletin qui concerne qu&rsquo;une rumeur pour le moment mais qui pourrait vite changer si le principal int\u00e9ress\u00e9 suit son coeur et non sa t\u00eate. Si cette rumeur devient nouvelle, le monde du catch\/Lutte pourrait \u00eatre sous le choc. Bien qui&rsquo;il soit actuellement le champion de NXT et tr\u00e8s important du c\u00f4t\u00e9 de&#8230;<\/p>\n","protected":false},"author":609,"featured_media":28216,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24,22,4,23],"tags":[],"ppma_author":[295],"class_list":["post-28215","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aew-impact-njpw-roh","category-indy","category-news","category-wwe"],"authors":[{"term_id":295,"user_id":609,"is_guest":0,"slug":"rodrigo","display_name":"Rodrigue Tousignant","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/51fe284bb6dbe8a6b4c2bf998ad658f4a9cd24b7e58f15ec85888070c7340ce6?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/28215","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/609"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=28215"}],"version-history":[{"count":3,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/28215\/revisions"}],"predecessor-version":[{"id":28219,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/28215\/revisions\/28219"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/28216"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=28215"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=28215"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=28215"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=28215"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}