{"id":26901,"date":"2020-05-10T15:15:59","date_gmt":"2020-05-10T19:15:59","guid":{"rendered":"http:\/\/www.jdx.info\/lutte\/?p=26901"},"modified":"2020-05-10T15:16:04","modified_gmt":"2020-05-10T19:16:04","slug":"the-man-passe-a-jamais-dans-lhistoire-de-la-wwe-gardera-telle-son-titre-encore-longtemps-avec-une-nouvelle-miss-money-in-the-bank","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2020\/05\/10\/the-man-passe-a-jamais-dans-lhistoire-de-la-wwe-gardera-telle-son-titre-encore-longtemps-avec-une-nouvelle-miss-money-in-the-bank\/","title":{"rendered":"The Man Passe \u00e0 Jamais Dans l&rsquo;Histoire de la WWE! Gardera T&rsquo;elle Son Titre Encore Longtemps Avec Une Nouvelle Miss Money In The Bank!"},"content":{"rendered":"\n<p>Becky Lynch est devenue la championne de RAW avec le plus long r\u00e8gne de l&rsquo;histoire que ce soit en un seul r\u00e8gne ou en plusieurs r\u00e8gnes cons\u00e9cutifs.<\/p>\n\n\n\n<p>Alexa Bliss \u00e9tait en premi\u00e8re position avec 396 jours comme championne sur un total de trois r\u00e8gnes mais voil\u00e0 que Becky Lynch a atteint les 397 jours aujourd&rsquo;hui, et ce, en un seul r\u00e8gne. <\/p>\n\n\n\n<p>The Man a remport\u00e9 le titre dans la finale de WrestleMania 35, l&rsquo;an pass\u00e9, face \u00e0 Ronda Rousey et Charlotte Flair et depuis, elle ne l&rsquo;a toujours pas perdu.<\/p>\n\n\n\n<p>On se souviendra alors qu&rsquo;elle avait \u00e0 ce moment les deux ceintures, celle de Smackdown qu&rsquo;elle avait d\u00e9j\u00e0 avant d&rsquo;entrer dans le match!<\/p>\n\n\n\n<p>On peut s&rsquo;imaginer que le 400e jour arrivera facilement, \u00e0 moins que la gagnante Money in the Bank encaisse directement sa mallette face \u00e0 Becky Lynch tr\u00e8s bient\u00f4t. D&rsquo;ailleurs, on sait d\u00e9j\u00e0 que ce lundi \u00e0 RAW, le 11 mai, Becky confrontera Miss Money in the Bank au micro.<\/p>\n\n\n\n<p>Gardera t&rsquo;elle son titre encore longtemps? Ce sera \u00e0 suivre!<\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Becky Lynch est devenue la championne de RAW avec le plus long r\u00e8gne de l&rsquo;histoire que ce soit en un seul r\u00e8gne ou en plusieurs r\u00e8gnes cons\u00e9cutifs. Alexa Bliss \u00e9tait en premi\u00e8re position avec 396 jours comme championne sur un total de trois r\u00e8gnes mais voil\u00e0 que Becky Lynch a atteint les 397 jours aujourd&rsquo;hui,&#8230;<\/p>\n","protected":false},"author":4,"featured_media":26912,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[46,4,23],"tags":[],"ppma_author":[292],"class_list":["post-26901","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-money-in-the-bank","category-news","category-wwe"],"authors":[{"term_id":292,"user_id":4,"is_guest":0,"slug":"jean","display_name":"Jean Vinnier","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/33aba0263fd870a0b487e0e079ff407e10e3997c9d2987cbcc0db0db2c5c75a9?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/26901","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=26901"}],"version-history":[{"count":1,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/26901\/revisions"}],"predecessor-version":[{"id":26913,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/26901\/revisions\/26913"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/26912"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=26901"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=26901"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=26901"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=26901"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}