{"id":24954,"date":"2020-04-09T13:59:53","date_gmt":"2020-04-09T17:59:53","guid":{"rendered":"http:\/\/www.jdx.info\/lutte\/?p=24954"},"modified":"2020-04-09T14:27:47","modified_gmt":"2020-04-09T18:27:47","slug":"le-show-de-paris-repousse-en-octobre-mais","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2020\/04\/09\/le-show-de-paris-repousse-en-octobre-mais\/","title":{"rendered":"Le Show De Paris Repouss\u00e9 En Octobre Mais&#8230;"},"content":{"rendered":"\n<p>Come vous le savez, la WWE devait revenir en France le samedi 16 mai pour un show \u00e0 l&rsquo;AccorHotels Arena de Paris. Cependant, apr\u00e8s avoir annul\u00e9 tous les \u00e9v\u00e9nements en raison de la pand\u00e9mie du coronavirus, il fallait s&rsquo;attendre \u00e0 rien de moins concernant la tourn\u00e9e europ\u00e9enne de la f\u00e9d\u00e9ration. <\/p>\n\n\n\n<p>C&rsquo;est maintenant officiel :&nbsp;WWE Paris est report\u00e9 !<\/p>\n\n\n\n<p>L&rsquo;AccorHotels Arena nous informe que&nbsp;le show du samedi 16 mai a \u00e9t\u00e9 report\u00e9 au jeudi 8 octobre. Tous les billets (parking inclus) sont toujours valables pour cette date. Si des personnes veulent se faire rembourser, il faut se tourner vers le point de vente l\u00e9gal. Ce qui veut dire que ceux qui ont achet\u00e9 sur des site de revente, il vaut mieux le garder pour la prochaine date car il vous sera difficile de vous faire rembourser sauf avis contraire. <\/p>\n\n\n\n<p>Rendez-vous donc en octobre si la situation revient \u00e0 la normal car nous avons apprit via une personne bien plac\u00e9 \u00e0 la OMS (Organisme Mondial de la Sant\u00e9) que les grands rassemblements ne devraient pas reprendre en 2020, bien que chaque pays et chaque \u00e9tat et ville y vont \u00e0 leur rythme. <\/p>\n\n\n\n<blockquote class=\"twitter-tweet\"><p lang=\"fr\" dir=\"ltr\">[INFORMATION 9 AVRIL] Communication concernant l&rsquo;\u00e9v\u00e9nement WWE LIVE \u00e0 l&rsquo;AccorHotels Arena <a href=\"https:\/\/t.co\/rpSnoHn1RF\">pic.twitter.com\/rpSnoHn1RF<\/a><\/p>\u2014 AccorHotels Arena (@AccorH_Arena) <a href=\"https:\/\/twitter.com\/AccorH_Arena\/status\/1248241776567214081?ref_src=twsrc%5Etfw\">April 9, 2020<\/a><\/blockquote> <script async=\"\" src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Come vous le savez, la WWE devait revenir en France le samedi 16 mai pour un show \u00e0 l&rsquo;AccorHotels Arena de Paris. Cependant, apr\u00e8s avoir annul\u00e9 tous les \u00e9v\u00e9nements en raison de la pand\u00e9mie du coronavirus, il fallait s&rsquo;attendre \u00e0 rien de moins concernant la tourn\u00e9e europ\u00e9enne de la f\u00e9d\u00e9ration. C&rsquo;est maintenant officiel :&nbsp;WWE Paris&#8230;<\/p>\n","protected":false},"author":4,"featured_media":24963,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,28,23],"tags":[],"ppma_author":[292],"class_list":["post-24954","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-vf","category-wwe"],"authors":[{"term_id":292,"user_id":4,"is_guest":0,"slug":"jean","display_name":"Jean Vinnier","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/33aba0263fd870a0b487e0e079ff407e10e3997c9d2987cbcc0db0db2c5c75a9?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/24954","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=24954"}],"version-history":[{"count":3,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/24954\/revisions"}],"predecessor-version":[{"id":24964,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/24954\/revisions\/24964"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/24963"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=24954"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=24954"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=24954"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=24954"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}