{"id":2062,"date":"2019-04-16T15:11:22","date_gmt":"2019-04-16T15:11:22","guid":{"rendered":"http:\/\/www.jdx.info\/lutte\/?p=2062"},"modified":"2019-04-16T15:34:28","modified_gmt":"2019-04-16T15:34:28","slug":"roman-reigns-en-direction-de-smackdown-quelques-noms-evoques-et-plus","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2019\/04\/16\/roman-reigns-en-direction-de-smackdown-quelques-noms-evoques-et-plus\/","title":{"rendered":"Roman Reigns en Direction de Smackdown? Quelques noms \u00c9voqu\u00e9s, et plus!"},"content":{"rendered":"\n<p>\n\nDans cet Express, d\u00e9couvrez les possibles transf\u00e8res vers Smackdown Live ce soir, et bien plus!\n\n<\/p>\n\n\n\n<p>&#8211; Vous n&rsquo;\u00eates surement pas sans savoir que nous sommes actuellement en plein c\u0153ur du Superstar Shake-Up et pour le moment, Smackdown s&rsquo;est bien fait d\u00e9pouiller pour le compte de RAW. Ce soir, le show bleu verra cependant son roster \u00eatre renforc\u00e9 et plusieurs noms sont \u00e9voqu\u00e9s. <\/p>\n\n\n\n<p>Tout d&rsquo;abord concernant la grande annonce promise par Vince McMahon, il semblerait bien que cela soit pour&nbsp;<strong>Roman Reigns<\/strong> dont la fa\u00e7on dont il \u00e9tait \u00e9voqu\u00e9 hier soir \u00e0 RAW semblait marquer un futur d\u00e9part. Cela serait \u00e9galement l&rsquo;occasion de s\u00e9parer le Shield une bonne fois pour toute et laisser un peu plus de place pour Seth Rollins. Smackdown ayant perdu deux gros noms en AJ Styles et The Miz, le show bleu aura besoin de renfort dans cette division et Reigns semble pouvoir \u00eatre la solution. Au cas o\u00f9, Dave Meltzer \u00e9voque tout de m\u00eame la possibilit\u00e9 que ce soit Braun Strowman ou Seth Rollins . Dans le cas de Reigns, l&rsquo;\u00e9change contre Styles devait \u00eatre faite l&rsquo;an pass\u00e9 et avait finalement avort\u00e9e.<\/p>\n\n\n\n<p>Toujours selon Meltzer, la mani\u00e8re dont <strong>Bobby Lashley<\/strong> a \u00e9t\u00e9 utilis\u00e9 hier soir \u00e0 RAW lui fait croire que cela semble \u00eatre une bonne indication d&rsquo;un futur d\u00e9part pour lui vers Smackdown. <\/p>\n\n\n\n<p>Enfin au niveau de la division f\u00e9minine, Naomi est partie \u00e0 RAW alors que Lacey Evans a \u00e9t\u00e9 confirm\u00e9e comme faisant partie du roster du show rouge, il semble que <strong>Kairi Sane<\/strong> en provenance de NXT semble quasiment acquis chez les bleus. <\/p>\n\n\n\n<p><a href=\"https:\/\/www.jdx.info\/lutte\/2019\/04\/16\/vince-annoncera-la-plus-grosse-acquisition-a-vie-de-smackdown-live-la-suite-du-shake-up-et-bien-plus\/\">Pour l&rsquo;avant gout complet du Smackdown Live de ce soir, cliquez ici<\/a>.<\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Dans cet Express, d\u00e9couvrez les possibles transf\u00e8res vers Smackdown Live ce soir, et bien plus! &#8211; Vous n&rsquo;\u00eates surement pas sans savoir que nous sommes actuellement en plein c\u0153ur du Superstar Shake-Up et pour le moment, Smackdown s&rsquo;est bien fait d\u00e9pouiller pour le compte de RAW. Ce soir, le show bleu verra cependant son roster&#8230;<\/p>\n","protected":false},"author":4,"featured_media":2064,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"ppma_author":[292],"class_list":["post-2062","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"authors":[{"term_id":292,"user_id":4,"is_guest":0,"slug":"jean","display_name":"Jean Vinnier","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/33aba0263fd870a0b487e0e079ff407e10e3997c9d2987cbcc0db0db2c5c75a9?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/2062","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=2062"}],"version-history":[{"count":3,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/2062\/revisions"}],"predecessor-version":[{"id":2067,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/2062\/revisions\/2067"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/2064"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=2062"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=2062"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=2062"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=2062"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}