{"id":1401,"date":"2019-04-04T18:10:21","date_gmt":"2019-04-04T18:10:21","guid":{"rendered":"http:\/\/www.jdx.info\/lutte\/?p=1401"},"modified":"2019-04-04T18:10:23","modified_gmt":"2019-04-04T18:10:23","slug":"un-nouvel-adversaire-pour-batista","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2019\/04\/04\/un-nouvel-adversaire-pour-batista\/","title":{"rendered":"Un nouvel adversaire pour Batista!"},"content":{"rendered":"\n<p>Bonjour \u00e0 tous et bienvenue, dans cet express, d\u00e9couvrez la personne qui aimerait affronter Batista juste apr\u00e8s son match de WrestleMania.<\/p>\n\n\n\n<p>Alors que le match entre Triple H et Batista \u00e0 WrestleMania 35 a lieu dans quatre jours, une autre personne r\u00eave d\u00e9j\u00e0 d&rsquo;affronter l&rsquo;animal.<\/p>\n\n\n\n<p>L&rsquo;ancien joueur de football am\u00e9ricain des San Diego Charger, Shawne Merriman, a rencontr\u00e9 TMZ pour lancer un d\u00e9fi \u00e0 Batista dans un combat en MMA. Merriman loue la carri\u00e8re de Batista et comprend qu\u2019il est un homme occup\u00e9, mais pense que c\u2019est quelque chose que les gens veulent voir.<\/p>\n\n\n\n<p>\u00ab\u00a0Il a l&rsquo;air d&rsquo;un mec bien. Je sais que les gens vont regarder \u00e7a. Je sais que les gens veulent voir \u00e7a. S&rsquo;il \u00e9tait pr\u00eat \u00e0 le faire, je le ferais en une seconde. Je ne remettrais m\u00eame pas cette question en doute. Je sais qu\u2019il a d&rsquo;autres projets en cours, mais pourquoi ne pas donner aux gens quelque chose qu&rsquo;ils veulent voir. H\u00e9 Batista, si tu regardes ce mec, nous sommes tous les deux de la m\u00eame r\u00e9gion. Je suis fou d&rsquo;amour et de respect pour toi. Je sais que tu est depuis longtemps dans le sport et les gens veulent le voir. Je serai pr\u00eat.\u00a0\u00bb<\/p>\n\n\n\n<p>Le challenge est lanc\u00e9.<\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Bonjour \u00e0 tous et bienvenue, dans cet express, d\u00e9couvrez la personne qui aimerait affronter Batista juste apr\u00e8s son match de WrestleMania. Alors que le match entre Triple H et Batista \u00e0 WrestleMania 35 a lieu dans quatre jours, une autre personne r\u00eave d\u00e9j\u00e0 d&rsquo;affronter l&rsquo;animal. L&rsquo;ancien joueur de football am\u00e9ricain des San Diego Charger, Shawne&#8230;<\/p>\n","protected":false},"author":3,"featured_media":1402,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"ppma_author":[291],"class_list":["post-1401","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"authors":[{"term_id":291,"user_id":3,"is_guest":0,"slug":"amine","display_name":"Amine Benhelal","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/2ac225a45c11cce8567af8f2b64e669faee748a823f5f22499aaa30f28cfa944?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/1401","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=1401"}],"version-history":[{"count":1,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/1401\/revisions"}],"predecessor-version":[{"id":1403,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/1401\/revisions\/1403"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/1402"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=1401"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=1401"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=1401"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=1401"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}