{"id":136015,"date":"2026-07-16T01:07:00","date_gmt":"2026-07-16T05:07:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=136015"},"modified":"2026-07-16T22:15:08","modified_gmt":"2026-07-17T02:15:08","slug":"ken-anderson-affirme-que-vince-mcmahon-lui-a-dit-quil-etait-trop-drole-lorigines-de-sa-voix-radiophonique-se-comparant-a-the-rock-et-plus","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2026\/07\/16\/ken-anderson-affirme-que-vince-mcmahon-lui-a-dit-quil-etait-trop-drole-lorigines-de-sa-voix-radiophonique-se-comparant-a-the-rock-et-plus\/","title":{"rendered":"Ken Anderson affirme que Vince McMahon lui a dit qu\u2019il \u00e9tait trop dr\u00f4le, l&rsquo;origines de sa voix radiophonique, se comparant \u00e0 The Rock et plus !"},"content":{"rendered":"\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<p class=\"wp-block-paragraph\">Ken Anderson est un vrai dr\u00f4le de type. Vince McMahon le pense.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lors d\u2019une r\u00e9cente interview accord\u00e9e au magazine Soundsphere, M. Anderson s\u2019est rappel\u00e9 le moment o\u00f9 Vince McMahon lui a dit qu\u2019il \u00e9tait trop dr\u00f4le, sa voix unique et bien plus encore.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Voici quelques points forts de l\u2019interview o\u00f9 il aborde ces sujets avec ses r\u00e9flexions. Ci-dessous est \u00e9galement int\u00e9gr\u00e9 une archive vid\u00e9o compl\u00e8te de la discussion.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Sur la fa\u00e7on dont il a acquis sa voix radiophonique qu\u2019il a utilis\u00e9e dans sa carri\u00e8re de catch professionnel :<\/strong>&nbsp;<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">\u00ab C\u2019\u00e9tait vraiment juste une imitation de ce que j\u2019ai vu&#8230; Je passais beaucoup de temps seul dans ma chambre \u00e0 \u00e9couter des disques&#8230; Livres audio&#8230; J\u2019avais les cassettes du Seigneur des Anneaux , quatre cassettes par livre, une s\u00e9rie en 12 \u00e9pisodes que la BBC a sortie, et j\u2019\u00e9coutais ce truc encore et encore. \u00bb<\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Sur la fa\u00e7on dont un de ses professeurs le poussait \u00e0 utiliser sa voix et \u00e0 faire quelque chose avec :<\/strong>&nbsp;<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">\u00ab Mon professeur m\u2019a dit : &lsquo;Tu as une tr\u00e8s bonne voix, tu devrais faire \u00e7a. Tu devrais faire quelque chose avec \u00e7a.&rsquo; \u00bb<\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Sur la fa\u00e7on dont Vince McMahon lui a dit de ne pas s\u2019inqui\u00e9ter d\u2019\u00eatre un gentil ou un mauvais gars :<\/strong><\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">&nbsp;\u00ab Je me souviens avoir demand\u00e9 \u00e0 Vince : &lsquo;<em>Qu\u2019est-ce que tu veux que je fasse dans cette promo ?<\/em>&lsquo; Et il disait juste : \u00ab <em>Ne sors pas l\u00e0-bas et ne t\u2019inqui\u00e8te pas d\u2019\u00eatre un bon ou un m\u00e9chant, passe \u00e0 autre chose. Juste divertissant.<\/em>&lsquo; \u00bb<\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00c0 propos du fait qu\u2019apr\u00e8s un segment avec Tony Chimel, Vince soulignait qu\u2019il \u00e9tait trop dr\u00f4le  :<\/strong>&nbsp;<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">\u00ab Vince m\u2019a carr\u00e9ment dit que j\u2019\u00e9tais trop dr\u00f4le, je suis revenue par le rideau apr\u00e8s ce sketch au beignet \u00e0 la gel\u00e9e avec Chimel et il a juste dit : &lsquo;<em>Trop dr\u00f4le, bordel<\/em>.&rsquo; Plus tard, il m\u2019a dit : \u00ab <em>Dr\u00f4le ne signifie pas de l\u2019argent<\/em>. \u00bb C\u2019est l\u00e0 que j\u2019ai compris qu\u2019il y avait un plafond \u00e0 la volont\u00e9 de pousser ce c\u00f4t\u00e9 de ma personnalit\u00e9. J\u2019ai dit : \u00ab <em>Et The Rock ?<\/em> \u00bb Et il a r\u00e9pondu : <em>&lsquo;Eh bien, je te comprends, mais&#8230;<\/em>&lsquo; \u00bb<\/p>\n<\/blockquote>\n<\/div><\/div>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-prise-en-charge-des-contenus-embarqu-s wp-block-embed-prise-en-charge-des-contenus-embarqu-s wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Ken Anderson talks JCW, Vince McMahon finding him TOO FUNNY and his favourite modern performers\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/rUu_vyRQisI?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Ken Anderson est un vrai dr\u00f4le de type. Vince McMahon le pense. Lors d\u2019une r\u00e9cente interview accord\u00e9e au magazine Soundsphere, M. Anderson s\u2019est rappel\u00e9 le moment o\u00f9 Vince McMahon lui a dit qu\u2019il \u00e9tait trop dr\u00f4le, sa voix unique et bien plus encore. Voici quelques points forts de l\u2019interview o\u00f9 il aborde ces sujets avec&#8230;<\/p>\n","protected":false},"author":665,"featured_media":136074,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24,30,187,4],"tags":[],"ppma_author":[289],"class_list":["post-136015","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aew-impact-njpw-roh","category-ex-wwe","category-legends","category-news"],"authors":[{"term_id":289,"user_id":665,"is_guest":0,"slug":"line","display_name":"Line Edmond","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/852de09636413c90cdaa278312f9ea5bc4396768745424755cb63d99a05989d0?s=96&d=mm&r=g","author_category":"","first_name":"Line","last_name":"Edmond","user_url":"http:\/\/Info-Lutte.com","job_title":"","description":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/136015","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/665"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=136015"}],"version-history":[{"count":3,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/136015\/revisions"}],"predecessor-version":[{"id":136078,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/136015\/revisions\/136078"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/136074"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=136015"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=136015"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=136015"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=136015"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}