{"id":134411,"date":"2026-05-30T20:09:00","date_gmt":"2026-05-31T00:09:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=134411"},"modified":"2026-06-02T13:16:24","modified_gmt":"2026-06-02T17:16:24","slug":"resultats-et-video-pour-le-aaa-noch-de-los-grande-du-30-mai-2026-presente-par-la-wwe","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2026\/05\/30\/resultats-et-video-pour-le-aaa-noch-de-los-grande-du-30-mai-2026-presente-par-la-wwe\/","title":{"rendered":"R\u00e9sultats et Vid\u00e9o pour le AAA Noch De Los Grande du 30 Mai 2026 pr\u00e9sent\u00e9 par la WWE !"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">C&rsquo;est l&rsquo;affrontement historique : Grande Americano vs Grande Americano Original dans un Masque vs Masque ! Un seul Grande Americano triomphera \u00e0 la WWE \u00e0 l&rsquo;issue de ce match pr\u00e9sent\u00e9 \u00e0 AAA Noche De Los Grandes du 30 mai 2026 en direct de Monterrey, au Mexique.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong><a href=\"https:\/\/www.jdx.info\/lutte\/2026\/05\/30\/reprise-pour-le-aaa-noche-de-los-grandes-du-30-mai-2026\/\" target=\"_blank\" rel=\"noreferrer noopener\">Pour voir Noche de Los Grandes, cliquez ici.<\/a><\/strong><\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Championnat du Monde Cruiserweight de la AAA : Laredo Kid \u00a9 vs Rey Fenix<\/strong><\/p>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<p class=\"wp-block-paragraph\"><em>Rey Fenix<\/em> bat Laredo Kid \u00a9 pour devenir le nouveau champion.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En fin de match, Rey Fenix r\u00e9siste \u00e0 un Frog Splash de Kid et \u00e9vite une charge dans le coin sans coussin. Fenix lui porte un coup de pied avant d&rsquo;encha\u00eener avec un Muscle Buster pour le compte de trois.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Championnat d&rsquo;Am\u00e9rique latine de la AAA : El Hijo de Dr. Wagner Jr. \u00a9 vs El Hijo del Vikingo<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>El Hijo del Vikingo<\/em> bat El Hijo de Dr. Wagner Jr. \u00a9 pour devenir le nouveau champion.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En fin de match, apr\u00e8s de multiples interventions, Omos frappe Wagner et Vikingo encha\u00eene avec son 630 pour le compte de trois.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<p class=\"wp-block-paragraph\"><strong>Championnat du Monde par \u00e9quipes de la AAA : Pagano et Psycho Clown \u00a9 vs War Raiders (Erik et Ivar)<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>War Raiders (Erik et Ivar)<\/em> battent Pagano et Psycho Clown \u00a9 pour devenir les nouveaux champions.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En fin de match, Pagano frappe accidentellement Psycho Clown lorsque Ivar \u00e9vite une attaque. Ivar en profite pour envoyer Pagano \u00e0 l&rsquo;ext\u00e9rieur du ring. Erik et Ivar encha\u00eenent avec leur PowerSlam \u00e0 deux pour le compte de trois.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Apr\u00e8s le combat, Psycho Clown est furieux et pousse Pagano. Pagano le pousse \u00e0 son tour et les deux hommes se disputent. Pagano d\u00e9cide finalement de quitter les lieux, mais Erik et Ivar reviennent pour attaquer Psycho Clown. Pagano observe l&rsquo;attaque et choisit de partir. Les War Raiders terminent avec une Double Powerbomb sur Clown.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Masque vs Masque : Grande Americano vs Grande Americano Original<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Grande Americano fait son entr\u00e9e comme une v\u00e9ritable m\u00e9gastar. Grande Americano Original le frappe avec une guitare sur la t\u00eate pendant les pr\u00e9sentations afin de lancer le combat.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Grande Americano<\/em> bat Grande Americano Original.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pendant le combat, les Creed Brothers tentent d&rsquo;intervenir, mais Rayo et Bravo Americano arrivent pour les repousser aux abords du ring.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En fin de match, Americano se fait \u00e9trangler par Original \u00e0 l&rsquo;aide d&rsquo;une corde. Sa petite amie Andrea Bazarte arrive dans la foule afin de l&rsquo;encourager \u00e0 ne pas abandonner. Original abandonne sa prise et s&rsquo;approche d&rsquo;Andrea Bazarte en lui annon\u00e7ant qu&rsquo;elle est renvoy\u00e9e de la AAA. Andrea Bazarte sort alors un billet de sa poche pour prouver qu&rsquo;elle assiste simplement au spectacle comme spectatrice. Americano en profite pour attaquer Original dans le dos et reprendre l&rsquo;avantage. Il lui porte un DDT sur une chaise et tente le tomb\u00e9, mais Original r\u00e9siste \u00e0 deux.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<p class=\"wp-block-paragraph\">Les deux Americano \u00e9changent ensuite les coups. Original r\u00e9ussit une Suplex dans le coin et le couvre, mais Americano r\u00e9siste \u00e0 deux. Original lui bloque ensuite la jambe dans le coin avant de lui porter plusieurs coups de chaise. Il encha\u00eene avec un Ankle Lock. Americano r\u00e9siste et parvient \u00e0 le renverser en Headlock, mais Original contre imm\u00e9diatement avec un autre Ankle Lock. Americano refuse d&rsquo;abandonner et r\u00e9ussit finalement une Suplex. Il tente ensuite une charge, mais sa cheville le trahit. Original lui porte alors une German Suplex en pont, mais Americano r\u00e9siste encore \u00e0 deux. Americano \u00e9vite ensuite une charge et lui porte son Running Headbutt pour le compte de trois.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Apr\u00e8s le combat, Grande Americano c\u00e9l\u00e8bre sa victoire avec sa petite amie et les Americanos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Discours de Grande Americano Original<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Grande Americano Original revient sur le ring avec sa famille et explique qu&rsquo;il souhaite prendre la parole avant de retirer son masque. Il affirme avoir port\u00e9 ce masque pour apprendre la lucha libre et battre tous les luchadors du monde qu&rsquo;il d\u00e9testait. Au fil de ce parcours, il dit avoir tout appris sur les luchadors, le Mexique et sa culture. Il ajoute qu&rsquo;aujourd&rsquo;hui, il est capable de se pr\u00e9senter comme un homme. Il reconna\u00eet que cela lui fait mal de l&rsquo;admettre, mais qu&rsquo;il n&rsquo;a pas \u00e9t\u00e9 capable de vaincre l&rsquo;esprit mexicain ce soir.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Original dit ensuite \u00e0 Grande Americano qu&rsquo;il doit comprendre qu&rsquo;il restera toujours l&rsquo;Original. Mais \u00e0 partir de maintenant, il est le seul El Grande Americano.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Original retire son masque et il s&rsquo;agit bien de Chad Gable. La foule scande son nom. Chad Gable explique qu&rsquo;il est n\u00e9 aux \u00c9tats-Unis, \u00e0 Minneapolis. Il rappelle avoir particip\u00e9 aux Jeux olympiques et \u00eatre lutteur depuis 30 ans. Il ajoute qu&rsquo;il ne sait ni quand ni comment, mais que Chad Gable sera de retour \u00e0 la AAA. Gable remet ensuite son masque \u00e0 Americano.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le spectacle se termine avec la c\u00e9l\u00e9bration de Grande Americano.<\/p>\n<\/div><\/div>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\"><strong><a href=\"https:\/\/www.jdx.info\/lutte\/2026\/05\/30\/reprise-pour-le-aaa-noche-de-los-grandes-du-30-mai-2026\/\" target=\"_blank\" rel=\"noreferrer noopener\">Pour voir Noche de Los Grandes, cliquez ici.<\/a><\/strong><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-info-lutte wp-block-embed-info-lutte\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"sFaNcz1pjN\"><a href=\"https:\/\/www.jdx.info\/lutte\/2026\/05\/30\/reprise-pour-le-aaa-noche-de-los-grandes-du-30-mai-2026\/\">Reprise pour le AAA Noche de Los Grandes du 30 Mai 2026 !<\/a><\/blockquote><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"\u00ab\u00a0Reprise pour le AAA Noche de Los Grandes du 30 Mai 2026 !\u00a0\u00bb \u2014 Info-Lutte\" src=\"https:\/\/www.jdx.info\/lutte\/2026\/05\/30\/reprise-pour-le-aaa-noche-de-los-grandes-du-30-mai-2026\/embed\/#?secret=KGn2bcnjPT#?secret=sFaNcz1pjN\" data-secret=\"sFaNcz1pjN\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>C&rsquo;est l&rsquo;affrontement historique : Grande Americano vs Grande Americano Original dans un Masque vs Masque ! Un seul Grande Americano triomphera \u00e0 la WWE \u00e0 l&rsquo;issue de ce match pr\u00e9sent\u00e9 \u00e0 AAA Noche De Los Grandes du 30 mai 2026 en direct de Monterrey, au Mexique. Championnat du Monde Cruiserweight de la AAA : Laredo&#8230;<\/p>\n","protected":false},"author":4,"featured_media":134422,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[240,21,23],"tags":[339,540,598,599,107],"ppma_author":[292],"class_list":["post-134411","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aaa-nxt","category-resultats","category-wwe","tag-aaa","tag-el-grande-americano","tag-noche-de-los-grandes","tag-rey-fenix","tag-wwe"],"authors":[{"term_id":292,"user_id":4,"is_guest":0,"slug":"jean","display_name":"Jean Vinnier","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/33aba0263fd870a0b487e0e079ff407e10e3997c9d2987cbcc0db0db2c5c75a9?s=96&d=mm&r=g","author_category":"","first_name":"Jean","last_name":"Vinnier","user_url":"https:\/\/www.facebook.com\/jean.vinnier","job_title":"","description":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/134411","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=134411"}],"version-history":[{"count":1,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/134411\/revisions"}],"predecessor-version":[{"id":134423,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/134411\/revisions\/134423"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/134422"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=134411"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=134411"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=134411"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=134411"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}