{"id":13340,"date":"2019-10-04T20:09:31","date_gmt":"2019-10-05T00:09:31","guid":{"rendered":"http:\/\/www.jdx.info\/lutte\/?p=13340"},"modified":"2019-10-04T21:10:39","modified_gmt":"2019-10-05T01:10:39","slug":"resultats-du-wwe-friday-night-smackdown-4-octobre-2019","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2019\/10\/04\/resultats-du-wwe-friday-night-smackdown-4-octobre-2019\/","title":{"rendered":"R\u00e9sultats du WWE Friday Night Smackdown, 4 Octobre 2019!"},"content":{"rendered":"\n<p><strong>WWE Friday Night SmackDown Live, Los Angeles, Californie, 4 octobre 2019 sur FOX<\/strong><\/p>\n\n\n\n<p>Les commentateurs sont Michael Cole, Corey Graves et Renee Young.<\/p>\n\n\n\n<p>&#8211; Le WWE Friday Night SmackDown d\u00e9bute avec Cole qui nous souhaite la bienvenue dans cette nouvelle \u00e8re et Vince McMahon arrive sur la sc\u00e8ne avec Stephanie McMahon. Stephanie nous souhaite la bienvenue dans l&rsquo;histoire sur FOX. Vince nous souhaite la bienvenue \u00e0 Friday Night SmackDown ! <\/p>\n\n\n\n<p>&#8211; On poursuit avec la vid\u00e9o d&rsquo;intro du show et les feux d&rsquo;artifices.<\/p>\n\n\n\n<p> <br>&#8211; La championne de RAW Becky Lynch arrive sur le ring. Becky dit que c&rsquo;est g\u00e9nial de lancer le premier \u00e9pisode de SmackDown le vendredi. C&rsquo;est ici qu&rsquo;elle a chang\u00e9 le jeu en brisant des murs. C&rsquo;est notre voix qui a permis de l&rsquo;\u00e9lever. Elle veut donc remercier les fans en bottant des culs d\u00e8s maintenant. <\/p>\n\n\n\n<p>King Corbin arrive et dit qu&rsquo;on sait tous que le roi devrait ouvrir le show. Est-ce qu&rsquo;elle veut savoir qui est l&rsquo;homme ? La musique de <strong>The Rock<\/strong> se fait entendre ! <\/p>\n\n\n\n<p>The Rock arrive sur le ring sous une grande ovation. The Rock dit qu&rsquo;il y a beaucoup de temps The Rock a chang\u00e9 le paysage de la WWE pour toujours. Il a regard\u00e9 un idiot en disant qu&rsquo;il allait lui donner un SmackDown. Le mot SmackDown est devenu un mot, un show, devant des millions \u00e0 travers le monde. The Rock entrait sur le ring, l&rsquo;homme et Corbin se pr\u00e9sente ici comme un pauvre du Buger King ! On est tous ici devant les millions avec The Rock, l&rsquo;homme et le pauvre. ENFIN le Rock est de retour&#8230; \u00e0 la maison ! Corbin coupe The Rock et dit qu&rsquo;il doit faire une correction. Ce n&rsquo;est plus la maison du Rock, il n&rsquo;est plus le meilleur. Corbin dit qu&rsquo;on regarde au meilleur, le roi le plus \u00e9lectrifiant du sport. Et le roi dit de connaitre les r\u00e8gles et de se taire.<\/p>\n\n\n\n<p>The Rock dit qu&rsquo;il doit lui demander une chose. Corbin n&rsquo;est pas un roi avec une seule victoire du King of the Ring et se promener comme un vierge de 30 ans du Comic Con. Becky Lynch est l&rsquo;homme et ne se prom\u00e8ne pas avec une paire de testicule. Becky dit que si elle le ferait ses testicules seraient plus grosses que celles de Corbin. Corbin dit d&rsquo;arr\u00eater, ses testicules sont tr\u00e8s bien \u00e9quip\u00e9es ! Il est le roi, alors peut s&rsquo;habiller comme il veut et faire ce qu&rsquo;il veut car il est sup\u00e9rieur que Becky, The Rock et tout le monde. Cette ville a un seul roi et ce n&rsquo;est pas LeBron James. The Rock dit que Corbin croit \u00eatre sup\u00e9rieur que tout le monde. Est-ce vraiment ce qu&rsquo;il pense ? Corbin allait r\u00e9pondre mais Becky dit que ce n&rsquo;est pas important ce qu&rsquo;il pense ! The Rock dit que Corbin a gagn\u00e9 le Money in the Bank, le King of the Ring, envoy\u00e9 Kurt Angle \u00e0 la retraite. Corbin est un dur \u00e0 cuire. Il est super dur \u00e0 cuire. C&rsquo;est un show inclusif ce soir alors on va le faire bien sentir. Les gens vont chanter ce qu&rsquo;ils pensent de lui, STD. Becky dit que \u00e7a va rester avec Corbin pour le reste de sa vie. The Rock dit que \u00e7a lui fait plaisir.<\/p>\n\n\n\n<p>The Rock dit qu&rsquo;il voit que Corbin est froiss\u00e9 et devient f\u00e2ch\u00e9. Rock dit que c&rsquo;est \u00e7a qui arrive lorsqu&rsquo;on se pr\u00e9sente et insulte les gens et l&rsquo;homme. Il se pr\u00e9pare \u00e0 se faire botter le cul par The Man et le Great One. Becky frappe Corbin. The Rock et Becky enligne les coups sur Corbin. Becky fait un Leg Drop \u00e0 Corbin, Rock poursuit avec son People&rsquo;s Elbow ! Becky porte un coup de pied et Rock termine avec un Rock Bottom , et termine en disant: \u00ab\u00a0If You Smell, what the Rock is Coking?\u00a0\u00bb<\/p>\n\n\n\n<p>De retour Becky est toujours sur le Ring puis Charlotte Flair fait son entr\u00e9e suivit de Sasha Banks et Bayley.<\/p>\n\n\n\n<p><strong>Becky Lynch et Charlotte Flair vs Sasha Banks et Bayley<\/strong><\/p>\n\n\n\n<p> The Queen dbute par une tricherie mais Bayley revient en ramenant Flair au sol par les cheveux et passe au Boss qui y va de ses double knee. Flair r\u00e9pond par une s\u00e9rie de chops pour que la foule wooo, Banks finit sur le tablier et Flair d&rsquo;un big boot l&rsquo;envoie en bas et elle pose devant la foule. Flair monte sur le coin, Becky envoie Bayley en bas mais la hug girl parvient \u00e0 revenir et \u00e0 envoyer Flair en bas avant la pause.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n<p>En fin de match, Banks brise un compte apr\u00e8s un Natural Selection. Becky entre sur le ring pour la rouer de coups, mais Bayley la repousse. Le chaos \u00e9clate alors que les quatre s&rsquo;affrontent. Banks et Bayley sont expuls\u00e9es du ring, Charlotte poursuit avec un Moonsault de la troisi\u00e8me corde sur les deux. Charlotte ram\u00e8ne Bayley sur le ring et lui applique un Figure Eight pour la faire taper.<\/p>\n\n\n\n<p><strong>Gagnantes : Becky Lynch et Charlotte<\/strong><\/p>\n\n\n\n<p> &#8211; En coulisse, Erin Andrews de FOX est avec New Day pour une interview. Erin demande ses commentaires sur le fait qu&rsquo;il serait le sous-estim\u00e9 ce soir. Kofi dit qu&rsquo;il a toujours \u00e9t\u00e9 dans cette position, mais il est le champion comme on peut voir. Il monte des montages et bat les chances. Erin demande s&rsquo;il va monter la montagne avec ses fr\u00e8res ce soir. Xavier Woods dit que Kofi a d\u00e9cid\u00e9 de monter la montagne seule afin de prouver au monde entier et Brock Lesnar qu&rsquo;il m\u00e9rite d&rsquo;\u00eatre notre champion de la WWE. <\/p>\n\n\n\n<p>&#8211; On voit le champion Universal Seth Rollins marcher en coulisse et on annonce qu&rsquo;il affronte Shinsuke Nakamura apr\u00e8s la pause.<\/p>\n\n\n\n<p>&#8211; On pr\u00e9sente Tyson Fury dans la foule. Un clip du pr\u00e9-show puis les deux anciens GM de RAW, Kurt Angle et Mick Foley.<\/p>\n\n\n\n<p>&#8211; Seth Rollins fait son entr\u00e9e mais avant que Nakamura soit annonc\u00e9, Bray Wyatt appara\u00eet sur l&rsquo;\u00e9cran g\u00e9ant pour un FireFly Fun House.<\/p>\n\n\n\n<p><strong> Firefly Fun House<\/strong>. Bray Wyatt dit qu&rsquo;il fallait pr\u00e9senter \u00e0 tout le monde sa maison maintenant qu&rsquo;on a tous vu SmackDown. Wyatt nous pr\u00e9sente ses amis les marionnettes. Le lapin est v\u00eatu comme Rollins et lui dit de ne pas aller dans la cage avec le d\u00e9mon car \u00e7a ira mal. Wyatt dit que c&rsquo;est le moment de montrer \u00e0 Seth ce qui va arriver \u00e0 Hell in a Cell. Le lapin est dans la cage face au Buzzard. Le Buzzard le d\u00e9vore en quelques secondes. Wyatt commence \u00e0 rigoler en voyant que son lapin a perdu sa t\u00eate. Wyatt dit qu&rsquo;ils ont suffisamment attendu, c&rsquo;est le tour de Rollins.  <\/p>\n\n\n\n<p><strong>Champion Universal vs Champion  Intercontinental<\/strong><br><strong>Seth Rollins vs Shinsuke Nakamura<\/strong> <strong>acc Sami Zayn<\/strong> <br><em>Aucun titre en jeu <\/em><\/p>\n\n\n\n<p> <br>Nakamura tente de suite un armbar mais Rollins l&rsquo;envoie au sol et lui porte deux suicide dives, il jette Nak&rsquo; dans le ring et Zayn le confronte. Nakamura tente un coup mais slingblade de Rollins, il porte son coup de genou en springboard et Nakamura est d\u00e9j\u00e0 en position.  Rollins se pr\u00e9pare pour son Stomp, mais les lumi\u00e8res se ferment. Les lumi\u00e8res s&rsquo;allument et Seth a pris la fuite sur la sc\u00e8ne. Nakamura se retrouve seul sur le ring. <\/p>\n\n\n\n<p>The Fiend Bray Wyatt arrive sur la sc\u00e8ne et lui applique son Mandible Claw pour ensuite le pousser en bas de la sc\u00e8ne !   On a des gros plans sur le visage du Fiend et on entend dans le noir les rires de Wyatt pour conclure la premi\u00e8re heure. <\/p>\n\n\n\n<p class=\"has-medium-font-size\"><a href=\"https:\/\/www.jdx.info\/lutte\/2019\/10\/04\/resultats-deuxieme-heure-smackdown-du-4-octobre-2019\/\">Pour la suite de Smackdown et la deuxi\u00e8me heure, cliquez ici<\/a>.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>WWE Friday Night SmackDown Live, Los Angeles, Californie, 4 octobre 2019 sur FOX Les commentateurs sont Michael Cole, Corey Graves et Renee Young. &#8211; Le WWE Friday Night SmackDown d\u00e9bute avec Cole qui nous souhaite la bienvenue dans cette nouvelle \u00e8re et Vince McMahon arrive sur la sc\u00e8ne avec Stephanie McMahon. Stephanie nous souhaite la&#8230;<\/p>\n","protected":false},"author":4,"featured_media":13345,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,21,23],"tags":[],"ppma_author":[292],"class_list":["post-13340","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-resultats","category-wwe"],"authors":[{"term_id":292,"user_id":4,"is_guest":0,"slug":"jean","display_name":"Jean Vinnier","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/33aba0263fd870a0b487e0e079ff407e10e3997c9d2987cbcc0db0db2c5c75a9?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/13340","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=13340"}],"version-history":[{"count":38,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/13340\/revisions"}],"predecessor-version":[{"id":13396,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/13340\/revisions\/13396"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/13345"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=13340"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=13340"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=13340"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=13340"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}