{"id":133180,"date":"2026-05-04T13:08:10","date_gmt":"2026-05-04T17:08:10","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=133180"},"modified":"2026-05-04T13:11:56","modified_gmt":"2026-05-04T17:11:56","slug":"aj-styles-evoque-le-manque-de-show-non-televise-a-la-wwe-et-explique-son-changement-davis-concernant-fatal-influence-dans-le-roster-principal-de-la-wwe","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2026\/05\/04\/aj-styles-evoque-le-manque-de-show-non-televise-a-la-wwe-et-explique-son-changement-davis-concernant-fatal-influence-dans-le-roster-principal-de-la-wwe\/","title":{"rendered":"AJ Styles \u00e9voque le manque de show non t\u00e9l\u00e9vis\u00e9 \u00e0 la WWE et explique son changement d&rsquo;avis concernant Fatal Influence dans le roster principal de la WWE !"},"content":{"rendered":"\n<p>AJ Styles a chang\u00e9 d\u2019avis concernant Fatal Influence.<\/p>\n\n\n\n<p>Il a \u00e9galement partag\u00e9 une th\u00e9orie sur l\u2019impact de l\u2019absence d\u2019\u00e9v\u00e9nements non t\u00e9l\u00e9vis\u00e9s de la WWE sur les capacit\u00e9s sur le ring des talents \u00e9mergents de la compagnie.<\/p>\n\n\n\n<p>Lors du dernier \u00e9pisode de son podcast officiel \u00ab Phenomenally Retro \u00bb, \u00ab The Phenomenal One \u00bb a abord\u00e9 ces sujets.<\/p>\n\n\n\n<p>Voici les principaux propos d\u2019AJ Styles sur ces th\u00e8mes.<\/p>\n\n\n\n<p>AJ Styles :<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u00ab Ce qui est difficile avec \u00e7a aujourd\u2019hui, c\u2019est que beaucoup des anciens disaient : \u201c<em>Non, on va improviser sur le ring, gamin<\/em>.\u201d Mais souvent, ils avaient la possibilit\u00e9 d\u2019affronter \u00e9norm\u00e9ment d\u2019adversaires diff\u00e9rents et pouvaient improviser parce qu\u2019ils n\u2019\u00e9taient pas limit\u00e9s par le temps ou autre. Tu dois respecter un timing ou alors tu as affront\u00e9 ce gars tellement de fois avant. Bien s\u00fbr que tu peux improviser, moi je peux improviser beaucoup de choses. Plus je lutte contre quelqu\u2019un, plus c\u2019est facile : \u201c<em>On refait ce qu\u2019on a fait ici<\/em>\u201d et c\u2019est r\u00e9gl\u00e9. <\/p>\n\n\n\n<p>Mais on n\u2019a plus ces \u00e9v\u00e9nements non t\u00e9l\u00e9vis\u00e9s, donc les gars n\u2019accumulent plus d\u2019exp\u00e9rience ensemble. Je pense que \u00e7a va \u00eatre beaucoup plus difficile d\u2019improviser. Oui, on peut faire les bases, mais parfois les bases ne sont pas tr\u00e8s divertissantes et notre travail est d\u2019\u00eatre aussi divertissants que possible. Donc je pense que \u00e7a deviendra plus compliqu\u00e9 avec le temps. \u00bb<\/p>\n<\/blockquote>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u00ab Il y a beaucoup de styles diff\u00e9rents aujourd\u2019hui sur le ring. Ce n\u2019est plus pareil. Ce n\u2019est plus seulement des shoulder tackles, des prises de t\u00eate, des suplex, des powerslams, puis la fin. Il y a \u00e9norm\u00e9ment de choses diff\u00e9rentes, et beaucoup de prises que les hommes et les femmes r\u00e9alisent. C\u2019est assez incroyable. Quand on y pense, les plongeons \u00e0 l\u2019ext\u00e9rieur du ring et tout \u00e7a doivent \u00eatre ex\u00e9cut\u00e9s. Je ne suis pas s\u00fbr que \u00e7a pourrait \u00eatre fait aussi bien et aussi parfaitement qu\u2019avant, parce que c\u2019\u00e9tait beaucoup plus basique \u00e0 l\u2019\u00e9poque. Et il y a aussi le fait qu\u2019une fois sur le ring, on r\u00e9p\u00e8te certaines choses. Et quand je dis r\u00e9p\u00e9ter, on ne r\u00e9p\u00e8te pas le combat. On ne fait pas \u00e7a. On veut surtout voir o\u00f9 seront les cam\u00e9ras pour capter le meilleur angle sur la fin. C\u2019est \u00e7a qu\u2019on pr\u00e9pare, ou encore une intervention, pour que tout soit bien film\u00e9. C\u2019est ce genre de choses qu\u2019on met en place. \u00bb<\/p>\n<\/blockquote>\n\n\n\n<p>AJ Styles :<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u00ab Ce que j\u2019aime avec ce groupe, c\u2019est qu\u2019elles ressemblent au genre de personnes qui intimideraient ma fille. Oui, \u00e7a m\u2019\u00e9nerve. Et je me suis dit : \u201c<em>Elles font du tr\u00e8s bon travail.<\/em>\u201d C\u2019est l\u2019oppos\u00e9 de ce que je ressentirais normalement, mais en comprenant ce qu\u2019elles font et comment elles font leur travail, et qu\u2019elles le font bien, je me dis : \u201cC\u2019est \u00e7a.\u201d Donc je me dis : \u201c<em>Continuez comme \u00e7a. C\u2019est tr\u00e8s bon. C\u2019est du bon travail.<\/em>\u201d \u00bb<\/p>\n<\/blockquote>\n\n\n\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-info-lutte wp-block-embed-info-lutte\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"RDycoUyw9b\"><a href=\"https:\/\/www.jdx.info\/lutte\/2026\/05\/03\/wrestletalk-w-a-j-styles-phenomenally-retro-podcast\/\">Wrestletalk W\/ A.J Styles &#8211; Phenomenally Retro Podcast<\/a><\/blockquote><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"\u00ab\u00a0Wrestletalk W\/ A.J Styles &#8211; Phenomenally Retro Podcast\u00a0\u00bb &#8212; Info-Lutte\" src=\"https:\/\/www.jdx.info\/lutte\/2026\/05\/03\/wrestletalk-w-a-j-styles-phenomenally-retro-podcast\/embed\/#?secret=x9L7OiQ1NW#?secret=RDycoUyw9b\" data-secret=\"RDycoUyw9b\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>AJ Styles a chang\u00e9 d\u2019avis concernant Fatal Influence. Il a \u00e9galement partag\u00e9 une th\u00e9orie sur l\u2019impact de l\u2019absence d\u2019\u00e9v\u00e9nements non t\u00e9l\u00e9vis\u00e9s de la WWE sur les capacit\u00e9s sur le ring des talents \u00e9mergents de la compagnie. Lors du dernier \u00e9pisode de son podcast officiel \u00ab Phenomenally Retro \u00bb, \u00ab The Phenomenal One \u00bb a abord\u00e9&#8230;<\/p>\n","protected":false},"author":609,"featured_media":133190,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[313,4,36,23],"tags":[312,429,357,34,32,107],"ppma_author":[295],"class_list":["post-133180","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-hall-of-fame-wrestlemania","category-news","category-smackdown","category-wwe","tag-aj-styles","tag-fatal-incfluence","tag-jacy-jayne","tag-nxt","tag-smackdown","tag-wwe"],"authors":[{"term_id":295,"user_id":609,"is_guest":0,"slug":"rodrigo","display_name":"Rodrigue Tousignant","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/51fe284bb6dbe8a6b4c2bf998ad658f4a9cd24b7e58f15ec85888070c7340ce6?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/133180","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/609"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=133180"}],"version-history":[{"count":2,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/133180\/revisions"}],"predecessor-version":[{"id":133192,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/133180\/revisions\/133192"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/133190"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=133180"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=133180"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=133180"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=133180"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}