{"id":132159,"date":"2026-04-15T13:11:00","date_gmt":"2026-04-15T17:11:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=132159"},"modified":"2026-04-15T14:29:11","modified_gmt":"2026-04-15T18:29:11","slug":"aew-x-njpw-forbidden-door-2026-28-juin-2026-san-jose-californie-sap-center-diffusion-a-confirmer","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2026\/04\/15\/aew-x-njpw-forbidden-door-2026-28-juin-2026-san-jose-californie-sap-center-diffusion-a-confirmer\/","title":{"rendered":"AEW x NJPW Forbidden Door 2026 : 28 juin 2026, San Jose, Californie, SAP Center, diffusion \u00e0 confirmer !"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La AEW officialise les d\u00e9tails de l\u2019un de ses plus grands \u00e9v\u00e9nements interpromotions de l\u2019ann\u00e9e avec le retour de Forbidden Door en collaboration avec la New Japan Pro Wrestling. L\u2019\u00e9dition 2026 se tiendra le 28 juin au SAP Center de San Jose, en Californie, confirmant une nouvelle vitrine majeure pour les partenariats internationaux de la compagnie.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cependant, la date apporte une situation particuli\u00e8re puisque l\u2019\u00e9v\u00e9nement sera en concurrence directe avec TNA Slammiversary, \u00e9galement pr\u00e9vu le dimanche 28 juin, cr\u00e9ant une rare confrontation entre deux \u00e9v\u00e9nements majeurs du catch professionnel diffus\u00e9s le m\u00eame soir.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>AEW x NJPW Forbidden Door : annonce officielle et importance de l\u2019\u00e9v\u00e9nement<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tony Khan a soulign\u00e9 l\u2019importance grandissante de Forbidden Door depuis sa cr\u00e9ation, mettant en avant la collaboration entre la AEW, la New Japan Pro Wrestling, la CMLL et la STARDOM. Il insiste sur le caract\u00e8re historique de l\u2019\u00e9v\u00e9nement et sur l\u2019exp\u00e9rience offerte aux fans pr\u00e9sents sur place ainsi qu\u2019\u00e0 ceux qui suivront le show \u00e0 travers le monde.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Du c\u00f4t\u00e9 de la New Japan Pro Wrestling, le pr\u00e9sident Hiroshi Tanahashi a \u00e9galement exprim\u00e9 son enthousiasme. Il rappelle que chaque \u00e9dition de Forbidden Door met en avant une chimie forte entre les lutteurs des deux promotions et promet une nouvelle \u00e9dition comp\u00e9titive. Il affirme que la NJPW abordera cette \u00e9dition avec une approche plus agressive afin de d\u00e9montrer la qualit\u00e9 de son roster.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les billets pour AEW x NJPW Forbidden Door 2026 seront mis en vente le 27 avril, avec une pr\u00e9vente pr\u00e9vue d\u00e8s le 21 avril.<\/p>\n\n\n\n<blockquote class=\"twitter-tweet\" data-media-max-width=\"560\"><p lang=\"en\" dir=\"ltr\">As reported by <a href=\"https:\/\/twitter.com\/mercnews?ref_src=twsrc%5Etfw\">@mercnews<\/a>, AEW and New Japan Pro Wrestling are bringing <a href=\"https:\/\/twitter.com\/hashtag\/ForbiddenDoor?src=hash&amp;ref_src=twsrc%5Etfw\">#ForbiddenDoor<\/a> to San Jose, CA!<br><br>The 5th annual event will feature the brightest stars from AEW, <a href=\"https:\/\/twitter.com\/njpwglobal?ref_src=twsrc%5Etfw\">@njpwglobal<\/a>, <a href=\"https:\/\/twitter.com\/CMLL_OFICIAL?ref_src=twsrc%5Etfw\">@CMLL_OFICIAL<\/a>, and <a href=\"https:\/\/twitter.com\/we_are_stardom?ref_src=twsrc%5Etfw\">@we_are_stardom<\/a>, LIVE from the <a href=\"https:\/\/twitter.com\/SAPCenter?ref_src=twsrc%5Etfw\">@SAPCenter<\/a> on Sunday, June 28. <a href=\"https:\/\/t.co\/WnRlPoa2SQ\">pic.twitter.com\/WnRlPoa2SQ<\/a><\/p>&mdash; All Elite Wrestling (@AEW) <a href=\"https:\/\/twitter.com\/AEW\/status\/2044464524757975184?ref_src=twsrc%5Etfw\">April 15, 2026<\/a><\/blockquote> <script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>La AEW officialise les d\u00e9tails de l\u2019un de ses plus grands \u00e9v\u00e9nements interpromotions de l\u2019ann\u00e9e avec le retour de Forbidden Door en collaboration avec la New Japan Pro Wrestling. L\u2019\u00e9dition 2026 se tiendra le 28 juin au SAP Center de San Jose, en Californie, confirmant une nouvelle vitrine majeure pour les partenariats internationaux de la&#8230;<\/p>\n","protected":false},"author":609,"featured_media":132160,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38,24,30,106,55,4],"tags":[],"ppma_author":[295],"class_list":["post-132159","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aew","category-aew-impact-njpw-roh","category-ex-wwe","category-forbidden-door","category-njpw","category-news"],"authors":[{"term_id":295,"user_id":609,"is_guest":0,"slug":"rodrigo","display_name":"Rodrigue Tousignant","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/51fe284bb6dbe8a6b4c2bf998ad658f4a9cd24b7e58f15ec85888070c7340ce6?s=96&d=mm&r=g","author_category":"","first_name":"Rodrigue","last_name":"Tousignant","user_url":"http:\/\/Info-Lutte.com","job_title":"","description":"Il me fait plaisir de venir aider Jason qui tien Info-Lutte \u00e0 bout de bras depuis presque 20 ans. \r\n\r\nBien que je me suis pas journaliste cela a toujours \u00e9t\u00e9 mon r\u00eave donc je ferai de mon mieux avec la bonne formation qu'il me donne pour vous donner le meilleur des informations du catch."}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/132159","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/609"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=132159"}],"version-history":[{"count":1,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/132159\/revisions"}],"predecessor-version":[{"id":132161,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/132159\/revisions\/132161"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/132160"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=132159"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=132159"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=132159"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=132159"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}