{"id":131984,"date":"2026-04-11T23:37:00","date_gmt":"2026-04-12T03:37:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=131984"},"modified":"2026-04-13T17:45:56","modified_gmt":"2026-04-13T21:45:56","slug":"resultats-et-video-pour-le-lucha-libre-du-11-avril-2026-propulse-par-la-wwe","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2026\/04\/11\/resultats-et-video-pour-le-lucha-libre-du-11-avril-2026-propulse-par-la-wwe\/","title":{"rendered":"R\u00e9sultats et Vid\u00e9o pour le Lucha Libre du 11 avril 2026 propuls\u00e9 par la WWE !"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La AAA pr\u00e9sentait son show <strong>Lucha Libre<\/strong> du 11 avril 2026, c&rsquo;est la premi\u00e8re fois que le champion <strong>Intercontinental <\/strong>est d\u00e9fendu \u00e0 l&rsquo;ext\u00e9rieur de la WWE depuis 1996. Il faut remonter \u00e0 <strong>Triple H <\/strong>qui d\u00e9fendait le championnat \u00e0 Porto Rico en 1996 \u00e0 la <strong>WWA<\/strong>.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.jdx.info\/lutte\/2026\/04\/11\/reprise-video-pour-le-aaa-lucha-libre-du-11-avril-2026\/\" target=\"_blank\" rel=\"noreferrer noopener\">Pour voir le show, cliquez ici.<\/a><\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">&#8211; Le show d\u00e9bute avec <strong>Flammer<\/strong>, La <strong>Hiedra <\/strong>et <strong>Maravilla <\/strong>sur le ring afin de c\u00e9l\u00e9brer le r\u00e8gne de Flammer. La championne re\u00e7oit ensuite une vid\u00e9o regroupant plusieurs t\u00e9moignages. Flammer prend la parole et affirme vouloir remercier tout le monde, mais pr\u00e9cise qu\u2019elle ne reconna\u00eet personne en dehors de ses proches pr\u00e9sents sur place. Elle insiste sur le fait que seules ses alli\u00e9es comptent r\u00e9ellement.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Elle poursuit en remerciant toutes les adversaires qu\u2019elle a battues pour atteindre plus de 100 jours de r\u00e8gne, mentionnant \u00e9galement les catcheuses de RAW et de SmackDown comme Bayley et Natalya pour leur participation indirecte \u00e0 son parcours. Son discours est interrompu par une vid\u00e9o montrant une femme arrivant en voiture.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Catalina <\/strong>fait alors son arriv\u00e9e sur la sc\u00e8ne. Elle f\u00e9licite Flammer pour son r\u00e8gne, soulignant qu\u2019elle est la championne avec le plus long r\u00e8gne et la plus belle, selon elle. Catalina ajoute que c\u2019est une journ\u00e9e sp\u00e9ciale et qu\u2019elle conna\u00eet bien Flammer, ce qui explique sa pr\u00e9sence pour la f\u00e9liciter. Flammer r\u00e9agit imm\u00e9diatement en pr\u00e9cisant qu\u2019elles ne se sont jamais affront\u00e9es.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La situation d\u00e9g\u00e9n\u00e8re rapidement et une bagarre \u00e9clate sur le ring. Catalina prend l\u2019avantage et repousse Flammer, La Hiedra et Maravilla. Elle termine en projetant Flammer sur son g\u00e2teau de c\u00e9l\u00e9bration.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>El Grande Americano Original<\/strong> bat Octagon Jr en le for\u00e7ant \u00e0 abandonner apr\u00e8s un Ankle Lock. Le d\u00e9nouement survient lorsque Octagon Jr est d\u00e9masqu\u00e9 en pleine action, subissant la pression de la prise de soumission.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Apr\u00e8s le combat, Grande Americano OG attaque un acteur pr\u00e9sent au bord du ring. Un second Grande Americano arrive ensuite pour intervenir et s\u2019en prendre \u00e0 Grande Americano OG. Les officiels interviennent rapidement pour s\u00e9parer les deux hommes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Championnat Intercontinental de la WWE<\/strong><br><strong>Penta <\/strong>\u00a9 bat El Hijo Del Vikingo pour conserver son titre. Dorian Roldan est expuls\u00e9 du bord du ring apr\u00e8s \u00eatre intervenu ill\u00e9galement en faisant tr\u00e9bucher Penta. Plus tard, alors que l\u2019arbitre est distrait, Vikingo tente d\u2019utiliser la ceinture contre Penta, mais Mini Vikingo intervient et lui arrache l\u2019objet des mains. Penta en profite ensuite pour porter son Mexican Destroyer et obtenir le compte de trois.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Apr\u00e8s le combat, Penta c\u00e9l\u00e8bre sa victoire, mais les deux Grande Americano reviennent une nouvelle fois sur la sc\u00e8ne et \u00e9changent des coups. Les officiels doivent intervenir \u00e0 nouveau pour les s\u00e9parer. Grande Americano prend ensuite le micro et d\u00e9clare vouloir r\u00e9gler ce conflit dans un affrontement d\u00e9finitif, un \u0153il pour un \u0153il, sang pour sang, en exigeant un match masque contre masque.<\/p>\n\n\n\n<p class=\"has-text-align-center has-medium-font-size wp-block-paragraph\"><strong><a href=\"https:\/\/www.jdx.info\/lutte\/2026\/04\/11\/reprise-video-pour-le-aaa-lucha-libre-du-11-avril-2026\/\" target=\"_blank\" rel=\"noreferrer noopener\"> Pour voir le show, cliquez ici.<\/a><\/strong><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-info-lutte wp-block-embed-info-lutte\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"mJfjQpWhac\"><a href=\"https:\/\/www.jdx.info\/lutte\/2026\/04\/11\/reprise-video-pour-le-aaa-lucha-libre-du-11-avril-2026\/\">Reprise Vid\u00e9o pour le AAA Lucha Libre du 11 Avril 2026 !<\/a><\/blockquote><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"\u00ab\u00a0Reprise Vid\u00e9o pour le AAA Lucha Libre du 11 Avril 2026 !\u00a0\u00bb &#8212; Info-Lutte\" src=\"https:\/\/www.jdx.info\/lutte\/2026\/04\/11\/reprise-video-pour-le-aaa-lucha-libre-du-11-avril-2026\/embed\/#?secret=irIzR9tW8o#?secret=mJfjQpWhac\" data-secret=\"mJfjQpWhac\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>La AAA pr\u00e9sentait son show Lucha Libre du 11 avril 2026, c&rsquo;est la premi\u00e8re fois que le champion Intercontinental est d\u00e9fendu \u00e0 l&rsquo;ext\u00e9rieur de la WWE depuis 1996. Il faut remonter \u00e0 Triple H qui d\u00e9fendait le championnat \u00e0 Porto Rico en 1996 \u00e0 la WWA. &#8211; Le show d\u00e9bute avec Flammer, La Hiedra et&#8230;<\/p>\n","protected":false},"author":37048,"featured_media":131986,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[240,21],"tags":[339,340],"ppma_author":[297],"class_list":["post-131984","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aaa-nxt","category-resultats","tag-aaa","tag-lucha-libre"],"authors":[{"term_id":297,"user_id":37048,"is_guest":0,"slug":"mattante","display_name":"Mattias Antoinette","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/db141441570c9bdee0787662393889dfbc3d6c721d3318f2402846725b7b664e?s=96&d=mm&r=g","author_category":"","first_name":"Mattias","last_name":"Antoinette","user_url":"http:\/\/info-catch.com","job_title":"","description":"Une seule personne, deux t\u00eates \u00e0 claques"}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/131984","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/37048"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=131984"}],"version-history":[{"count":2,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/131984\/revisions"}],"predecessor-version":[{"id":131991,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/131984\/revisions\/131991"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/131986"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=131984"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=131984"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=131984"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=131984"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}