{"id":131938,"date":"2026-04-12T13:11:00","date_gmt":"2026-04-12T17:11:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=131938"},"modified":"2026-04-13T14:36:32","modified_gmt":"2026-04-13T18:36:32","slug":"rumeurs-concernantdwayne-the-rock-johnson-impliquant-un-eventuel-evenement-a-wrestlemania-42","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2026\/04\/12\/rumeurs-concernantdwayne-the-rock-johnson-impliquant-un-eventuel-evenement-a-wrestlemania-42\/","title":{"rendered":"Rumeurs concernantDwayne &lsquo;The Rock&rsquo; Johnson impliquant un \u00e9ventuel \u00e9v\u00e9nement \u00e0 WrestleMania 42"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La \u00ab\u00a0grande surprise\u00a0\u00bb annonc\u00e9e par <strong>Pat McAfee<\/strong> pour <strong>SmackDown <\/strong>a g\u00e9n\u00e9r\u00e9 une forte anticipation avant de se transformer en d\u00e9ception pour une partie du public.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dans les jours pr\u00e9c\u00e9dant l\u2019\u00e9mission, plusieurs sp\u00e9culations ont rapidement converg\u00e9 vers <strong>Dwayne Johnson,<\/strong> notamment en lien avec les rumeurs d\u2019un r\u00f4le d\u2019agent ou de conseiller myst\u00e9rieux dans une intrigue impliquant <strong>Randy Orton<\/strong>. L\u2019hypoth\u00e8se d\u2019une apparition majeure a pris de l\u2019ampleur jusqu\u2019\u00e0 la diffusion du segment.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La r\u00e9v\u00e9lation finale a toutefois pris une direction totalement diff\u00e9rente. McAfee a annonc\u00e9 une r\u00e9duction de 25 % sur les billets pour <strong>WrestleMania Saturday<\/strong>, une annonce commerciale qui n\u2019a pas eu l\u2019impact narratif attendu et qui a \u00e9t\u00e9 accueillie avec une certaine froideur par une partie de la base de fans. En coulisses, la r\u00e9action aurait \u00e9t\u00e9 partag\u00e9e, m\u00eame si le segment aurait tout de m\u00eame obtenu une r\u00e9ception positive du c\u00f4t\u00e9 des partenaires m\u00e9diatiques comme <strong>ESPN <\/strong>et du dirigeant de <strong>TKO <\/strong>Group Holdings, <strong>Ari Emanuel<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Selon Dave Meltzer dans le Wrestling Observer Newsletter, il existe un pr\u00e9c\u00e9dent \u00e0 ce type de sp\u00e9culation autour de grosses apparitions. Il rapporte notamment que lors d\u2019un \u00e9v\u00e9nement \u00e0 Toronto l\u2019an dernier, Emanuel aurait directement sollicit\u00e9 <strong>The Rock<\/strong> dans un contexte li\u00e9 \u00e0 la progression des ventes de billets, un point \u00e9galement \u00e9voqu\u00e9 r\u00e9cemment par <strong>CM Punk<\/strong> dans une promo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Toujours selon ces informations, les retours en coulisses seraient actuellement n\u00e9gatifs concernant une apparition imminente de Dwayne Johnson dans un r\u00f4le de surprise \u00e0 court terme. Une r\u00e9serve demeure cependant, puisque dans ce type de sc\u00e9nario, les d\u00e9cisions majeures sont g\u00e9n\u00e9ralement gard\u00e9es sous un strict secret et connues d\u2019un cercle tr\u00e8s restreint que <strong>Triple H<\/strong> appel toujours le <strong>Kayfabe<\/strong>. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les ventes de billets de WrestleMania seraient \u00e9galement en dessous des attentes, ce qui aurait pouss\u00e9 la WWE \u00e0 renforcer son positionnement avec des annonces majeures, notamment la confirmation de <strong>John Cena <\/strong>comme animateur officiel de l\u2019\u00e9v\u00e9nement. Mais comme nous vous l&rsquo;avions annonc\u00e9 l&rsquo;an dernier \u00e0 pareille date, Cena ne pouvait pas terminer sa carri\u00e8re sur un Saterday Night&rsquo;s Main Event et il reviendra l&rsquo;an prochain ou pour WrestleMania 45 pour son entr\u00e9e au Hall of Fame.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En l\u2019\u00e9tat, les seules figures capables d\u2019un impact comparable dans le paysage grand public restent <strong>Steve Austin<\/strong> ou <strong>Dwayne Johnson<\/strong>, mais les derni\u00e8res indications disponibles ne pointent pas vers une pr\u00e9sence imminente de ce dernier.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-info-lutte wp-block-embed-info-lutte\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"G1ix5gSJzF\"><a href=\"https:\/\/www.jdx.info\/lutte\/2026\/04\/11\/rappel-de-la-carte-wrestlemania-42-nuit-1-et-2-et-infos-pour-le-voir\/\">Rappel de la Carte : WrestleMania 42 Nuit 1 et 2, et infos pour le voir !<\/a><\/blockquote><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"\u00ab\u00a0Rappel de la Carte : WrestleMania 42 Nuit 1 et 2, et infos pour le voir !\u00a0\u00bb &#8212; Info-Lutte\" src=\"https:\/\/www.jdx.info\/lutte\/2026\/04\/11\/rappel-de-la-carte-wrestlemania-42-nuit-1-et-2-et-infos-pour-le-voir\/embed\/#?secret=sR5Eewc921#?secret=G1ix5gSJzF\" data-secret=\"G1ix5gSJzF\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>La \u00ab\u00a0grande surprise\u00a0\u00bb annonc\u00e9e par Pat McAfee pour SmackDown a g\u00e9n\u00e9r\u00e9 une forte anticipation avant de se transformer en d\u00e9ception pour une partie du public. Dans les jours pr\u00e9c\u00e9dant l\u2019\u00e9mission, plusieurs sp\u00e9culations ont rapidement converg\u00e9 vers Dwayne Johnson, notamment en lien avec les rumeurs d\u2019un r\u00f4le d\u2019agent ou de conseiller myst\u00e9rieux dans une intrigue impliquant&#8230;<\/p>\n","protected":false},"author":665,"featured_media":131981,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,100,42,23],"tags":[273,227,317],"ppma_author":[289],"class_list":["post-131938","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-tko","category-wrestlemania","category-wwe","tag-dwayne-johnson","tag-the-rock","tag-wrestlemania"],"authors":[{"term_id":289,"user_id":665,"is_guest":0,"slug":"line","display_name":"Line Edmond","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/852de09636413c90cdaa278312f9ea5bc4396768745424755cb63d99a05989d0?s=96&d=mm&r=g","author_category":"","first_name":"Line","last_name":"Edmond","user_url":"http:\/\/Info-Lutte.com","job_title":"","description":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/131938","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/665"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=131938"}],"version-history":[{"count":2,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/131938\/revisions"}],"predecessor-version":[{"id":131970,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/131938\/revisions\/131970"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/131981"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=131938"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=131938"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=131938"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=131938"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}