{"id":131558,"date":"2026-04-04T02:05:00","date_gmt":"2026-04-04T06:05:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=131558"},"modified":"2026-04-04T14:11:37","modified_gmt":"2026-04-04T18:11:37","slug":"nikki-bella-blessee-avant-wrestlemania-42-la-wwe-confirme-presence-toujours-prevue","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2026\/04\/04\/nikki-bella-blessee-avant-wrestlemania-42-la-wwe-confirme-presence-toujours-prevue\/","title":{"rendered":"Nikki Bella bless\u00e9e avant WrestleMania 42 : La WWE confirme, pr\u00e9sence toujours pr\u00e9vue !"},"content":{"rendered":"\n<p><\/p>\n\n\n\n<p>La <strong>WWE <\/strong>a confirm\u00e9 les rumeurs concernant une blessure de <strong>Nikki Bella<\/strong> \u00e0 quelques semaines de <strong>WrestleMania 42<\/strong>. Comme mentionn\u00e9, la l\u00e9gende du WWE Hall of Fame s\u2019est bless\u00e9e \u00e0 la cheville lors du combat The Bella Twins contre Charlotte Flair et Alexa Bliss la semaine derni\u00e8re.<\/p>\n\n\n\n<p>Nikki Bella a \u00e9t\u00e9 aper\u00e7ue avec une botte de marche lors d\u2019un enregistrement en direct de <em>The Nikki &amp; Brie Show<\/em> lundi dernier, ce qui a rapidement aliment\u00e9 les inqui\u00e9tudes.<\/p>\n\n\n\n<p>Lors de l\u2019\u00e9pisode du 3 avril de <strong>SmackDown<\/strong>, Joe Tessitore et Wade Barrett ont abord\u00e9 la situation en commentaire. Ils ont confirm\u00e9 que Nikki Bella est actuellement en r\u00e9\u00e9ducation, mais qu\u2019elle a toujours l\u2019intention de participer \u00e0 WrestleMania 42 aux c\u00f4t\u00e9s de Brie Bella.<\/p>\n\n\n\n<p>Les Bella Twins sont toujours annonc\u00e9es pour un combat pour le Championnat par \u00e9quipes f\u00e9minin de la WWE \u00e0 quatre \u00e9quipes, impliquant les championnes en titre The Irresistible Forces \u00a9, ainsi que Bayley et Lyra Valkyria, en plus de Charlotte Flair et Alexa Bliss.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-info-lutte wp-block-embed-info-lutte\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"c3rJ7yLg3U\"><a href=\"https:\/\/www.jdx.info\/lutte\/2026\/04\/02\/brie-bella-explique-sa-decision-de-revenir-a-la-wwe-je-suis-comme-nikki-on-est-comme-lequipe-originale\/\">Brie Bella explique sa d\u00e9cision de revenir \u00e0 la WWE : \u00ab Je suis comme, &lsquo;Nikki, on est comme l\u2019\u00e9quipe originale&#8230;&rsquo; \u00bb<\/a><\/blockquote><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"\u00ab\u00a0Brie Bella explique sa d\u00e9cision de revenir \u00e0 la WWE : \u00ab Je suis comme, &lsquo;Nikki, on est comme l\u2019\u00e9quipe originale&#8230;&rsquo; \u00bb\u00a0\u00bb &#8212; Info-Lutte\" src=\"https:\/\/www.jdx.info\/lutte\/2026\/04\/02\/brie-bella-explique-sa-decision-de-revenir-a-la-wwe-je-suis-comme-nikki-on-est-comme-lequipe-originale\/embed\/#?secret=ZKymbWZnSP#?secret=c3rJ7yLg3U\" data-secret=\"c3rJ7yLg3U\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>La WWE a confirm\u00e9 les rumeurs concernant une blessure de Nikki Bella \u00e0 quelques semaines de WrestleMania 42. Comme mentionn\u00e9, la l\u00e9gende du WWE Hall of Fame s\u2019est bless\u00e9e \u00e0 la cheville lors du combat The Bella Twins contre Charlotte Flair et Alexa Bliss la semaine derni\u00e8re. Nikki Bella a \u00e9t\u00e9 aper\u00e7ue avec une botte&#8230;<\/p>\n","protected":false},"author":665,"featured_media":131559,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,43,87,23],"tags":[152],"ppma_author":[289],"class_list":["post-131558","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-raw-wwe","category-road-to-wrestlemania","category-wwe","tag-women-of-wrestling"],"authors":[{"term_id":289,"user_id":665,"is_guest":0,"slug":"line","display_name":"Line Edmond","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/852de09636413c90cdaa278312f9ea5bc4396768745424755cb63d99a05989d0?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/131558","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/665"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=131558"}],"version-history":[{"count":1,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/131558\/revisions"}],"predecessor-version":[{"id":131560,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/131558\/revisions\/131560"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/131559"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=131558"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=131558"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=131558"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=131558"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}