{"id":130988,"date":"2026-03-21T19:18:00","date_gmt":"2026-03-21T23:18:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=130988"},"modified":"2026-03-23T15:45:24","modified_gmt":"2026-03-23T19:45:24","slug":"resultats-et-video-pour-le-aew-collision-special-slam-dunk-2026","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2026\/03\/21\/resultats-et-video-pour-le-aew-collision-special-slam-dunk-2026\/","title":{"rendered":"R\u00e9sultats et Vid\u00e9o pour le AEW Collision sp\u00e9cial Slam Dunk 2026 !"},"content":{"rendered":"\n<p>C&rsquo;est sp\u00e9cial Slam Dunk cette semaine \u00e0 AEW Collision du 21 mars 2026. En raison des&nbsp;finales du basketball NCAA,&nbsp;le show&nbsp;sera diffus\u00e9 sur deux soirs en format d&rsquo;une heure.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong><a href=\"https:\/\/www.jdx.info\/lutte\/2026\/03\/21\/reprise-video-pour-le-aew-collision-special-slam-dunk-nuit-1\/\" target=\"_blank\" rel=\"noreferrer noopener\">Pour voir la nuit 1, cliquez ici.<\/a><\/strong><\/li>\n<\/ul>\n\n\n\n<p><strong>AEW Collision, Fresno, Californie<\/strong><\/p>\n\n\n\n<p><strong>Championnat TNT de la AEW : Kyle Fletcher \u00a9 vs Robbie Eagle<\/strong><br>En fin de match, Eagle pr\u00e9pare une prise, mais Fletcher le bloque avec une Clothesline et le projette contre le coin. Fletcher enchaine avec un Running Kick et son Brain Buster pour le compte de trois.<br><em>Gagnant : Kyle Fletcher<\/em><\/p>\n\n\n\n<p><strong>Segment en coulisses : Jon Moxley et Pac<\/strong><br>On retrouve Jon Moxley et Pac. Moxley affirme que Will Ospreay est de retour dans le jeu et qu\u2019il a tenu de grandes d\u00e9clarations comme vouloir lui casser le cou. Rien de la sorte n\u2019arrivera. Ospreay a \u00e9norm\u00e9ment de talent, mais s\u2019il est d\u00e9termin\u00e9 \u00e0 finir \u00e0 l\u2019h\u00f4pital, ce sera son choix. Pac ajoute qu\u2019il ne comprend pas le probl\u00e8me avec Ospreay, rappelant qu\u2019il n\u2019\u00e9tait m\u00eame pas pr\u00e9sent lors de son attaque. Si Ospreay veut croiser son chemin, il sera pr\u00eat.<\/p>\n\n\n\n<p><strong> LFI (Dralistico, RUSH et The Beast Mortos) vs catcheurs locaux (Alpha Zo, Lucas Riley et Dom Kubrick)<\/strong><br>En fin de match, Mortos termine avec son Twisting Splash pour le compte de trois en moins de deux minutes.<br><em>Gagnants : LFI<\/em><\/p>\n\n\n\n<p><strong>Segment en coulisses : Thekla<\/strong><br>Lexie demande \u00e0 Thekla ses commentaires sur l\u2019attaque contre Toni Storm. Thekla affirme que c\u2019est une trag\u00e9die avant de commencer \u00e0 rire en lui souhaitant un prompt r\u00e9tablissement. Elle confirme ensuite \u00eatre responsable de cette attaque. Toni Storm voulait prendre son titre, mais elle vient de r\u00e9aliser qu\u2019elle n\u2019est pas \u00c9ternelle car elle ne peut pas rivaliser avec la Toxique.<\/p>\n\n\n\n<p><strong> The Brawling Birds (Alex Windsor et Jamie Hayter) vs The Sisters of Sin (Julia Hart et Skye Blue)<\/strong><br>En fin de match, Blue et Windsor s\u2019affrontent sur le coin. Blue r\u00e9ussit un Sunset Bomb, mais Hayter interrompt le compte. Hart la repousse du ring. Windsor bloque une attaque de Hart et Blue alors que Hayter prend le relais. Hayter porte une Clothesline \u00e0 Hart et elles enchainent avec leur combinaison Clothesline et Spinebuster pour le compte de trois.<br><em>Gagnantes : The Brawling Birds<\/em><\/p>\n\n\n\n<p><strong>Segment en coulisses : Brody King<\/strong><br>Lexie demande \u00e0 Brody King ses commentaires sur Revolution. King d\u00e9clare que c\u2019est gr\u00e2ce \u00e0 Kenny Omega s\u2019il est ici aujourd\u2019hui. Il pr\u00e9cise que son histoire avec Swerve Strickland est loin d\u2019\u00eatre termin\u00e9e et que sa qu\u00eate vers le championnat se poursuit.<\/p>\n\n\n\n<p><strong>Annonce : MJF<\/strong><br>Il est annonc\u00e9 que MJF sera pr\u00e9sent \u00e0 Dynamite mercredi.<\/p>\n\n\n\n<p><strong> Claudio Castagnoli et Daniel Garcia vs Komander et Mascara Dorada<\/strong><br>En fin de match, Komander r\u00e9alise un compte rapide sur Castagnoli, mais celui-ci r\u00e9siste et enchaine avec un Back Breaker. Castagnoli poursuit avec son Giant Swing et le couvre pour le compte de trois pendant que Garcia applique un Sleeper \u00e0 Dorada.<br><em>Gagnants : Claudio Castagnoli et Daniel Garcia<\/em><\/p>\n\n\n\n<p><strong>Appr\u00e9ciation g\u00e9n\u00e9rale :<\/strong><br>Un \u00e9pisode structur\u00e9 autour d\u2019une action efficace en ring et de segments en coulisses qui font progresser plusieurs rivalit\u00e9s. La domination rapide de LFI, la d\u00e9fense solide de Kyle Fletcher \u00a9 et les d\u00e9veloppements autour de Will Ospreay, Jon Moxley et Swerve Strickland marquent les points forts de la soir\u00e9e.<\/p>\n\n\n\n<p><strong>Moments forts :<\/strong><br>Victoire dominante de Kyle Fletcher \u00a9 pour conserver le Championnat TNT de la AEW<br>Confirmation de Thekla comme responsable de l\u2019attaque sur Toni Storm<br>Segment intense impliquant Jon Moxley, Pac et la situation autour de Will Ospreay<br>Performance convaincante de Claudio Castagnoli et Daniel Garcia en \u00e9quipe<\/p>\n\n\n\n<p class=\"has-text-align-center\"><strong><a href=\"https:\/\/www.jdx.info\/lutte\/2026\/03\/21\/reprise-video-pour-le-aew-collision-special-slam-dunk-nuit-1\/\" target=\"_blank\" rel=\"noreferrer noopener\">Pour voir le show, cliquez ici.<\/a><\/strong><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-info-lutte wp-block-embed-info-lutte\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"cMh2i1jYP1\"><a href=\"https:\/\/www.jdx.info\/lutte\/2026\/03\/21\/reprise-video-pour-le-aew-collision-special-slam-dunk-nuit-1\/\">Reprise Vid\u00e9o pour le AEW Collision Sp\u00e9cial Slam Dunk Nuit 1.<\/a><\/blockquote><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"\u00ab\u00a0Reprise Vid\u00e9o pour le AEW Collision Sp\u00e9cial Slam Dunk Nuit 1.\u00a0\u00bb &#8212; Info-Lutte\" src=\"https:\/\/www.jdx.info\/lutte\/2026\/03\/21\/reprise-video-pour-le-aew-collision-special-slam-dunk-nuit-1\/embed\/#?secret=zV1OYwBWTV#?secret=cMh2i1jYP1\" data-secret=\"cMh2i1jYP1\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n\n\n\n<p class=\"has-small-font-size\"><em>Sources et r\u00e9f\u00e9rences : WrestlingHeadlines, site officiel de la AEW, r\u00e9seaux sociaux de la AEW<\/em><\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>C&rsquo;est sp\u00e9cial Slam Dunk cette semaine \u00e0 AEW Collision du 21 mars 2026. En raison des&nbsp;finales du basketball NCAA,&nbsp;le show&nbsp;sera diffus\u00e9 sur deux soirs en format d&rsquo;une heure. AEW Collision, Fresno, Californie Championnat TNT de la AEW : Kyle Fletcher \u00a9 vs Robbie EagleEn fin de match, Eagle pr\u00e9pare une prise, mais Fletcher le bloque&#8230;<\/p>\n","protected":false},"author":4,"featured_media":130992,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38,24,89,21],"tags":[198],"ppma_author":[292],"class_list":["post-130988","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aew","category-aew-impact-njpw-roh","category-collision","category-resultats","tag-slam-dunk"],"authors":[{"term_id":292,"user_id":4,"is_guest":0,"slug":"jean","display_name":"Jean Vinnier","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/33aba0263fd870a0b487e0e079ff407e10e3997c9d2987cbcc0db0db2c5c75a9?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/130988","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=130988"}],"version-history":[{"count":2,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/130988\/revisions"}],"predecessor-version":[{"id":130998,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/130988\/revisions\/130998"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/130992"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=130988"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=130988"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=130988"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=130988"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}