{"id":130253,"date":"2026-03-18T13:22:27","date_gmt":"2026-03-18T17:22:27","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=130253"},"modified":"2026-03-18T13:22:27","modified_gmt":"2026-03-18T17:22:27","slug":"cody-rhodes-pense-que-la-wwe-doit-reintegrer-les-bodybuilders-en-pleine-forme-dans-leffectif-actif","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2026\/03\/18\/cody-rhodes-pense-que-la-wwe-doit-reintegrer-les-bodybuilders-en-pleine-forme-dans-leffectif-actif\/","title":{"rendered":"Cody Rhodes pense que la WWE doit r\u00e9int\u00e9grer les \u00ab bodybuilders en pleine forme \u00bb dans l\u2019effectif actif"},"content":{"rendered":"\n<p>Dans les ann\u00e9es 1980 et 1990, tout tournait autour de manger tes vitamines, fr\u00e8re.<\/p>\n\n\n\n<p>Eh bien, en plus de dire tes pri\u00e8res et de croire en toi, bien s\u00fbr.<\/p>\n\n\n\n<p>Les commandements Hulk Hogan \u00e9taient le mod\u00e8le de l\u2019apparence et de l\u2019ambiance de la WWE \u00e0 cette \u00e9poque, avec un accent fort sur les physiques massifs des culturistes et moins sur le talent et les capacit\u00e9s sur le ring.<\/p>\n\n\n\n<p>C\u2019est quelque chose que Cody Rhodes pense devoir revenir \u00e0 la WWE.<\/p>\n\n\n\n<p>Du moins \u00e0 un certain niveau.<\/p>\n\n\n\n<p>\u00ab J\u2019esp\u00e8re presque qu\u2019on ait encore des bodybuilders compl\u00e8tement d\u00e9fonc\u00e9s \u00bb, a d\u00e9clar\u00e9 l\u2019ancien champion incontest\u00e9 de la WWE en discutant avec Gunther dans le dernier \u00e9pisode de son&nbsp;<a href=\"https:\/\/podcasts.apple.com\/us\/podcast\/gunther\/id1816989347?i=1000753012604\" rel=\"noreferrer noopener\" target=\"_Blank\">\u00e9mission So What Do You Want to Talk About&nbsp;? with Cody Rhodes<\/a>. \u00ab De vrais ann\u00e9es 90 (les gars). Des sentiments que tous les gar\u00e7ons ne supportent pas. Juste quelqu\u2019un qui me dit : &lsquo;Regarde ce look&rsquo;, et ensuite il faudra tous qu\u2019on trouve comment faire. \u00bb<\/p>\n\n\n\n<p>Rhodes allait ensuite d\u00e9velopper.<\/p>\n\n\n\n<p>\u00ab Je dirais qu\u2019il manque \u00bb, poursuivit-il. \u00ab Le vieux type de bodybuilder l\u00e9gitime. &lsquo; Il est superbe. \u00bb J\u2019ai entendu ce terme l\u2019autre jour, quelqu\u2019un d\u00e9crivait qu\u2019\u00e0 la WWE, on n\u2019est peut-\u00eatre pas en forme, mais que tous ceux qui sont en forme ont une \u00ab carrure athl\u00e9tique \u00bb. Je d\u00e9teste le terme \u00ab physique athl\u00e9tique \u00bb. Je sais que \u00e7a n\u2019arrivera pas, mais je veux juste qu\u2019un bodybuilder revienne dans le lot. Juste un pur sang (bodybuilder). Tu le regardes, \u00ab Mon fr\u00e8re va se d\u00e9chirer les triceps rien qu\u2019en entrant sur le ring. \u00bb Nous n\u2019en avons plus. Les bodybuilders sont des dinosaures. Ils sont partis. \u00bb<\/p>\n\n\n\n<p>wrestlingheadlines.com\/cody-rhodes-thinks-wwe-needs-to-bring-back-jacked-up-bodybuilder-dudes-to-active-talent-roster\/<\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Dans les ann\u00e9es 1980 et 1990, tout tournait autour de manger tes vitamines, fr\u00e8re. Eh bien, en plus de dire tes pri\u00e8res et de croire en toi, bien s\u00fbr. Les commandements Hulk Hogan \u00e9taient le mod\u00e8le de l\u2019apparence et de l\u2019ambiance de la WWE \u00e0 cette \u00e9poque, avec un accent fort sur les physiques massifs&#8230;<\/p>\n","protected":false},"author":665,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"ppma_author":[289],"class_list":["post-130253","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"authors":[{"term_id":289,"user_id":665,"is_guest":0,"slug":"line","display_name":"Line Edmond","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/852de09636413c90cdaa278312f9ea5bc4396768745424755cb63d99a05989d0?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/130253","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/665"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=130253"}],"version-history":[{"count":1,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/130253\/revisions"}],"predecessor-version":[{"id":130257,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/130253\/revisions\/130257"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=130253"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=130253"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=130253"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=130253"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}