{"id":128907,"date":"2026-01-27T23:47:00","date_gmt":"2026-01-28T04:47:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=128907"},"modified":"2026-01-29T13:28:37","modified_gmt":"2026-01-29T18:28:37","slug":"tommaso-ciampa-evoque-ses-plans-post-wwe-en-tant-que-the-psycho-killer","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2026\/01\/27\/tommaso-ciampa-evoque-ses-plans-post-wwe-en-tant-que-the-psycho-killer\/","title":{"rendered":"Tommaso Ciampa \u00e9voque ses plans post-WWE en tant que \u00ab The Psycho Killer \u00bb"},"content":{"rendered":"\n<p>Plus d\u2019\u00e9tiquette \u00ab Jackass \u00bb pour Tommaso Ciampa.<\/p>\n\n\n\n<p>Il est d\u00e9sormais connu sous le nom de \u00ab Le Tueur Psychopathe \u00bb.<\/p>\n\n\n\n<p>Ou \u00ab Le Psychopathe \u00bb.<\/p>\n\n\n\n<p>L\u2019ancien membre de l\u2019\u00e9quipe #DIY aux c\u00f4t\u00e9s de Johnny Gargano a r\u00e9cemment\u00a0annonc\u00e9 son d\u00e9part de la WWE, et il se pr\u00e9pare maintenant \u00e0 son retour post-WWE.<\/p>\n\n\n\n<p>Voici ce qu&rsquo;a \u00e9crit Ciampa dans un nouveau post sur les r\u00e9seaux sociaux mardi.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u00ab Les t-shirts et sweats \u00e0 capuche de Psycho Killer et Psycho Kid sont d\u00e9sormais disponibles chez PWTees.  Illustration de Tom Nguyen. \u00bb<\/p>\n<\/blockquote>\n\n\n\n<p>Comme l\u2019a rapport\u00e9 la semaine derni\u00e8re Dave Meltzer, il y a \u00e9voqu\u00e9 sur un possible transfert de Ciampa \u00e0 New Japan Pro-Wrestling.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u00ab On parle qu\u2019il tenterait d\u2019entrer dans New Japan. Il s\u2019int\u00e8gre dans le style de la AEW mais la AEW a un effectif tellement large rempli de talents de haut niveau que c\u2019est difficile \u00e0 percer. Le fait qu\u2019il pousse des bookings ind\u00e9pendants semble indiquer qu\u2019il n\u2019est pas parti pour AEW et un contrat l\u00e0-bas, mais \u00e7a ne m\u2019\u00e9tonnerait pas de voir un tel accord se faire vu que Tony Khan a sign\u00e9 autant de joueurs et qu\u2019il est un catcheur solide sur le ring. \u00bb<\/p>\n<\/blockquote>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Plus d\u2019\u00e9tiquette \u00ab Jackass \u00bb pour Tommaso Ciampa. Il est d\u00e9sormais connu sous le nom de \u00ab Le Tueur Psychopathe \u00bb. Ou \u00ab Le Psychopathe \u00bb. L\u2019ancien membre de l\u2019\u00e9quipe #DIY aux c\u00f4t\u00e9s de Johnny Gargano a r\u00e9cemment\u00a0annonc\u00e9 son d\u00e9part de la WWE, et il se pr\u00e9pare maintenant \u00e0 son retour post-WWE. Voici ce qu&rsquo;a&#8230;<\/p>\n","protected":false},"author":665,"featured_media":128974,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24,30,22,4],"tags":[],"ppma_author":[289],"class_list":["post-128907","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aew-impact-njpw-roh","category-ex-wwe","category-indy","category-news"],"authors":[{"term_id":289,"user_id":665,"is_guest":0,"slug":"line","display_name":"Line Edmond","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/852de09636413c90cdaa278312f9ea5bc4396768745424755cb63d99a05989d0?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/128907","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/665"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=128907"}],"version-history":[{"count":2,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/128907\/revisions"}],"predecessor-version":[{"id":128975,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/128907\/revisions\/128975"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/128974"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=128907"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=128907"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=128907"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=128907"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}