{"id":128507,"date":"2026-02-08T12:55:45","date_gmt":"2026-02-08T17:55:45","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=128507"},"modified":"2026-02-08T12:55:45","modified_gmt":"2026-02-08T17:55:45","slug":"ted-dibiase-jr-cherche-a-annuler-son-proces-dans-une-affaire-federale-en-cours","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2026\/02\/08\/ted-dibiase-jr-cherche-a-annuler-son-proces-dans-une-affaire-federale-en-cours\/","title":{"rendered":"Ted DiBiase Jr. cherche \u00e0 annuler son proc\u00e8s dans une affaire f\u00e9d\u00e9rale en cours"},"content":{"rendered":"\n<p>Un nouveau d\u00e9veloppement juridique est apparu dans l\u2019affaire f\u00e9d\u00e9rale en cours impliquant l\u2019ancien star de la WWE Ted DiBiase Jr.<\/p>\n\n\n\n<p>Tard hier, des avocats repr\u00e9sentant DiBiase ont d\u00e9pos\u00e9 une requ\u00eate en annulation du proc\u00e8s aupr\u00e8s du tribunal f\u00e9d\u00e9ral pour le district sud du Mississippi. Le d\u00e9p\u00f4t soutient que la poursuite des proc\u00e9dures dans les circonstances actuelles porterait atteinte aux droits constitutionnels de DiBiase et compromettrait l\u2019\u00e9quit\u00e9 du proc\u00e8s.<\/p>\n\n\n\n<p>Dans la requ\u00eate, l\u2019\u00e9quipe juridique de DiBiase a d\u00e9clar\u00e9 :<\/p>\n\n\n\n<p>\u00ab Le d\u00e9fendeur, Theodore DiBiase, Jr. (\u00ab&nbsp;D\u00e9fendeur&nbsp;\u00bb), par l\u2019interm\u00e9diaire d\u2019un avocat soussign\u00e9, demande respectueusement un proc\u00e8s nul pour les raisons \u00e9nonc\u00e9es dans le M\u00e9morandum confidentiel des autorit\u00e9s qui est simultan\u00e9ment fourni \u00e0 la Cour \u00e0 huis clos et sur lequel le d\u00e9fendeur s\u2019appuie pleinement. La poursuite du proc\u00e8s dans ces circonstances violerait le droit du d\u00e9fendeur au sixi\u00e8me amendement \u00e0 l\u2019avocat de son choix, \u00e0 l\u2019assistance effective de son avocat, compromettrait l\u2019\u00e9quit\u00e9 des proc\u00e9dures et entra\u00eenerait une n\u00e9cessit\u00e9 manifeste justifiant un proc\u00e8s nul. \u00bb<\/p>\n\n\n\n<p>Le m\u00e9morandum mentionn\u00e9 dans le d\u00e9p\u00f4t a \u00e9t\u00e9 soumis de mani\u00e8re confidentielle pour examen par le tribunal.<\/p>\n\n\n\n<p>Au moment o\u00f9 j\u2019\u00e9cris ces lignes, le tribunal n\u2019a pas encore statu\u00e9 sur la demande d\u2019annulation du proc\u00e8s.<\/p>\n\n\n\n<p>Malgr\u00e9 la requ\u00eate en attente, le proc\u00e8s de DiBiase Jr. est actuellement pr\u00e9vu pour reprendre demain \u00e0 Biloxi, dans le Mississippi.<\/p>\n\n\n\n<p>(video<\/p>\n\n\n\n<p>wrestlingheadlines.com\/ted-dibiase-jr-seeking-mistrial-in-ongoing-federal-case\/<\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Un nouveau d\u00e9veloppement juridique est apparu dans l\u2019affaire f\u00e9d\u00e9rale en cours impliquant l\u2019ancien star de la WWE Ted DiBiase Jr. Tard hier, des avocats repr\u00e9sentant DiBiase ont d\u00e9pos\u00e9 une requ\u00eate en annulation du proc\u00e8s aupr\u00e8s du tribunal f\u00e9d\u00e9ral pour le district sud du Mississippi. Le d\u00e9p\u00f4t soutient que la poursuite des proc\u00e9dures dans les circonstances&#8230;<\/p>\n","protected":false},"author":665,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"ppma_author":[289],"class_list":["post-128507","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"authors":[{"term_id":289,"user_id":665,"is_guest":0,"slug":"line","display_name":"Line Edmond","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/852de09636413c90cdaa278312f9ea5bc4396768745424755cb63d99a05989d0?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/128507","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/665"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=128507"}],"version-history":[{"count":1,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/128507\/revisions"}],"predecessor-version":[{"id":128508,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/128507\/revisions\/128508"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=128507"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=128507"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=128507"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=128507"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}