{"id":127757,"date":"2026-01-01T15:33:00","date_gmt":"2026-01-01T20:33:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=127757"},"modified":"2026-01-02T19:03:56","modified_gmt":"2026-01-03T00:03:56","slug":"john-cena-partage-une-declaration-repensant-a-sa-marquante-annee-2025-la-vie-continue-et-nous","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2026\/01\/01\/john-cena-partage-une-declaration-repensant-a-sa-marquante-annee-2025-la-vie-continue-et-nous\/","title":{"rendered":"John Cena partage une d\u00e9claration repensant \u00e0 sa marquante ann\u00e9e 2025 : \u00ab La vie continue, et nous&#8230; \u00bb"},"content":{"rendered":"\n<p>Pour de nombreux fans de catch professionnel, 2025 restera l\u2019ann\u00e9e de <strong>The Last Time Is Now<\/strong>. Pourquoi ? John Cena. Toute l\u2019ann\u00e9e 2025 a servi de tourn\u00e9e de retraite WWE d\u2019une ann\u00e9e pour <strong>The Greatest of All-Time<\/strong>.<\/p>\n\n\n\n<p>Avec 2026 qui approche, la future l\u00e9gende du WWE Hall Of Fame est apparue sur les r\u00e9seaux sociaux pour revenir sur cette ann\u00e9e m\u00e9morable de sa carri\u00e8re et de sa vie. L\u2019ancien champion du monde le Marine original a utilis\u00e9 son compte officiel X, au jour de l\u2019An, jeudi 1er janvier 2026, pour publier une d\u00e9claration revenant sur sa saison 2025.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u00ab La vie continue et nous avan\u00e7ons tous, alors que 2026 approche, je me souviendrai avec tendresse de tant de moments de 2025. Merci \u00e0 TOUS les fans, coll\u00e8gues, critiques et tous ceux qui ont utilis\u00e9 leur voix pour faire de 2025 une ann\u00e9e que je n\u2019oublierai jamais. \u00bb<\/p>\n<\/blockquote>\n\n\n\n<p>Cena a conclu la br\u00e8ve d\u00e9claration sur les r\u00e9seaux sociaux le 1\/1 par une citation en espagnol.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u00ab Omnia Dedi. Pro omnibus gratias ago \u00bb,<\/p>\n<\/blockquote>\n\n\n\n<p><\/p>\n\n\n\n<p>Qui se traduit en fran\u00e7ais par :<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u00ab J\u2019ai tout donn\u00e9. Je te remercie pour tout. \u00bb<\/p>\n<\/blockquote>\n\n\n\n<p>La citation est celle que John Cena a port\u00e9e sur le dernier t-shirt WWE qu\u2019il portait lors de son match de retraite \u00ab The Last Time Is Now \u00bb contre Gunther lors du WWE Saturday Night\u2019s Main Event le 13 d\u00e9cembre 2025, en direct \u00e0 la Capital One Arena \u00e0 Washington, DC.<\/p>\n\n\n\n<center><blockquote class=\"twitter-tweet\" data-media-max-width=\"560\"><p lang=\"en\" dir=\"ltr\">Life goes on and we all move onward, as 2026 is here I\u2019ll fondly remember so many moments from 2025. Thanks to ALL fans, co workers, critics and anyone around the world who used their voice to make 2025 a year that I\u2019ll never forget. Omnia Dedi. Pro omnibus gratias ago.<\/p>&mdash; John Cena (@JohnCena) <a href=\"https:\/\/twitter.com\/JohnCena\/status\/2006803043040506219?ref_src=twsrc%5Etfw\">January 1, 2026<\/a><\/blockquote> <script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/center>\n\n\n\n<p><\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Pour de nombreux fans de catch professionnel, 2025 restera l\u2019ann\u00e9e de The Last Time Is Now. Pourquoi ? John Cena. Toute l\u2019ann\u00e9e 2025 a servi de tourn\u00e9e de retraite WWE d\u2019une ann\u00e9e pour The Greatest of All-Time. Avec 2026 qui approche, la future l\u00e9gende du WWE Hall Of Fame est apparue sur les r\u00e9seaux sociaux&#8230;<\/p>\n","protected":false},"author":665,"featured_media":127810,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,23],"tags":[277],"ppma_author":[289],"class_list":["post-127757","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-wwe","tag-last-time-is-now"],"authors":[{"term_id":289,"user_id":665,"is_guest":0,"slug":"line","display_name":"Line Edmond","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/852de09636413c90cdaa278312f9ea5bc4396768745424755cb63d99a05989d0?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/127757","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/665"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=127757"}],"version-history":[{"count":2,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/127757\/revisions"}],"predecessor-version":[{"id":127809,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/127757\/revisions\/127809"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/127810"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=127757"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=127757"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=127757"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=127757"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}