{"id":127524,"date":"2025-12-24T19:58:00","date_gmt":"2025-12-25T00:58:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=127524"},"modified":"2025-12-27T13:17:01","modified_gmt":"2025-12-27T18:17:01","slug":"resultats-et-video-pour-le-aew-dynamite-du-24-decembre-2025","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2025\/12\/24\/resultats-et-video-pour-le-aew-dynamite-du-24-decembre-2025\/","title":{"rendered":"R\u00e9sultats et Vid\u00e9o pour le AEW Dynamite du 24 D\u00e9cembre 2025 !"},"content":{"rendered":"\n<p>C&rsquo;est le AEW Dynamite sp\u00e9cial 34th Street pour c\u00e9l\u00e9brer la vieille de No\u00ebl le 24 d\u00e9cembre 2025. Un show qui a \u00e9t\u00e9 enregistr\u00e9 le 20 d\u00e9cembre, pour ensuite \u00eatre diffus\u00e9 le mercredi. Au programme, MJF fait son premier match depuis son retour et la finale du Dynamite Diamond Ring !<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong><a href=\"https:\/\/www.jdx.info\/lutte\/2025\/12\/24\/reprise-video-pour-le-aew-dynamite-du-24-decembre-2025\/\" target=\"_blank\" rel=\"noreferrer noopener\">Pour voir Dynamite, cliquez ici.<\/a><\/strong><\/li>\n<\/ul>\n\n\n\n<p><strong>Tournoi Continental Classic &#8211; Singles Match<\/strong><br>Konosuke Takeshita bat Orange Cassidy<\/p>\n\n\n\n<p><strong>Tournoi Continental Classic &#8211; Singles Match<\/strong><br>Mascara Dorada bat Roderick Strong<\/p>\n\n\n\n<p>&#8211; Face \u00e0 face entre Jamie Hayter et Kris Statlander pour Worlds End. Statlander demande \u00e0 Hayter de lui prouver \u00e0 Worlds End qu&rsquo;elle m\u00e9rite d&rsquo;\u00eatre une championne. Hayter lui rappel que la derni\u00e8re fois qu&rsquo;elle frapp\u00e9 Statlander, elle ne sait pas relev\u00e9e.<\/p>\n\n\n\n<p><strong>MJF bat le catcheur local Dustin Waller<\/strong><\/p>\n\n\n\n<p>Apr\u00e8s le combat, Adam Page et Swerve Strickland arrivent par la foule. Page invite MJF a faire un autre commentaire de mauvais go\u00fbt sur eux avant de se diriger vers le ring. Les \u00e9l\u00e8ves du Opps arrivent, mais ils se font tous repousser par Page et Strickland. MJF arrive \u00e0 \u00e9viter l&rsquo;attaque et quitter le ring.<\/p>\n\n\n\n<p>Samoa Joe d\u00e9barque sur le TitanTron et avise tout le monde qu&rsquo;il va briser leur r\u00eave \u00e0 Worlds End en restant le champion. MJF veut en profiter pour attaquer Strickland et Page, mais Page&nbsp;commence \u00e0 immobiliser MJF avec une cha\u00eene au cou pendant que Strickland fait sa promo \u00e0 MJF. Strickland rappel \u00e0 MJF qu&rsquo;il est un narcissiste. Il souligne que le Pinnacle ont tous \u00e9t\u00e9 une victime de MJF et qu&rsquo;ils vont r\u00e9gler son probl\u00e8me \u00e0 Worlds End.<\/p>\n\n\n\n<p><strong>Finale Dynamite Diamond Ring<\/strong><br><em>Le gagnant va affronter le champion mondial AEW \u00e0 Dynamite Maximum Carnage.<\/em><br>Bandido bat Ricochet<\/p>\n\n\n\n<p>Apr\u00e8s le combat, le clan de Ricochet vient attaquer Bandido, mais Brody King vient le sauver.<\/p>\n\n\n\n<p><strong>Marina Shafir bat Mina Shirakawa<\/strong><\/p>\n\n\n\n<p>Apr\u00e8s le combat, Shafir pourquoi sa soumission sur Shirakawa, mais Toni Storm d\u00e9barque sur le ring. Shafir arrive \u00e0 la sonner.<\/p>\n\n\n\n<p>&#8211; En coulisses, les Young Bucks annoncent qu&rsquo;ils devront rester sur la touche pour le reste de l&rsquo;ann\u00e9e. Kenny Omega dit qu&rsquo;ils vont rester The Elite, mais il doit aller se charger de quelque chose qu&rsquo;il aurait d\u00fb faire depuis bien longtemps.<\/p>\n\n\n\n<p><strong>Tournoi Continental Classic &#8211; Singles Match<\/strong><br>Jungle Jack Perry bat Pac<\/p>\n\n\n\n<p>\u00a0<strong>Bilan sur les points sur AEW Continental Classic 2025<\/strong><\/p>\n\n\n\n<p><strong>Ligue Or (Victoire \/ D\u00e9faite \/ \u00c9galit\u00e9)<\/strong><br>Kyle Fletcher (2-2-0, 6 points)<br>Kazuchika Okada (2-2-0, 6 points)<br>Mike Bailey (2-2-0, 6 points)<br>Pac (2-2-0, 6 points)<br>Kevin Knight (2-2-0, 6 points)<br>Jack Perry (2-2-0, 6 points)<\/p>\n\n\n\n<p><strong>Ligue Bleue (Victoire \/ D\u00e9faite \/ \u00c9galit\u00e9)<\/strong><\/p>\n\n\n\n<p>Konosuke Takeshita (3-0-1, 10 points)<br>Claudio Castagnoli (2-1-1, 7 points)<br>Jon Moxley (2-2-0, 6 points)<br>Orange Cassidy (2-2-0, 6 points)<br>Mascara Dorada (1-2-0, 6 points)<br>Roderick Strong (0-4-0, 0 points)<\/p>\n\n\n\n<p class=\"has-text-align-center has-medium-font-size\"><strong><a href=\"https:\/\/www.jdx.info\/lutte\/2025\/12\/24\/reprise-video-pour-le-aew-dynamite-du-24-decembre-2025\/\" target=\"_blank\" rel=\"noreferrer noopener\">Pour voir Dynamite, cliquez ici.<\/a><\/strong><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-info-lutte wp-block-embed-info-lutte\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"H5jX73i2tf\"><a href=\"https:\/\/www.jdx.info\/lutte\/2025\/12\/24\/reprise-video-pour-le-aew-dynamite-du-24-decembre-2025\/\">Reprise Vid\u00e9o pour le AEW Dynamite du 24 D\u00e9cembre 2025 !<\/a><\/blockquote><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"\u00ab\u00a0Reprise Vid\u00e9o pour le AEW Dynamite du 24 D\u00e9cembre 2025 !\u00a0\u00bb &#8212; Info-Lutte\" src=\"https:\/\/www.jdx.info\/lutte\/2025\/12\/24\/reprise-video-pour-le-aew-dynamite-du-24-decembre-2025\/embed\/#?secret=D7i6JVOPJM#?secret=H5jX73i2tf\" data-secret=\"H5jX73i2tf\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>C&rsquo;est le AEW Dynamite sp\u00e9cial 34th Street pour c\u00e9l\u00e9brer la vieille de No\u00ebl le 24 d\u00e9cembre 2025. Un show qui a \u00e9t\u00e9 enregistr\u00e9 le 20 d\u00e9cembre, pour ensuite \u00eatre diffus\u00e9 le mercredi. Au programme, MJF fait son premier match depuis son retour et la finale du Dynamite Diamond Ring ! Tournoi Continental Classic &#8211; Singles&#8230;<\/p>\n","protected":false},"author":37048,"featured_media":127525,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38,24,50,30,21],"tags":[],"ppma_author":[297],"class_list":["post-127524","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aew","category-aew-impact-njpw-roh","category-dynamite","category-ex-wwe","category-resultats"],"authors":[{"term_id":297,"user_id":37048,"is_guest":0,"slug":"mattante","display_name":"Mattias Antoinette","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/db141441570c9bdee0787662393889dfbc3d6c721d3318f2402846725b7b664e?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/127524","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/37048"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=127524"}],"version-history":[{"count":1,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/127524\/revisions"}],"predecessor-version":[{"id":127526,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/127524\/revisions\/127526"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/127525"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=127524"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=127524"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=127524"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=127524"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}