{"id":125762,"date":"2025-11-11T00:12:00","date_gmt":"2025-11-11T05:12:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=125762"},"modified":"2025-11-11T14:58:16","modified_gmt":"2025-11-11T19:58:16","slug":"rikishi-fatu-legende-du-wwe-hall-of-fame-fait-le-point-sur-sa-situation-je-ne-vais-pas-entrer-dans-les-details-sur-tout-ce-qui-sest-passe","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2025\/11\/11\/rikishi-fatu-legende-du-wwe-hall-of-fame-fait-le-point-sur-sa-situation-je-ne-vais-pas-entrer-dans-les-details-sur-tout-ce-qui-sest-passe\/","title":{"rendered":"Rikishi Fatu, l\u00e9gende du WWE Hall of Fame fait le point sur sa situation : \u00ab\u00a0Je ne vais pas entrer dans les d\u00e9tails sur tout ce qui s\u2019est pass\u00e9&#8230;\u00a0\u00bb"},"content":{"rendered":"\n<p>Une l\u00e9gende du WWE Hall of Fame s\u2019est renseign\u00e9e avec une mise \u00e0 jour.<\/p>\n\n\n\n<p>La l\u00e9gende de la WWE, Rikishi Fatu, s\u2019est exprim\u00e9e sur le dernier \u00e9pisode de son podcast&nbsp;<a href=\"https:\/\/www.youtube.com\/watch?v=s0Adce0E2aA\" rel=\"noreferrer noopener\" target=\"_Blank\">Off The Top<\/a>&nbsp;sur la r\u00e9cente intervention chirurgicale d\u2019urgence qu\u2019il a subie.<\/p>\n\n\n\n<p>Vous trouverez ci-dessous quelques-uns des moments forts de l\u2019\u00e9pisode o\u00f9 il aborde ces sujets avec ses pens\u00e9es.<\/p>\n\n\n\n<p><strong>Sur comment il se sent depuis l\u2019op\u00e9ration :<\/strong><\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u00a0\u00abJe suis g\u00e9nial, je suis g\u00e9nial. Vous savez, je ne vais pas entrer dans les d\u00e9tails sur tout ce qui s\u2019est pass\u00e9 et ainsi de suite. Mais vous me connaissez, la seule chose que je ne ferais jamais, c\u2019est de manquer une r\u00e9servation, pendant de nombreuses ann\u00e9es, c\u2019est juste un non non pour le grand Kish. Mais pour moi, \u00eatre \u00e0 terre, c\u2019\u00e9tait une sorte d\u2019op\u00e9ration d\u2019urgence. Et je vais m\u2019arr\u00eater l\u00e0. Il a fallu environ six heures pour pouvoir \u00eatre sous le bistouri. Et je me suis r\u00e9veill\u00e9 en me sentant bien, vous voyez ce que je veux dire ? Je me sens comme une nouvelle personne. <em>\u00bb\u00a0<\/em><\/p>\n<\/blockquote>\n\n\n\n<p><strong>Sur la gratitude, il a \u00e9t\u00e9 attrap\u00e9 juste \u00e0 temps :<\/strong>\u00a0<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u00ab En fin de compte, c\u2019\u00e9tait juste le genre de choses o\u00f9, lorsque vous ne vous faites pas contr\u00f4ler, vous devez normalement vous assurer que vous pouvez consulter vos m\u00e9decins et faire tout le travail de A \u00e0 Z. Et je fais partie de ces gars qui d\u00e9testent aller \u00e0 l\u2019h\u00f4pital. C\u2019\u00e9tait juste le genre de choses qui ont \u00e9t\u00e9 saisies juste \u00e0 temps et avec la gr\u00e2ce de Dieu et des chirurgiens qui \u00e9taient l\u00e0 ce jour-l\u00e0, je suis ici aujourd\u2019hui pour pouvoir m\u2019asseoir et parler avec vous. <em>\u00bb\u00a0<\/em><\/p>\n<\/blockquote>\n\n\n\n<center><iframe loading=\"lazy\" width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/s0Adce0E2aA?si=b4VnfYDW5NEkOdyM\" title=\"YouTube video player\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/center>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Une l\u00e9gende du WWE Hall of Fame s\u2019est renseign\u00e9e avec une mise \u00e0 jour. La l\u00e9gende de la WWE, Rikishi Fatu, s\u2019est exprim\u00e9e sur le dernier \u00e9pisode de son podcast&nbsp;Off The Top&nbsp;sur la r\u00e9cente intervention chirurgicale d\u2019urgence qu\u2019il a subie. Vous trouverez ci-dessous quelques-uns des moments forts de l\u2019\u00e9pisode o\u00f9 il aborde ces sujets avec&#8230;<\/p>\n","protected":false},"author":665,"featured_media":125796,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[30,77,4],"tags":[],"ppma_author":[289],"class_list":["post-125762","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ex-wwe","category-hall-of-fame","category-news"],"authors":[{"term_id":289,"user_id":665,"is_guest":0,"slug":"line","display_name":"Line Edmond","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/852de09636413c90cdaa278312f9ea5bc4396768745424755cb63d99a05989d0?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/125762","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/665"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=125762"}],"version-history":[{"count":2,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/125762\/revisions"}],"predecessor-version":[{"id":125797,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/125762\/revisions\/125797"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/125796"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=125762"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=125762"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=125762"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=125762"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}