{"id":125593,"date":"2025-11-04T20:03:00","date_gmt":"2025-11-05T01:03:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=125593"},"modified":"2025-11-07T12:23:33","modified_gmt":"2025-11-07T17:23:33","slug":"resultats-et-video-pour-le-wwe-nxt-du-4-novembre-au-soir-2025","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2025\/11\/04\/resultats-et-video-pour-le-wwe-nxt-du-4-novembre-au-soir-2025\/","title":{"rendered":"R\u00e9sultats et Vid\u00e9o pour le WWE NXT du 4 Novembre au Soir 2025 !"},"content":{"rendered":"\n<ul class=\"wp-block-list\">\n<li><strong><a href=\"https:\/\/www.jdx.info\/lutte\/2025\/11\/04\/reprise-video-pour-le-wwe-nxt-du-4-novembre-au-soir-2025\/\" target=\"_blank\" rel=\"noreferrer noopener\">Pour voir NXT, cliquez ici.<\/a><\/strong><\/li>\n<\/ul>\n\n\n\n<p><strong>WWE NXT \u2013 R\u00e9sultats du 4 novembre 2025<\/strong><br>Orlando, Floride<\/p>\n\n\n\n<p>Les commentateurs sont Vic Joseph et Booker T. La version francophone est assur\u00e9e par Christophe Agius et Nadir Mohammedi.<\/p>\n\n\n\n<p>Le show s\u2019ouvre alors que les commentateurs souhaitent la bienvenue. Les catcheuses arrivent ensuite sur le ring pour lancer la soir\u00e9e.<\/p>\n\n\n\n<p><strong>Affrontement \u00e0 six :<\/strong><br><em>Tatum Paxley, Izzi Dame et Lola Vice vs Fatal Influence (Jacy Jayne, Fallon Henley et Lainey Reid)<\/em><br>\u00c0 la fin, Paxley bloque une charge de Henley, mais Jayne prend la tag dans le dos. Dame prend aussi la tag et veut attaquer Henley, mais Jayne la surprend avec son Back Fist pour le compte de trois.<br><strong>Gagnantes : <em>Fatal Influence<\/em><\/strong><\/p>\n\n\n\n<p>En coulisses, Los Americanos arrivent. Grande Americano demande \u00e0 ses partenaires o\u00f9 est son vestiaire priv\u00e9. Il s\u2019en prend \u00e0 Josh Briggs et le provoque en duel, promettant de lui montrer qui il est vraiment.<\/p>\n\n\n\n<p>Une vid\u00e9o montre <strong>Lei Ying Lee<\/strong> (Xia Li \u00e0 la TNA) s\u2019adressant \u00e0 <strong>Kelani Jordan<\/strong>, promettant de lui reprendre le titre Knockout.<\/p>\n\n\n\n<p>En coulisses, <strong>Wren Sinclair<\/strong> f\u00e9licite <strong>Kendal Grey<\/strong> pour son entr\u00e9e dans le clan No Quarter Catch Crew. <strong>Kelani Jordan<\/strong> les interrompt pour se vanter de son r\u00e8gne de championne.<\/p>\n\n\n\n<p><strong>Segment sur le ring : Kelani Jordan<\/strong><br>La championne TNA Knockout monte sur le ring et affirme qu\u2019elle ne d\u00e9fendra pas son titre \u00e0 Gold Rush, pr\u00e9tendant que personne \u00e0 NXT ne m\u00e9rite une chance. Elle dit que Lei Ying Lee n\u2019est m\u00eame pas sur son radar et qu\u2019elle l\u2019a d\u00e9j\u00e0 battue.<\/p>\n\n\n\n<p>En coulisses, <strong>OTM<\/strong> s\u2019adresse \u00e0 Sarah en disant qu\u2019ils sont l\u00e0 pour tout prendre. <strong>Uriah Connors<\/strong> et <strong>Kale Dixon<\/strong> interviennent, puis <strong>ChaseU<\/strong> s\u2019en m\u00eale avant qu\u2019Ava ne calme les tensions.<\/p>\n\n\n\n<p><strong>Josh Briggs vs Grande Americano (avec Bravo et Rayo Americano)<\/strong><br>\u00c0 la fin, Americano effectue un saut suicide sur Briggs. Les Americanos profitent d\u2019une distraction pour un Double Back Stabber, puis Americano applique un Chin Lock pour la victoire.<br><strong>Gagnant : <em>Grande Americano<\/em> (soumission)<\/strong><\/p>\n\n\n\n<p>En coulisses, Ava intervient aupr\u00e8s de Kelani Jordan pour lui rappeler qu\u2019elle ne d\u00e9cide pas seule de d\u00e9fendre son titre. <strong>Tyra Mae Steele<\/strong> provoque Jordan et Ava officialise un combat entre elles pour ce soir.<\/p>\n\n\n\n<p><strong>Interview : Trick Williams et Ricky Saints<\/strong><br>Les deux hommes s\u2019affrontent en \u00e9cran partag\u00e9 avant leur match de la semaine prochaine. La tension explose et Williams prend le dessus en coulisses \u00e0 coups de tuyau d\u2019acier.<\/p>\n\n\n\n<p><strong>Tournoi WWE Speed \u2013 Premier tour :<\/strong><br><em>Zaria (avec Sol Ruca) vs Wren Sinclair (avec Kendal Grey)<\/em><br>\u00c0 la fin, Zaria encha\u00eene un Spear puis un F5 pour la victoire.<br><strong>Gagnante : <em>Zaria<\/em><\/strong><\/p>\n\n\n\n<p><strong>Kelani Jordan vs Tyra Mae Steele<\/strong><br>\u00c0 la fin, Jordan ex\u00e9cute un Split Legged Moonsault pour le compte de trois.<br><strong>Gagnante : <em>Kelani Jordan<\/em><\/strong><\/p>\n\n\n\n<p>Apr\u00e8s le combat, <strong>Santino Marella<\/strong> appara\u00eet sur le TitanTron pour annoncer que Jordan d\u00e9fendra finalement son titre Knockout \u00e0 Gold Rush contre <strong>Lei Ying Lee<\/strong> et <strong>Jordynne Grace<\/strong>.<\/p>\n\n\n\n<p><strong>Je\u2019Von Evans vs Saquon Shugars (avec Darkstate)<\/strong><br>Evans esquive un saut du coin et encha\u00eene Cutter apr\u00e8s Cutter avant de terminer avec un Twisted Splash.<br><strong>Gagnant : <em>Je\u2019Von Evans<\/em><\/strong><\/p>\n\n\n\n<p>En coulisses, <strong>Blake Monroe<\/strong> annonce \u00e0 Ava vouloir d\u00e9fendre le titre Glamour \u00e0 Gold Rush contre <strong>Sol Ruca<\/strong>, sous r\u00e9serve du feu vert m\u00e9dical.<\/p>\n\n\n\n<p><strong>C\u00e9l\u00e9bration canadienne : Ethan Page, Chelsea Green et Alba Fyre<\/strong><br>Les nouveaux champions mixtes de la AAA f\u00eatent leur victoire. <strong>Joe Hendry<\/strong> les interrompt, annonce <strong>Thea Hail<\/strong> comme partenaire, et tous deux lancent des tartes au visage de Page et Green pour conclure l\u2019\u00e9mission.<\/p>\n\n\n\n<p class=\"has-text-align-center has-medium-font-size\"><strong><a href=\"https:\/\/www.jdx.info\/lutte\/2025\/11\/04\/reprise-video-pour-le-wwe-nxt-du-4-novembre-au-soir-2025\/\" target=\"_blank\" rel=\"noreferrer noopener\">Pour voir NXT, cliquez ici.<\/a><\/strong><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-info-lutte wp-block-embed-info-lutte\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"0d1Gk8Xgtx\"><a href=\"https:\/\/www.jdx.info\/lutte\/2025\/11\/04\/reprise-video-pour-le-wwe-nxt-du-4-novembre-au-soir-2025\/\">Reprise Vid\u00e9o pour le WWE NXT du 4 Novembre au Soir 2025 !<\/a><\/blockquote><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"\u00ab\u00a0Reprise Vid\u00e9o pour le WWE NXT du 4 Novembre au Soir 2025 !\u00a0\u00bb &#8212; Info-Lutte\" src=\"https:\/\/www.jdx.info\/lutte\/2025\/11\/04\/reprise-video-pour-le-wwe-nxt-du-4-novembre-au-soir-2025\/embed\/#?secret=PPzlxuEkNA#?secret=0d1Gk8Xgtx\" data-secret=\"0d1Gk8Xgtx\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>WWE NXT \u2013 R\u00e9sultats du 4 novembre 2025Orlando, Floride Les commentateurs sont Vic Joseph et Booker T. La version francophone est assur\u00e9e par Christophe Agius et Nadir Mohammedi. Le show s\u2019ouvre alors que les commentateurs souhaitent la bienvenue. Les catcheuses arrivent ensuite sur le ring pour lancer la soir\u00e9e. Affrontement \u00e0 six :Tatum Paxley, Izzi&#8230;<\/p>\n","protected":false},"author":609,"featured_media":125596,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[85,21,23],"tags":[],"ppma_author":[295],"class_list":["post-125593","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nxt","category-resultats","category-wwe"],"authors":[{"term_id":295,"user_id":609,"is_guest":0,"slug":"rodrigo","display_name":"Rodrigue Tousignant","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/51fe284bb6dbe8a6b4c2bf998ad658f4a9cd24b7e58f15ec85888070c7340ce6?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/125593","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/609"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=125593"}],"version-history":[{"count":2,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/125593\/revisions"}],"predecessor-version":[{"id":125678,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/125593\/revisions\/125678"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/125596"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=125593"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=125593"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=125593"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=125593"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}