{"id":125222,"date":"2025-10-28T23:21:00","date_gmt":"2025-10-29T03:21:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=125222"},"modified":"2025-10-30T14:25:35","modified_gmt":"2025-10-30T18:25:35","slug":"legende-du-temple-de-la-renommee-de-la-wwe-pere-de-lactuelle-superstar-de-la-wwe-place-sous-soins-palliatifs","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2025\/10\/28\/legende-du-temple-de-la-renommee-de-la-wwe-pere-de-lactuelle-superstar-de-la-wwe-place-sous-soins-palliatifs\/","title":{"rendered":"L\u00e9gende du Temple de la renomm\u00e9e de la WWE, p\u00e8re de l\u2019actuelle superstar de la WWE plac\u00e9 sous soins palliatifs"},"content":{"rendered":"\n<p>De tristes nouvelles ont fait surface concernant une l\u00e9gende du WWE Hall of Fame.<\/p>\n\n\n\n<p>Mike Rotunda, anciennement connu sous le nom d\u2019Irwin R. Schyster (I.R.S.) \u00e0 la WWE, a \u00e9t\u00e9 plac\u00e9 en soins palliatifs. La nouvelle a \u00e9t\u00e9 rapport\u00e9e pour la premi\u00e8re fois par son beau-fr\u00e8re, Barry Windham, une autre l\u00e9gende de la lutte professionnelle.<\/p>\n\n\n\n<p>Steve Stasiak de Book Pro Wrestlers a partag\u00e9 la d\u00e9claration suivante concernant la nouvelle via sa page&nbsp;<a href=\"https:\/\/www.facebook.com\/story.php?story_fbid=1281588927346790\" target=\"_Blank\" rel=\"noreferrer noopener\">Facebook<\/a>&nbsp;officielle mardi matin :<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>Mike Rotunda a \u00e9t\u00e9 plac\u00e9 sous soins palliatifs.<br>Cette nouvelle vient directement de son beau-fr\u00e8re et partenaire de longue date dans le ring, Barry Windham, qui a partag\u00e9 la mise \u00e0 jour dans une interview avec Bill Apter ce week-end.<br>Mike a fait partie de l\u2019histoire de la lutte \u00e0 chaque tournant.<br>Le Varsity Club.<br>The U.S. Express avec Barry Windham &#8211; Champions par \u00e9quipe de la WWE \u00e0 l\u2019\u00e9poque du Rock &lsquo;n&rsquo; Wrestling.<br>Money Inc. avec Ted DiBiase.<br>Et bien s\u00fbr, l\u2019un des personnages les plus m\u00e9morables du d\u00e9but des ann\u00e9es 90 : I.R.S.<br>Mais bien avant les mallettes et les bretelles, il \u00e9tait le gars sur qui on pouvait compter quand les lumi\u00e8res s\u2019allumaient.<br>Un professionnel.<br>Un leader.<br>Une pr\u00e9sence constante sur laquelle les gar\u00e7ons pouvaient compter.<br>Mike a consacr\u00e9 sa vie \u00e0 cette entreprise.<br>Et ce d\u00e9vouement ne s\u2019est pas arr\u00eat\u00e9 lorsqu\u2019il a quitt\u00e9 le ring.<br>Il a aid\u00e9 \u00e0 \u00e9lever la prochaine g\u00e9n\u00e9ration \u2013 pas seulement ses propres enfants, mais d\u2019innombrables jeunes talents qui l\u2019ont vu se comporter avec humilit\u00e9, discipline et classe chaque soir.<br>\u00c0 l\u2019heure actuelle, la famille Rotunda est confront\u00e9e \u00e0 un combat qu\u2019aucun d\u2019entre nous ne veut jamais voir.<br>Ils ont besoin de force.<br>Ils ont besoin de r\u00e9confort.<br>Ils ont besoin de l\u2019amour des m\u00eames personnes que Mike a diverties et inspir\u00e9es pendant des d\u00e9cennies.<br>Alors aujourd\u2019hui, si vous voulez&#8230;<br>Dites une pri\u00e8re.<\/p>\n\n\n\n<p>Envoyez une pens\u00e9e.<br>\u00c9l\u00e8ve sa femme et ses enfants.<br>Que cette famille ressente le respect que Mike a gagn\u00e9 au cours d\u2019une vie pass\u00e9e \u00e0 donner tout ce qu\u2019il avait \u00e0 la lutte.<br>Mike, nous sommes avec vous.<br>Nous vous en remercions.<br>Et nous vous aimons.<\/p>\n\n\n\n<p>\u2014 Steve Stasiak, Book Pro Wrestlers<\/p>\n<\/blockquote>\n\n\n\n<p>De plus, Barry Windham a parl\u00e9 de la situation lors d\u2019une r\u00e9cente interview avec le journaliste v\u00e9t\u00e9ran de la lutte professionnelle Bill Apter (voir la vid\u00e9o ci-dessous).<\/p>\n\n\n\n<p>Mike Rotunda est le p\u00e8re de la l\u00e9gende de la WWE Bray Wyatt (Windham Rotunda) et le membre actuel de The Wyatt Sicks, Bo Dallas, alias Oncle Howdy (Taylor Rotunda).<\/p>\n\n\n\n<p>Nous envoyons nos pens\u00e9es et nos pri\u00e8res \u00e0 Mike Rotunda et \u00e0 sa famille en ce moment. Nous vous tiendrons au courant ici au fur et \u00e0 mesure que les mises \u00e0 jour continuent de faire surface.<\/p>\n\n\n\n<center><iframe loading=\"lazy\" width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/IR6rEpxzOEs?si=6oUcyYvtRORkrBWo\" title=\"YouTube video player\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/center>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>De tristes nouvelles ont fait surface concernant une l\u00e9gende du WWE Hall of Fame. Mike Rotunda, anciennement connu sous le nom d\u2019Irwin R. Schyster (I.R.S.) \u00e0 la WWE, a \u00e9t\u00e9 plac\u00e9 en soins palliatifs. La nouvelle a \u00e9t\u00e9 rapport\u00e9e pour la premi\u00e8re fois par son beau-fr\u00e8re, Barry Windham, une autre l\u00e9gende de la lutte professionnelle&#8230;.<\/p>\n","protected":false},"author":665,"featured_media":125322,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[30,77,187,4],"tags":[],"ppma_author":[289],"class_list":["post-125222","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ex-wwe","category-hall-of-fame","category-legends","category-news"],"authors":[{"term_id":289,"user_id":665,"is_guest":0,"slug":"line","display_name":"Line Edmond","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/852de09636413c90cdaa278312f9ea5bc4396768745424755cb63d99a05989d0?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/125222","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/665"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=125222"}],"version-history":[{"count":2,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/125222\/revisions"}],"predecessor-version":[{"id":125323,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/125222\/revisions\/125323"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/125322"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=125222"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=125222"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=125222"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=125222"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}