{"id":121378,"date":"2025-08-03T19:10:00","date_gmt":"2025-08-03T23:10:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=121378"},"modified":"2025-08-04T14:20:21","modified_gmt":"2025-08-04T18:20:21","slug":"le-groupe-compose-du-nouveau-champion-du-monde-poids-lourd-wwe-seth-rollins-paul-heyman-bron-breakker-et-bronson-reed-devrait-sappeler-the-vision","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2025\/08\/03\/le-groupe-compose-du-nouveau-champion-du-monde-poids-lourd-wwe-seth-rollins-paul-heyman-bron-breakker-et-bronson-reed-devrait-sappeler-the-vision\/","title":{"rendered":"Le Groupe compos\u00e9 du nouveau champion du monde poids lourd WWE Seth Rollins, Paul Heyman, Bron Breakker et Bronson Reed devrait s&rsquo;appeler The Vision !"},"content":{"rendered":"\n<p>La WWE a une vision pour la nouvelle faction dirig\u00e9e par Seth Rollins.<\/p>\n\n\n\n<p>Et elle a commenc\u00e9 \u00e0 prendre forme la nuit, l\u2019une des \u00ab plus grandes f\u00eates de l\u2019\u00e9t\u00e9 \u00bb.<\/p>\n\n\n\n<p>Le samedi 2 ao\u00fbt, la WWE a officiellement d\u00e9pos\u00e9 une demande de marque pour le nom \u00ab&nbsp;The Vision&nbsp;\u00bb aupr\u00e8s de l\u2019Office des brevets et des marques des \u00c9tats-Unis (USPTO). Le d\u00e9p\u00f4t a \u00e9t\u00e9 fait pour \u00eatre utilis\u00e9 dans des contextes de lutte professionnelle et de divertissement, avec Lauren A. Dienes-Middlen r\u00e9pertori\u00e9e comme avocate au dossier de la WWE.<\/p>\n\n\n\n<p>Le d\u00e9p\u00f4t de la marque d\u00e9crit l\u2019utilisation comme suit :\u00a0<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p><em>\u00ab Services de divertissement, \u00e0 savoir des expositions de lutte et des performances d\u2019un lutteur professionnel et d\u2019un artiste diffus\u00e9es en direct et par le biais de m\u00e9dias audiovisuels, y compris la t\u00e9l\u00e9vision et la radio et via Internet ou un service commercial en ligne ; fournir des nouvelles et des informations sur la lutte via un r\u00e9seau informatique mondial\u00a0; fournir des informations dans les domaines du sport et du divertissement via un portail communautaire en ligne ; la mise \u00e0 disposition d\u2019un site web dans le domaine de l\u2019information sur le divertissement sportif ; les services de fan club, nomm\u00e9ment l\u2019organisation d\u2019\u00e9v\u00e9nements sportifs dans le domaine de la lutte pour les membres de fan club de lutte\u00a0; l\u2019organisation d\u2019\u00e9v\u00e9nements de divertissement social \u00e0 des fins de divertissement pour les membres du fan club de lutte\u00a0; la fourniture de bulletins d\u2019information en ligne dans les domaines du divertissement sportif ; les revues en ligne, \u00e0 savoir les blogs, dans le domaine du divertissement sportif.<\/em><\/p>\n<\/blockquote>\n\n\n\n<p>Bien qu\u2019aucun lien officiel n\u2019ait \u00e9t\u00e9 confirm\u00e9, les sp\u00e9culations vont d\u00e9j\u00e0 bon train sur le fait que \u00ab&nbsp;The Vision&nbsp;\u00bb pourrait \u00eatre le nom \u00e9ventuel de la faction suppos\u00e9e impliquant Seth Rollins, qui s\u2019est longtemps qualifi\u00e9 de \u00ab&nbsp;The Visionary&nbsp;\u00bb. Rollins s\u2019est r\u00e9cemment align\u00e9 \u00e0 la t\u00e9l\u00e9vision de la WWE avec Paul Heyman, Bron Breakker et Bronson Reed, ce qui a amen\u00e9 beaucoup de gens \u00e0 croire qu\u2019un groupe formel pourrait se former.<\/p>\n\n\n\n<p>Rollins est revenu de \u00ab\u00a0blessure\u00a0\u00bb lors du combat principal de la WWE SummerSlam Night 1, r\u00e9ussissant ce qui est surnomm\u00e9 \u00ab\u00a0La Ruse du si\u00e8cle\u00a0\u00bb en encaissant sa mallette Money In The Bank pour mettre fin au nouveau r\u00e8gne de CM Punk qui aura dur\u00e9 environ cinq minutes.<\/p>\n\n\n\n<p><\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>La WWE a une vision pour la nouvelle faction dirig\u00e9e par Seth Rollins. Et elle a commenc\u00e9 \u00e0 prendre forme la nuit, l\u2019une des \u00ab plus grandes f\u00eates de l\u2019\u00e9t\u00e9 \u00bb. Le samedi 2 ao\u00fbt, la WWE a officiellement d\u00e9pos\u00e9 une demande de marque pour le nom \u00ab&nbsp;The Vision&nbsp;\u00bb aupr\u00e8s de l\u2019Office des brevets et&#8230;<\/p>\n","protected":false},"author":665,"featured_media":121460,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,43,53,23],"tags":[],"ppma_author":[289],"class_list":["post-121378","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-raw-wwe","category-summerslam","category-wwe"],"authors":[{"term_id":289,"user_id":665,"is_guest":0,"slug":"line","display_name":"Line Edmond","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/852de09636413c90cdaa278312f9ea5bc4396768745424755cb63d99a05989d0?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/121378","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/665"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=121378"}],"version-history":[{"count":2,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/121378\/revisions"}],"predecessor-version":[{"id":121461,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/121378\/revisions\/121461"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/121460"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=121378"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=121378"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=121378"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=121378"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}