{"id":121117,"date":"2025-07-27T16:25:25","date_gmt":"2025-07-27T20:25:25","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=121117"},"modified":"2025-07-28T17:48:48","modified_gmt":"2025-07-28T21:48:48","slug":"121117","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2025\/07\/27\/121117\/","title":{"rendered":"Jimmy Korderas s&rsquo;en prend aux haineux d&rsquo;Hogan, Kane et Lex Luger parle de la M\u00e9moire du Hulkster, et plus !"},"content":{"rendered":"\n<p>&#8211; Lex Luger est r\u00e9cemment revenu sur sa victoire au WCW World Heavyweight Championship de 1997 contre Hulk Hogan lors d\u2019un \u00e9pisode de son podcast \u00ab&nbsp;Lex Expressed&nbsp;\u00bb. Luger a battu Hogan lors de l\u2019\u00e9dition du 4 ao\u00fbt de WCW Monday Nitro, remportant le titre pour un bref r\u00e8gne de cinq jours avant de le laisser tomber.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u00ab Je ne l\u2019ai d\u00e9couvert que lorsque j\u2019\u00e9tais presque pr\u00eat \u00e0 monter sur le ring. Ils ont demand\u00e9 \u00e0 Hulk : \u00ab&nbsp;<em>Avec qui veux-tu faire \u00e7a ?<\/em>&nbsp;\u00bb &#8230; Il a dit : \u00ab&nbsp;\u00c0 100&nbsp;%, je veux le faire avec Lex.&nbsp;\u00bb<\/p>\n\n\n\n<p>\u00ab C\u2019\u00e9tait un \u00e9norme compliment de la part de l\u2019une des plus grandes stars de l\u2019histoire de l\u2019entreprise. C\u2019\u00e9tait incroyable de revenir et d\u2019avoir la chance d\u2019atteindre \u00e0 nouveau ce niveau \u00e0 la WCW. \u00bb<\/p>\n<\/blockquote>\n\n\n\n<p>&#8211; Kane, \u00e9galement connu sous le nom de Glenn Jacobs, a r\u00e9cemment r\u00e9fl\u00e9chi au d\u00e9c\u00e8s de Hulk Hogan, et a partag\u00e9 ses souvenirs de travail avec la l\u00e9gendaire superstar. Apparaissant sur Newsmax, Kane a rendu hommage \u00e0 l\u2019h\u00e9ritage de Hogan, apr\u00e8s sa mort jeudi \u00e0 l\u2019\u00e2ge de 71 ans.<\/p>\n\n\n\n<p>Vous pouvez d\u00e9couvrir ci-dessous quelques points forts de l\u2019interview :<\/p>\n\n\n\n<p><strong>Sur l\u2019h\u00e9ritage de Hulk Hogan :<\/strong><\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>&nbsp; \u00ab [Il] a vraiment pris la lutte professionnelle et a contribu\u00e9 \u00e0 en faire ce qu\u2019elle est aujourd\u2019hui, il n\u2019\u00e9tait pas seulement un lutteur professionnel, il a transcend\u00e9 cela&nbsp;; Je veux dire, c\u2019\u00e9tait une ic\u00f4ne du divertissement et de la culture pop&#8230; Il nous manquera certainement et j\u2019ai eu tellement de gens qui m\u2019ont contact\u00e9 et juste&#8230; c\u2019est comme si une partie de notre enfance \u00e9tait morte parce que beaucoup d\u2019entre nous \u2013 c\u2019est avec \u00e7a que nous avons grandi \u2013 \u00e9taient Hulk Hogan. &nbsp;\u00bb<\/p>\n<\/blockquote>\n\n\n\n<p><strong>Sur la collaboration avec Hogan :<\/strong>&nbsp;<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p> \u00ab Surtout les gens de mon \u00e2ge, nous \u00e9tions tous des fans de Hulk Hogan en grandissant. Un peu diff\u00e9rent, \u00e9videmment, parce que j\u2019ai eu l\u2019occasion de travailler avec lui, mais pas tant que \u00e7a. Ce qui, pour moi, \u00e9tait presque un r\u00eave devenu r\u00e9alit\u00e9, vous savez, de le regarder quand j\u2019\u00e9tais enfant et de l\u2019idol\u00e2trer, de pouvoir travailler un peu avec lui \u00e9tait un r\u00eave r\u00e9alis\u00e9 pour moi.<\/p>\n<\/blockquote>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>  \u00abIl avait un charisme \u00e9norme et \u00e9tait un grand interpr\u00e8te et il \u00e9tait vraiment au bon endroit ; Il \u00e9tait la bonne personne, au bon endroit, au bon moment. Avec un m\u00e9lange de Rock &amp; Wrestling et de MTV au milieu des ann\u00e9es 80, son personnage a \u00e9volu\u00e9 au fil des ans et je pense qu\u2019il a su saisir ce qui se passait dans la culture pop. En fin de compte, c\u2019est juste le fait qu\u2019il \u00e9tait un artiste fantastique et qu\u2019il a eu l\u2019occasion de vraiment le montrer. &nbsp;\u00bb<\/p>\n<\/blockquote>\n\n\n\n<iframe loading=\"lazy\" width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/D1dFJZwFPEQ?si=bt1kJdf4DF5yaBR4\" title=\"YouTube video player\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n\n\n\n<p>L\u2019ancien arbitre de la WWE, Jimmy Korderas, s\u2019est exprim\u00e9 contre la vague de r\u00e9actions en ligne qui a suivi le d\u00e9c\u00e8s de Hulk Hogan, critiquant le ton imm\u00e9diat et s\u00e9v\u00e8re adopt\u00e9 par certains membres de la communaut\u00e9 de la lutte.<\/p>\n\n\n\n<p>Dans un message s\u00e9v\u00e8re sur Twitter, Korderas a exprim\u00e9 sa d\u00e9ception face \u00e0 la rapidit\u00e9 avec laquelle certains fans et personnalit\u00e9s se sont pr\u00e9cipit\u00e9s pour mettre en lumi\u00e8re l\u2019histoire controvers\u00e9e de Hogan \u2013 en particulier ses remarques racistes pass\u00e9es \u2013 peu de temps apr\u00e8s que la nouvelle de sa mort soit devenue publique. Il a \u00e9crit :<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u00ab\u00a0La mani\u00e8re dont les gens n\u2019ont pas pu le garder dans leur pantalon, m\u00eame pendant quelques heures, avec la nouvelle du d\u00e9c\u00e8s de Hulk Hogan a \u00e9t\u00e9 un moment aussi R\u00c9EL que nous l\u2019avons eu \u00e0 la IWC. La rapidit\u00e9 avec laquelle beaucoup voulaient faire un tour d\u2019honneur au vitriol de la haine de Hogan sur la mort d\u2019un homme \u00e9tait r\u00e9v\u00e9latrice.<\/p>\n<\/blockquote>\n\n\n\n<p>Korderas a reconnu que Hogan avait<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>&nbsp;<em>\u00ab&nbsp;de nombreux d\u00e9fauts&nbsp;\u00bb<\/em>&nbsp;qui ne devraient pas \u00eatre effac\u00e9s de son h\u00e9ritage, mais a soulign\u00e9 que le timing et le tact comptent. <em>\u00bb<\/em><\/p>\n\n\n\n<p>\u00ab Les d\u00e9fauts de Hogan ne doivent PAS \u00eatre ignor\u00e9s. Cela DEVRAIT faire partie de son h\u00e9ritage. Mais il y a un temps et un lieu pour cela. Il y a un certain niveau de tact que l\u2019on peut avoir lorsqu\u2019on en discute.\u00bb<\/p>\n<\/blockquote>\n\n\n\n<p>Apr\u00e8s avoir offici\u00e9 \u00e0 la WWE pendant plus de 20 ans, Korderas a poursuivi en critiquant ce qu\u2019il a appel\u00e9 une&nbsp;<em>\u00ab&nbsp;foule toxique qui vit dans la mis\u00e8re&nbsp;\u00bb,<\/em>&nbsp;accusant beaucoup d\u2019\u00eatre plus int\u00e9ress\u00e9s par l\u2019attention des m\u00e9dias sociaux que par une r\u00e9flexion r\u00e9fl\u00e9chie.&nbsp;<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>&nbsp;<em>\u00ab&nbsp;<\/em> Il ne devrait pas \u00eatre si difficile de NE RIEN DIRE si vous n\u2019avez rien de bon \u00e0 dire \u00e0 la suite du d\u00e9c\u00e8s de quelqu\u2019un. Ce n\u2019\u00e9tait pas un meurtrier en s\u00e9rie. Il n\u2019\u00e9tait pas un criminel condamn\u00e9. Il \u00e9tait aim\u00e9 par plus de gens qu\u2019il ne le d\u00e9testait. <em>\u00bb<\/em><\/p>\n<\/blockquote>\n\n\n\n<p>Il a conclu en sugg\u00e9rant qu\u2019une grande partie des critiques provenaient d\u2019un lieu d\u2019indignation performative. Il a conclu :&nbsp;<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u00ab Ils ne d\u00e9testaient pas l\u2019homme autant qu\u2019ils aimaient montrer qu\u2019ils le d\u00e9testaient. Encore une fois, plus plein de qu\u2019un \u00e9gout qui veut fuir dans toute la soci\u00e9t\u00e9.<\/p>\n<\/blockquote>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>&#8211; Lex Luger est r\u00e9cemment revenu sur sa victoire au WCW World Heavyweight Championship de 1997 contre Hulk Hogan lors d\u2019un \u00e9pisode de son podcast \u00ab&nbsp;Lex Expressed&nbsp;\u00bb. Luger a battu Hogan lors de l\u2019\u00e9dition du 4 ao\u00fbt de WCW Monday Nitro, remportant le titre pour un bref r\u00e8gne de cinq jours avant de le laisser&#8230;<\/p>\n","protected":false},"author":609,"featured_media":121128,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[30,77,187,4],"tags":[201],"ppma_author":[295],"class_list":["post-121117","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ex-wwe","category-hall-of-fame","category-legends","category-news","tag-hogan"],"authors":[{"term_id":295,"user_id":609,"is_guest":0,"slug":"rodrigo","display_name":"Rodrigue Tousignant","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/51fe284bb6dbe8a6b4c2bf998ad658f4a9cd24b7e58f15ec85888070c7340ce6?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/121117","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/609"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=121117"}],"version-history":[{"count":3,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/121117\/revisions"}],"predecessor-version":[{"id":121126,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/121117\/revisions\/121126"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/121128"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=121117"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=121117"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=121117"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=121117"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}