{"id":118939,"date":"2025-06-13T20:01:00","date_gmt":"2025-06-14T00:01:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=118939"},"modified":"2025-06-18T12:56:17","modified_gmt":"2025-06-18T16:56:17","slug":"reprise-video-pour-le-wwe-friday-night-smackdown-du-vendredi-13-juin-2025-2","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2025\/06\/13\/reprise-video-pour-le-wwe-friday-night-smackdown-du-vendredi-13-juin-2025-2\/","title":{"rendered":"R\u00e9sultats et Vid\u00e9o pour le WWE Friday Night Smackdown du Vendredi 13 Juin 2025 !"},"content":{"rendered":"\n<ul class=\"wp-block-list\">\n<li><strong><a href=\"https:\/\/www.jdx.info\/lutte\/2025\/06\/13\/reprise-video-pour-le-wwe-friday-night-smackdown-du-vendredi-13-juin-2025\/\" target=\"_blank\" rel=\"noreferrer noopener\">Pour voir Smackdown, cliquez ici.<\/a><\/strong><\/li>\n<\/ul>\n\n\n\n<p>WWE SmackDown&nbsp;Lexington, Kentucky<\/p>\n\n\n\n<p>Les commentateurs sont Joe Tessitore et Wade Barrett. Les commentateurs en VF sont Christophe Agius et Nadir Mohammedi.<\/p>\n\n\n\n<p>&#8211; Le WWE Friday Night Smackdown d\u00e9bute avec les commentateurs qui vous souhaitent la bienvenue puis pr\u00e9sentent le programme de la soir\u00e9e puis on revoit ce qu&rsquo;il s&rsquo;est pass\u00e9\u00a0\u00e0 Money in the Bank samedi dernier. <\/p>\n\n\n\n<p>&#8211; John Cena fait son entr\u00e9e et dit que le Mont Rushmore du catch, c&rsquo;est lui, lui, lui et lui. Il y a eu de grands catcheurs mais personne ne peut \u00eatre compar\u00e9 \u00e0 lui. S&rsquo;il est meilleur, ce n&rsquo;est pas parce qu&rsquo;il n&rsquo;abandonne pas, c&rsquo;est parce qu&rsquo;il est plus malin. Il a toujours 1 000 coups d&rsquo;avance sur nous, il a pens\u00e9 \u00e0 tout \u00e7a il y a plus d&rsquo;un an. Il a annonc\u00e9 sa retraite pour avoir 6 mois pour r\u00e9fl\u00e9chir \u00e0 ses adversaires. Il savait que s&rsquo;il perdait le Royal Rumble, il pourrait utiliser son anciennet\u00e9 pour avoir sa place \u00e0 l&rsquo;Elimination Chamber. Il savait aussi que CM Punk et Seth Rollins allaient p\u00e9ter un c\u00e2ble, lui offrant la victoire. Il savait aussi que le Final Boss attirerait l&rsquo;attention de Cody Rhodes. Tout ce qu&rsquo;il avait \u00e0 faire \u00e9tait d&rsquo;utiliser la passion de Cody Rhodes pour la grande sc\u00e8ne pour s&rsquo;assurer une victoire \u00e0 WrestleMania.<\/p>\n\n\n\n<p>Il a utilis\u00e9 une rivalit\u00e9 de 25 ans et la ville natale de Randy Orton pour le mettre en confiance et il a mis R-Truth en Main Event. Pendant que les fans perdaient leur temps avec R-Truth, il a fait \u00e9quipe avec Logan Paul et se pr\u00e9pare maintenant \u00e0 affronter CM Punk. Si CM Punk veut vraiment le titre, il devra avouer que c&rsquo;est un hypocrite. Concernant Seth Rollins, il ne va jamais cash-in lui. Rollins veut qu&rsquo;il parte avec ce titre car il sera le seul champion apr\u00e8s son cash-in. Personne ne m\u00e9rite de mettre ses mains sur son titre. <\/p>\n\n\n\n<p>Cody Rhodes fait son entr\u00e9e pour dire que John Cena est un g\u00e9nie. Il a raison sur tout, mais pourquoi a-t-il oubli\u00e9 d&rsquo;inclure qu&rsquo;\u00e0 Money in the Bank, Rhodes a fait le tomb\u00e9 sur lui au milieu du ring ? Cody Rhodes ne fait pas partie du plan de John Cena, mais Cena fait partie du sien. Alors ils en sont o\u00f9 maintenant ? <\/p>\n\n\n\n<p>Randy Orton arrive et dit \u00e0 John Cena que tout le monde a vu qu&rsquo;il l&rsquo;avait battu, mais quelqu&rsquo;un est venu le sauver. S&rsquo;il doit gagner le King of the Ring pour chercher le titre, \u00e7a lui va, m\u00eame s&rsquo;il aime Cody comme un fr\u00e8re !<\/p>\n\n\n\n<p> LA Knight arrive \u00e0 son tour et dit qu&rsquo;il va aller chercher le titre en passant par Randy Orton et Cody Rhodes dans le King of the Ring.<\/p>\n\n\n\n<p>John Cena quitte le ring&#8230; mais Ron Killings (R-Truth) l&rsquo;attaque par derri\u00e8re ! Les officiels viennent s\u00e9parer les deux hommes.<\/p>\n\n\n\n<p><strong>Fatal 4-Way<\/strong> : <strong>Qualification King of the Ring <\/strong><br>Randy Orton vs LA Knight vs Carmelo Hayes vs Aleister Black<\/p>\n\n\n\n<p>\u00c0 la fin du match, LA Knight se fait attaquer par Bronson Reed puis se prend un Spear de Bron Breakker ! Carmelo Hayes monte sur la troisi\u00e8me corde et tente un Frog Splash mais il se prend un RKO Outta Nowhere de Randy Orton qui enchaine avec le tomb\u00e9 sur LA Knight pour l&#8217;emporter.<\/p>\n\n\n\n<p><em>Gagnant :\u00a0Randy Orton<\/em><\/p>\n\n\n\n<p>&#8211; Randy Orton affrontera Sami Zayn en demi-finales du King of the Ring.<\/p>\n\n\n\n<p>&#8211; Jacob Fatu fait son entr\u00e9e&nbsp;et prend un micro. Il dit que ce n&rsquo;est pas parce que quelqu&rsquo;un fait partie de ta famille qu&rsquo;il peut te poignarder dans le dos. Solo Sikoa dit que Fatu ne serait rien sans lui. Solo Sikoa apparait sur l&rsquo;\u00e9cran g\u00e9ant et dit \u00e0 Jacob Fatu qu&rsquo;il a fait la plus grosse erreur de sa vie mais il peut le pardonner. Quand il est venu le voir l&rsquo;ann\u00e9e derni\u00e8re, Fatu ne faisait rien. C&rsquo;est lui qui l&rsquo;a fait devenir une Superstar. La semaine prochaine, Solo Sikoa sera sur le ring avec les bras ouverts, mais il devra entendre les mots suivants de sa bouche : I Love You Solo.&nbsp;Jacob Fatu doit se rappeler que c&rsquo;est Solo Sikoa qui l&rsquo;a fait entrer dans ce monde et qu&rsquo;il peut l&rsquo;en faire sortir.<\/p>\n\n\n\n<p>&#8211; En coulisses, Piper Niven et Alba Fyre vont voir Nick Aldis et Chelsea Green est en Facetime. Green dit qu&rsquo;elle n&rsquo;a pas pu aller \u00e0 Lexington et son match doit \u00eatre report\u00e9 \u00e0 la semaine prochaine. Aldis refuse et annonce que c&rsquo;est Alba Fyre qui prendra sa place ce soir. <\/p>\n\n\n\n<p>The Secret Hervice s&rsquo;en va et Zelina Vega arrive. La championne veut affronter Giulia. Nick Aldis dit qu&rsquo;elle n&rsquo;est pas l\u00e0 ce soir. Green affirme qu&rsquo;elle veut l&rsquo;affronter la semaine prochaine.<\/p>\n\n\n\n<p><strong>Fatal 4-Way<\/strong> : <strong>Qualification Queen of the Ring <\/strong><br>Jade Cargill vs Piper Niven vs Michin vs Nia Jax<\/p>\n\n\n\n<p>\u00c0 la fin du match,&nbsp;Piper Niven fait sa Piper Bomb sur Michin&#8230; mais Jade Cargill remonte sur le ring et porte son Jaded sur Niven pour l&#8217;emporter par tomb\u00e9.<\/p>\n\n\n\n<p><em>Gagnante :\u00a0Jade Cargill<\/em><\/p>\n\n\n\n<p>&#8211; Jade Cargill affrontera Roxanne Perez en demi-finales du Queen of the Ring.<\/p>\n\n\n\n<p>&#8211; Naomi fait son entr\u00e9e et prend un micro. Elle dit que les gens ont l&rsquo;air surpris mais elle a pris ce qu&rsquo;elle m\u00e9ritait et la voil\u00e0 Ms. Money in the Bank !\u00a0Mais quand elle essayait de battre Nia Jax pour le titre, Tiffany Stratton \u00e9tait l\u00e0 avec sa mallette pour l&rsquo;arr\u00eater. L&rsquo;ancienne Naomi avait laiss\u00e9 faire, mais ce n&rsquo;est plus le cas maintenant. \u00c7a lui fera du bien quand elle frappera Tiffany Stratton avec la mallette. La musique de Tiffany Stratton retentit et elle arrive. <\/p>\n\n\n\n<p>La championne lui demande pourquoi elle ne fait pas son cash-in maintenant. C&rsquo;est toujours la m\u00eame Naomi : \u00e7a parle mais \u00e7a n&rsquo;agit pas. C&rsquo;est pour \u00e7a qu&rsquo;elle n&rsquo;avait pas battu Nia Jax. Naomi lui demande si elle a l&rsquo;air idiote. Elle utilisera sa mallette quand Tiffany Stratton s&rsquo;y attendra le moins. En attendant, elle va faire de sa vie un enfer. Son temps est compt\u00e9.<\/p>\n\n\n\n<p>Naomi quitte le ring, mais Nia Jax attaque Tiffany Stratton par derri\u00e8re sur le ring ! Stratton r\u00e9ussit \u00e0 mettre Jax au sol puis fait tomber Naomi du tablier du ring. Nia Jax profite de cette distraction pour&nbsp;attaquer \u00e0 nouveau la championne et lui porter son Annihilator. Naomi monte sur le ring mais Nia Jax lui dit de s&rsquo;en aller. Naomi quitte le ring.<\/p>\n\n\n\n<p>&#8211; Plus t\u00f4t aujourd&rsquo;hui, DIY propose \u00e0 Nick Aldis les diff\u00e9rentes \u00e9quipes pour affronter les Wyatt Sicks. Aldis annonce que les Motor City Machine Guns affronteront les Wyatt Sicks ce soir.<\/p>\n\n\n\n<p><strong>Motor City Machine Guns (Alex Shelley et Chris Sabin) vs\u00a0Joe Gacy et Dexter Lumis\u00a0acc des Wyatt Sicks<\/strong><\/p>\n\n\n\n<p>\u00c0 la fin du match,&nbsp;Dexter Lumis et Joe Gacy \u00e9vitent un Skull and Bones des MCMG et font une prise \u00e0 deux sur Chris Sabin. Lumis enchaine avec le tomb\u00e9 mais il abandonne le tomb\u00e9. Dexter Lumis monte sur la troisi\u00e8me corde pour un Leg Drop sur Sabin suivi du tomb\u00e9 pour la victoire.<\/p>\n\n\n\n<p><em>Gagnants : Wyatt Sicks Joe Gacy et\u00a0Dexter Lumis<\/em><\/p>\n\n\n\n<p>&#8211; En coulisses, John Cena croise Jimmy Uso et lui demande s&rsquo;il a vu R-Truth ou Ron Killings. Jimmy Uso r\u00e9pond qu&rsquo;il n&rsquo;a vu ni l&rsquo;un ni l&rsquo;autre. Cena affirme qu&rsquo;il sait qu&rsquo;ils sont proches, il peut lui dire de le retrouver sur le ring maintenant.<\/p>\n\n\n\n<p>&#8211; John Cena fait son entr\u00e9e et invite R-Truth \u00e0 venir ! <\/p>\n\n\n\n<p>La musique de CM Punk se lance et il d\u00e9barque. pour dire \u00e0 John Cena\u00a0d&rsquo;arr\u00eater ce qu&rsquo;il fait, de laisser les fans c\u00e9l\u00e9brer qui il est et le mettre sur un pi\u00e9destal pour ce qu&rsquo;il a fait pour le catch. Que John Cena offre aux fans une fin heureuse ! John Cena demande pourquoi il perdrait son temps. Les fans n&rsquo;ont pas d&rsquo;importance. Tout ce qui compte, c&rsquo;est le titre. CM Punk d\u00e9clare que John Cena ne peut pas le battre au meilleur de sa forme. Il ne l&rsquo;a jamais battu. Si John Cena veut ruiner le catch, CM Punk va le sauver. Punk s&rsquo;est d\u00e9j\u00e0 barr\u00e9 avec le titre, Cena suit ses traces. Il va rendre le r\u00e8gne de Cena int\u00e9ressant, il va le suivre jusqu&rsquo;\u00e0 Mars pour lui botter le cul. Ouais, John Cena est un GOAT, mais lui aussi. Concernant le Mont Rushmore du catch, il y a des personnes comme Terry Funk, Harley Race, Bret Hart ou encore Eddie Guerrero. CM Punk voit \u00e0 travers John Cena et il l&rsquo;a toujours vu&#8230; c&rsquo;est la v\u00e9rit\u00e9. CM Punk quitte le ring et R-Truth attaque \u00e0 nouveau John Cena puis lui applique un STF ! CM Punk dit que la v\u00e9rit\u00e9 blesse.<\/p>\n\n\n\n<p>&#8211; En coulisses, Alexa Bliss dit qu&rsquo;elle a d\u00e9j\u00e0 gagn\u00e9 le Money in the Bank Ladder Match, elle va rappeler qui est Alexa Bliss et va gagner le Queen of the Ring. Charlotte Flair apparait et dit qu&rsquo;il n&rsquo;y a qu&rsquo;une Reine dans cette division.<\/p>\n\n\n\n<p>&#8211; En coulisses,\u00a0R-Truth demande \u00e0 Nick Aldis d&rsquo;affronter John Cena la semaine prochaine. Aldis accepte.<\/p>\n\n\n\n<p><strong>Fatal 4-Way<\/strong> : <strong>Qualification Queen of the Ring <\/strong><br>Charlotte Flair vs Alexa Bliss vs Alba Fyre vs Candice LeRae<\/p>\n\n\n\n<p>\u00c0 la fin du match, Charlotte Flair applique son Figure Eight Leglock sur Alba Fyre. Pendant ce temps, Alexa Bliss porte le Sister Abigail sur Candice LeRae suivi du tomb\u00e9 pour l&#8217;emporter.<\/p>\n\n\n\n<p><em>Gagnante :\u00a0Alexa Bliss<\/em><\/p>\n\n\n\n<p>&#8211; Apr\u00e8s le match, Charlotte Flair n&rsquo;en revient pas, alors qu&rsquo;Alexa Bliss c\u00e9l\u00e8bre sa victoire.<\/p>\n\n\n\n<p>&#8211; En coulisses, CM Punk souhaite une bonne chance \u00e0 Cody Rhodes pour ce soir.<\/p>\n\n\n\n<p>&#8211; La semaine prochaine \u00e0 SamckDown : Randy Orton vs Sami Zayn en demi-finale du King of the Ring \/ Alexa Bliss vs ? (la gagnante \u00e0 RAW) en demi-finale du Queen of the Ring \/ R-Truth contre John Cena.<\/p>\n\n\n\n<p><strong>Fatal 4-Way<\/strong> : <strong>Qualification King of the Ring <\/strong><br>Cody Rhodes vs Damian Priest vs Andrade vs Shinsuke Nakamura<\/p>\n\n\n\n<p>Cody Rhodes contre un Razor&rsquo;s Edge de Damian Priest et lui porte un Cody Cutter ! Rhodes \u00e9vite un coup d&rsquo;Andrade et lui porte un Cross Rhodes, mais Shinsuke Nakamura surprend Cody Rhodes&#8230; ce dernier le contre avec un Cross Rhodes suivi du tomb\u00e9 pour l&#8217;emporter.<\/p>\n\n\n\n<p><em>Gagnant :\u00a0Cody Rhodes<\/em><\/p>\n\n\n\n<p>&#8211; Cody Rhodes affrontera le vainqueur de RAW en demi-finales d\u00e9pendamment de qui gagnera entre Sheamus, Rusev, Bronson Reed et Jey Uso. <\/p>\n\n\n\n<p>Le show se termine sur une c\u00e9l\u00e9bration de Cody Rhodes.<\/p>\n\n\n\n<p class=\"has-text-align-center has-medium-font-size\"><strong><a href=\"https:\/\/www.jdx.info\/lutte\/2025\/06\/13\/reprise-video-pour-le-wwe-friday-night-smackdown-du-vendredi-13-juin-2025\/\" target=\"_blank\" rel=\"noreferrer noopener\">Pour voir Smackdown, cliquez ici.<\/a><\/strong><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-info-lutte wp-block-embed-info-lutte\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"o9eICHhM6I\"><a href=\"https:\/\/www.jdx.info\/lutte\/2025\/06\/13\/reprise-video-pour-le-wwe-friday-night-smackdown-du-vendredi-13-juin-2025\/\">Reprise Vid\u00e9o pour le WWE Friday Night Smackdown du Vendredi 13 Juin 2025 !<\/a><\/blockquote><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"\u00ab\u00a0Reprise Vid\u00e9o pour le WWE Friday Night Smackdown du Vendredi 13 Juin 2025 !\u00a0\u00bb &#8212; Info-Lutte\" src=\"https:\/\/www.jdx.info\/lutte\/2025\/06\/13\/reprise-video-pour-le-wwe-friday-night-smackdown-du-vendredi-13-juin-2025\/embed\/#?secret=JeOKfwPpVw#?secret=o9eICHhM6I\" data-secret=\"o9eICHhM6I\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>WWE SmackDown&nbsp;Lexington, Kentucky Les commentateurs sont Joe Tessitore et Wade Barrett. Les commentateurs en VF sont Christophe Agius et Nadir Mohammedi. &#8211; Le WWE Friday Night Smackdown d\u00e9bute avec les commentateurs qui vous souhaitent la bienvenue puis pr\u00e9sentent le programme de la soir\u00e9e puis on revoit ce qu&rsquo;il s&rsquo;est pass\u00e9\u00a0\u00e0 Money in the Bank samedi&#8230;<\/p>\n","protected":false},"author":37048,"featured_media":118980,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[103,88,21,23],"tags":[248],"ppma_author":[297],"class_list":["post-118939","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-king-of-the-ring","category-night-of-champions","category-resultats","category-wwe","tag-queen"],"authors":[{"term_id":297,"user_id":37048,"is_guest":0,"slug":"mattante","display_name":"Mattias Antoinette","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/db141441570c9bdee0787662393889dfbc3d6c721d3318f2402846725b7b664e?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/118939","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/37048"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=118939"}],"version-history":[{"count":9,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/118939\/revisions"}],"predecessor-version":[{"id":119055,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/118939\/revisions\/119055"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/118980"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=118939"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=118939"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=118939"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=118939"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}