{"id":118834,"date":"2025-06-13T14:29:08","date_gmt":"2025-06-13T18:29:08","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=118834"},"modified":"2025-06-13T14:29:11","modified_gmt":"2025-06-13T18:29:11","slug":"echos-concernant-le-draft-2025-a-la-wwe-ce-repechage-devrait-lancer-une-nouvelle-tradition-cette-annee","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2025\/06\/13\/echos-concernant-le-draft-2025-a-la-wwe-ce-repechage-devrait-lancer-une-nouvelle-tradition-cette-annee\/","title":{"rendered":"\u00c9chos concernant le Draft 2025 \u00e0 la WWE : Ce rep\u00eachage devrait lancer une nouvelle tradition cette ann\u00e9e !"},"content":{"rendered":"\n<p>La WWE est peut-\u00eatre en train de modifier une tradition de longue date sur le calendrier.<\/p>\n\n\n\n<p>Selon une source, la WWE envisage s\u00e9rieusement de d\u00e9placer le rep\u00eachage de la WWE 2025 de son cr\u00e9neau printanier habituel apr\u00e8s WrestleMania \u00e0 quelque temps apr\u00e8s SummerSlam.<\/p>\n\n\n\n<p>Historiquement, le WWE Draft a eu lieu au printemps pour rafra\u00eechir les rosters de RAW et de SmackDown suite aux retomb\u00e9es de WrestleMania. Mais les conversations internes pointent maintenant vers un \u00e9ventuel calendrier d\u2019automne comme c&rsquo;est aussi \u00e9galement arriv\u00e9 dans le pass\u00e9 pour lancer les nouvelles saisons bien que g\u00e9n\u00e9ralement au printemps. L\u2019id\u00e9e actuelle \u00e9tant d\u2019organiser le Draft en septembre pour co\u00efncider avec les premiers \u00e9pisodes de la saison de la t\u00e9l\u00e9vision WWE.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u00ab\u00a0La derni\u00e8re fois que j\u2019ai entendu parler du Draft WWE, c\u2019est qu\u2019ils ont envisag\u00e9 de le faire apr\u00e8s SummerSlam, tr\u00e8s probablement en lien avec les premiers \u00e9pisodes de la saison en septembre\u00a0\u00bb, indique le rapport.<\/p>\n<\/blockquote>\n\n\n\n<p>L\u2019une des raisons envisag\u00e9es pour le changement d\u2019horaire est le d\u00e9sir de permettre aux intrigues estivales en cours d\u2019atteindre leurs conclusions naturelles. Avec SummerSlam pr\u00e9vu pour le week-end du 2 et 3 ao\u00fbt, les responsables de la WWE verraient cet \u00e9v\u00e9nement comme un point de pivot logique pour un remaniement de l\u2019effectif \u00e0 l\u2019approche de l\u2019automne.<\/p>\n\n\n\n<p>Le rapport note \u00e9galement que les r\u00e9centes convocations \u00e0 NXT et plusieurs sc\u00e9narios \u00e0 long terme en cours ont r\u00e9duit le besoin imm\u00e9diat d\u2019un Draft au printemps, permettant \u00e0 la WWE d\u2019\u00eatre plus flexible avec son timing.<\/p>\n\n\n\n<p>Bien qu\u2019une date officielle n\u2019ait pas encore \u00e9t\u00e9 confirm\u00e9e, on s\u2019attend maintenant \u00e0 ce que le rep\u00eachage de la WWE 2025 serve de coup d\u2019envoi d\u2019automne, s\u2019\u00e9loignant de son placement traditionnel apr\u00e8s WrestleMania.<\/p>\n\n\n\n<p>Nous vous tiendrons au courant au fur et \u00e0 mesure que des informations suppl\u00e9mentaires continueront de faire surface concernant le rep\u00eachage de la WWE 2025.<\/p>\n\n\n\n<p><\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>La WWE est peut-\u00eatre en train de modifier une tradition de longue date sur le calendrier. Selon une source, la WWE envisage s\u00e9rieusement de d\u00e9placer le rep\u00eachage de la WWE 2025 de son cr\u00e9neau printanier habituel apr\u00e8s WrestleMania \u00e0 quelque temps apr\u00e8s SummerSlam. Historiquement, le WWE Draft a eu lieu au printemps pour rafra\u00eechir les&#8230;<\/p>\n","protected":false},"author":665,"featured_media":118920,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"ppma_author":[289],"class_list":["post-118834","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"authors":[{"term_id":289,"user_id":665,"is_guest":0,"slug":"line","display_name":"Line Edmond","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/852de09636413c90cdaa278312f9ea5bc4396768745424755cb63d99a05989d0?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/118834","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/665"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=118834"}],"version-history":[{"count":2,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/118834\/revisions"}],"predecessor-version":[{"id":118921,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/118834\/revisions\/118921"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/118920"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=118834"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=118834"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=118834"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=118834"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}