{"id":118530,"date":"2025-06-04T20:28:00","date_gmt":"2025-06-05T00:28:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=118530"},"modified":"2025-06-07T17:29:47","modified_gmt":"2025-06-07T21:29:47","slug":"resultats-et-video-pour-le-dynamite-special-fyter-fest-2025","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2025\/06\/04\/resultats-et-video-pour-le-dynamite-special-fyter-fest-2025\/","title":{"rendered":"R\u00e9sultats et Vid\u00e9o pour le Dynamite Sp\u00e9cial Fyter Fest 2025 !"},"content":{"rendered":"\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.jdx.info\/lutte\/2025\/06\/04\/reprise-video-pour-le-aew-dynamite-du-4-juin-2025-special-fyter-fest\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Pour voir Fyter Fest, cliquez ici<\/strong><\/a><\/li>\n<\/ul>\n\n\n\n<p>Cette semaine la All Elite Wrestling pr\u00e9sente un show sp\u00e9cial de 4 heures sous le nom de AEW Fyter Fest. AEW Dynamite et AEW Collision sont combin\u00e9s en un soir cette semaine pour ce show sp\u00e9cial, il n&rsquo;y aura pas de AEW Collision ce samedi 7 juin.<\/p>\n\n\n\n<p><strong>AEW Dynamite Denver, Colorado, 4 juin 2025<\/strong><br>Les commentateurs sont Ian Riccaboni, Taz et Excalibur.<\/p>\n\n\n\n<p>&#8211; Le AEW Dynamite sp\u00e9cial Fyter Fest d\u00e9bute avec les commentateurs qui nous souhaitent la bienvenue et on voit les catcheurs arriver dans l&rsquo;ar\u00e9na plus t\u00f4t aujourd&rsquo;hui.<\/p>\n\n\n\n<p>&#8211; Toni Storm arrive dans l&rsquo;ar\u00e9na \u00e0 son tour et d\u00e9clare que Mercedes Mon\u00e9 aura un si\u00e8ge en premi\u00e8re rang\u00e9e pour voir ce qui l&rsquo;attend \u00e0 All In.<\/p>\n\n\n\n<p>&#8211; Tony Schiavone est sur le ring et nous pr\u00e9sente<strong>&nbsp;Will Ospreay<\/strong>. Schiavone dit que quelque chose est arriv\u00e9 mercredi dernier apr\u00e8s Dynamite et il veut avoir ses commentaires. On voit une vid\u00e9o de mercredi dernier de Swerve Strickland et Ospreay qui argumentent au sujet de Adam Page avant qu&rsquo;une bagarre \u00e9clate. Ospreay dit que c&rsquo;est humiliant car il n&rsquo;a jamais voulu se battre avec Strickland, il le connait depuis des ann\u00e9es. Strickland et Page se d\u00e9testent, mais ils ne sont pas les ennemis, l&rsquo;ennemi ici est Jon Moxley. S&rsquo;il peut arriver \u00e0 mettre c\u00f4t\u00e9 leurs diff\u00e9rends pour un soir et prendre le titre mondial AEW ce serait parfait. Moxley a dit qu&rsquo;il d\u00e9teste ce que l&rsquo;AEW est devenu. Ospreay dit que son conseil pour Moxley est de partir. L&rsquo;AEW craint pr\u00e9sentement car Moxley est leur champion mondial. Il a donn\u00e9 sa parole \u00e0 Adam Page et il va s&rsquo;assurer que le titre mondial revienne \u00e0 Page.<\/p>\n\n\n\n<p>Ospreay dit que Strickland et Page ne veulent pas se voir champion mondial. Il ne peut pas laisser Strickland emp\u00eacher Adam Page de battre Jon Moxley. Alors s&rsquo;il doit \u00eatre celui qui devra arr\u00eater Strickland, il le fera.\u00a0Il adore Swerve Strickland, il prendrait une balle pour Strickland, mais avant toute chose il prendrait une balle pour la AEW. Alors la semaine prochaine \u00e0 Summer Blockbuster il invite Strickland pour un match\u00a0! Lio Rush et Action Andretti arrivent sur le ring. Ospreay demande qui sont ces types. Lio Rush dit qu&rsquo;il aime bien Ospreay, les fans aussi aiment Ospreay. Mais il connait bien une chose sur les britanniques, ils aiment bien parler. Rush dit qu&rsquo;ils reviennent d&rsquo;un vol de 15 heures du Japon et il aimerait prouver quelque chose. Il pense vraiment que la pire chose de l&rsquo;AEW est l&rsquo;idiot d&rsquo;Ospreay. Ospreay dit qu&rsquo;il adorerait aider Rush \u00e0 faire sortir sa col\u00e8re. Ospreay dit que c&rsquo;est sold out, il a son faux bronzage, alors il est pr\u00eat pour le match. Ils vont se voir ce soir sur le ring !<\/p>\n\n\n\n<p>&#8211; En vid\u00e9o, Mark Briscoe dit qu&rsquo;il a pris une d\u00e9faite dans un Trios Match par un Bulldog Choke de Jon Moxley. Son fils lui a demand\u00e9 s&rsquo;il a abandonn\u00e9. Briscoe dit qu&rsquo;il n&rsquo;a pas abandonn\u00e9, mais voil\u00e0 que son fils doute en lui. Alors il veut affronter Jon Moxley \u00e0 Dynamite pour enlever ces doutes.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>Jon Moxley\u00a0<em>acc de Wheeler Yuta et Marina Shafir<\/em>\u00a0vs Mark Briscoe<\/strong><\/p>\n\n\n\n<p>\u00c0 la fin du combat, Briscoe roule en bas du ring, Moxley parle avec l&rsquo;arbitre et Yuta en profite pour pousser Briscoe contre la marche d&rsquo;acier. Shafir pousse Briscoe sur le ring. Briscoe surprend Moxley avec un Death Valley Driver et enchaine avec un Jay Driller ! Briscoe le couvre, mais Moxley r\u00e9siste \u00e0 deux. Briscoe prend Moxley sur ses \u00e9paules, mais Moxley le repousse au sol et lui fait un Stomp. Moxley enchaine avec son Bulldog Choke, Briscoe veut r\u00e9sister, mais Moxley poursuit la soumission et l&rsquo;arbitre arr\u00eate le match comme Briscoe ne r\u00e9pond plus.<\/p>\n\n\n\n<p><em>Gagnant : Jon Moxley\u00a0<\/em><\/p>\n\n\n\n<p>&#8211; On pr\u00e9sente une vid\u00e9o sur Mistico de la CMLL puisque l&rsquo;AEW pr\u00e9pare leur show Grand Slam Mexique. Il sera \u00e0 Dynamite la semaine prochaine.<\/p>\n\n\n\n<p>&#8211; Mercedes Mon\u00e9 arrive pour prendre place avec les commentateurs.<\/p>\n\n\n\n<p>&#8211; De retour suite \u00e0 la pause, Mercedes Mon\u00e9 se fait amener du vin et un steak pour regarder le match.<\/p>\n\n\n\n<p><strong>Toni Storm et Mina Shirakawa vs Julia Hart et Skye Blue<\/strong><\/p>\n\n\n\n<p>\u00c0 la fin du combat, Storm et Shirakawa posent ensemble sur le ring pour faire un Hip Attack aux adversaires. Storm enchaine avec un Cross Face Chicken Wing pour faire abandonner Blue.<\/p>\n\n\n\n<p><em>Gagnantes : Toni Storm et Mina Shirakawa<\/em><\/p>\n\n\n\n<p>&#8211; En coulisses, Lexie demande \u00e0 Will Ospreay ses commentaires sur son match contre Strickland, mais&nbsp;<strong>MJF<\/strong>&nbsp;arrive. MJF dit qu&rsquo;il vient ici pour l&rsquo;aider. Ospreay doit rester loin du cowboy et de Strickland. Cette histoire va mal se termienr pour Ospreay comme il n&rsquo;est pas capable de battre Adam Page, donc m\u00eame si Page gagne ce n&rsquo;est pas bon. Ospreay dit que c&rsquo;est int\u00e9ressant, mais il a un match \u00e0 pr\u00e9parer. Il comprend ce qui se passe : MJF ne veut pas voir Page gagner comme il n&rsquo;a aucune chance de battre Page. MJF demande comment va son enfant Harry. Ospreay attrape MJF par le cou, mais le Hurt Syndicate arrive pour le calmer. MVP dit qu&rsquo;ils ont du business \u00e0 faire ailleurs, mais bonne chance \u00e0 Ospreay pour son match ce soir.<\/p>\n\n\n\n<p>&#8211; De retour, le\u00a0<strong>Hurt Syndicate<\/strong>\u00a0arrive sur le ring. <strong>MVP <\/strong>dit qu&rsquo;ils ont une annonce officielle \u00e0 faire pour le Hurt Syndicate. Mais avant, il doit souligner le fait que Bobby Lashley vivait ici \u00e0 Denver. Mais maintenant que Lashley vit au Texas, quelle est son opinion sur Denver ? Lashley fait un pouce vers le bas. MVP dit que c&rsquo;est l&rsquo;AEW, o\u00f9 les meilleurs font du catch. Et il est sur le ring avec la meilleure \u00e9quipe de l&rsquo;histoire. On peut envoyer n&rsquo;importe quelle \u00e9quipe de n&rsquo;importe o\u00f9 : personne ne peut leur enlever les titres par \u00e9quipe. Si c&rsquo;est l&rsquo;endroit o\u00f9 les meilleurs font du catch, o\u00f9 sont les meilleures \u00e9quipes ? C&rsquo;est dans notre imagination car il n&rsquo;y a personne capable de battre le Hurt Syndicate pour les titres par \u00e9quipe.<\/p>\n\n\n\n<p>MJF dit qu&rsquo;il veut l&rsquo;or comme ses amis Lashley et Benjamin. Il veut retrouver son titre mondial AEW. Alors comme les idiots en coulisses, il devra recommencer \u00e0 catcher un peu. Ce qui l&rsquo;am\u00e8ne au Mexique. Apparemment le meilleur du Mexique est Mistico. Son pays pense que Mistico est le meilleur catcheur au monde, mais c&rsquo;est faux car c&rsquo;est lui le meilleur. Le meilleur catcheur ne vient pas du Mexique, mais bien du seul pays important, les \u00c9tats-Unis. Il a sold out l&rsquo;ar\u00e9na de Mistico au Mexique, le plus jeune \u00e0 le faire. Et pourquoi il a \u00e9t\u00e9 capable de le faire ? Car au contraire de nous les pauvres, il est une m\u00e9ga star. Si on ne le croit pas, Happy Gilmore arrive.\u00a0 MJF ajoute que la semaine prochaine il va regarder le match de Mistico, et s&rsquo;il pense que Mistico le m\u00e9rite, il va le laisser l&rsquo;affronter \u00e0 Grand Slam Mexique.<\/p>\n\n\n\n<p>La musique de Mike Bailey se lance et il arrive avec Kevin Knight et Komander sur la sc\u00e8ne. MVP demande c&rsquo;est quoi \u00e7a. Komander dit \u00e0 MJF qu&rsquo;il a manqu\u00e9 de respect \u00e0 Mistico, la Lucha Libre et lui. Tout ce qui dit MJF est de la merde. Cet idiot doit respecter la Lucha Libre. Mike Bailey dit que le Hurt Syndicate veut affronter les meilleurs, voici un groupe de tueurs internationaux. MJF commence \u00e0 rigoler. Kevin Knight dit qu&rsquo;on dirait qu&rsquo;ils n&rsquo;ont pas compris.\u00a0Ils veulent se battre ce soir avec le Hurt Syndicate ! MVP dit que le match n&rsquo;aura pas lieu ce soir comme ils ne l&rsquo;ont pas m\u00e9rit\u00e9. S&rsquo;ils veulent une chance d&rsquo;affronter les champions par \u00e9quipe, ils devraient les impressionner et gagner ce match.<\/p>\n\n\n\n<p><strong>Mike Bailey, Kevin Knight et Komander vs Rush, Dralistico et Beast Mortos<\/strong><\/p>\n\n\n\n<p>\u00c0 la fin du combat, Bailey fait son Double Knee \u00e0 Mortos et le couvre, mais Rush brise le compte. Knight intervient et chasse Rush du ring avec un Drop Kick. Mortos fait une Clothesline \u00e0 Bailey. Bailey arrive \u00e0 bloquer une prise et porte un coup de pied \u00e0 Mortos. Knight prend la tag. Bailey fait son Round Kick \u00e0 Mortos. Komander compl\u00e8te avec un saut en marchant sur les cordres \u00e0 Rush et Dralistico en ringside. Knight enchaine avec un Frog Splash \u00e0 Mortos pour le compte de trois.<\/p>\n\n\n\n<p><em>Gagnants : Mike Bailey, Kevin Knight et Komander<\/em><\/p>\n\n\n\n<p>Apr\u00e8s le combat, le Hurt Syndicate arrive sur la sc\u00e8ne. MVP dit qu&rsquo;il est impressionn\u00e9 pour leur match. Il est tellement impressionn\u00e9 qu&rsquo;ils ont gagn\u00e9 le prix.\u00a0La semaine prochaine ils pourront affronter Benjamin, Lashley et MJF dans un Trios Match. Et en bonus ils auront une preview de cette racl\u00e9e maintenant. Bobby Lashley et Shelton Benjamin vont sur le ring pour se battre, mais Knight et Bailey repoussent les deux avec des coups de pieds. MJF entre sur le ring, mais Komander le repousse directement avec un Drop Kick. Ils se lancent en Cross Body les trois sur le Hurt Syndicate en ringside !<\/p>\n\n\n\n<p>&#8211; En coulisses, Alicia est avec Adam Cole et Daniel Garcia. Adam Cole dit qu&rsquo;ils ont eu leur bataille par le pass\u00e9, mais ils ont gagn\u00e9 un respect mutuel. Et plus important, ils ne peuvent pas endurer la Famille Don Callis. C&rsquo;est le moment de leur donner une le\u00e7on de respect. Garcia approuve.<\/p>\n\n\n\n<p>&#8211; De retour, en coulisses, Lexie souhaite la bienvenue \u00e0 Christian Cage pour son retour. Christian Cage dit que Nick Wayne a tr\u00e8s bien perform\u00e9 au Best of Super Juniors, mais il n&rsquo;a pas gagn\u00e9 le tournoi. Mais il a eu un planning charg\u00e9, il a fait 14 matchs en 22 jours, mais aucune excuse. Ce genre d&rsquo;horaire devrait venir avec un cong\u00e9 pour n&rsquo;importe qui, mais Nick Wayne n&rsquo;est pas n&rsquo;importe qui. Nick Wayne est le fils de Christian Cage, le champion ROH TV, alors il va d\u00e9fendre son titre ce soir.\u00a0<\/p>\n\n\n\n<p>Nick Wayne conclu en disant que Cage l&rsquo;a fait avant son d\u00e9part et c&rsquo;\u00e9tait facile, alors aucun probl\u00e8me. Cage dit que ce sera diff\u00e9rent, car ce soir Wayne va d\u00e9fendre son titre dans un 4-Way Match\u00a0!<\/p>\n\n\n\n<p>&#8211; Max Caster est sur le ring et dit qu&rsquo;il a une p\u00e9tition dans ses mains. Une p\u00e9tition pour confirmer qu&rsquo;il est le meilleur catcheur au monde et il ne pense pas que Monsieur l&rsquo;arbitre l&rsquo;a sign\u00e9. Caster demande \u00e0 l&rsquo;arbitre d&rsquo;ajouter son nom. Caster commence \u00e0 faire chanter les fans disant qu&rsquo;il est le meilleur catcheur. Caster dit que ce soir c&rsquo;est le retour du Open Challenge de cinq minutes. Alors qui va venir essayer de survivre contre le meilleur catcheur ? Hobbs arrive sur le ring.<\/p>\n\n\n\n<p><strong>Max Caster vs Powerhouse Hobbs<\/strong><\/p>\n\n\n\n<p>Hobbs attrape Caster pour lui faire une Powerbomb en moins de deux minutes pour le compte de trois.<\/p>\n\n\n\n<p><em>Gagnant : Powerhouse Hobbs<\/em><\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>AEW International Championship &#8211; 4-Way Match<\/strong><\/p>\n\n\n\n<p><strong>Kenny Omega \u00a9 vs Brody King vs Mascara Dorada vs Claudio Castagnoli<\/strong><\/p>\n\n\n\n<p>\u00c0 la fin du combat, Dorada se lance sur Castagnoli en ringside d&rsquo;un c\u00f4t\u00e9 et de l&rsquo;autre c\u00f4t\u00e9 sur King. Dorada remonte sur le ring et veut faire un Rana \u00e0 Omega, mais Omega le bloque et lui fait un One Winged Angel pour le compte de trois.<\/p>\n\n\n\n<p><em>Gagnant : Kenny Omega<\/em><\/p>\n\n\n\n<p>&#8211; Apr\u00e8s le combat, Omega c\u00e9l\u00e8bre sa victoire, mais la musique de<strong>&nbsp;Kazuchika Okada<\/strong>&nbsp;se lance ! Okada arrive sur le ring et fait un face \u00e0 face avec Omega. Les deux se bousculent. Omega et Okada commencent \u00e0 \u00e9changer des coups, mais Okada prend l&rsquo;avantage. Okada veut faire un Rainmaker, mais Omega le renverse pour son finisher, mais Okada le repousse et prend la fuite.<\/p>\n\n\n\n<p>&#8211; En coulisses, Ricochet dit que ce soir on a la chance d&rsquo;avoir 4 heures de AEW. On aura la chance de voir beaucoup de catcheurs, mais pas lui. Il ne va pas combattre dans cette ville nulle. Mais il va surveiller tous ces catcheurs pour bien les observer et continuer sa qu\u00eate pour devenir champion.<\/p>\n\n\n\n<p>&#8211; Nigel McGuinness et Tony Schiavone sont les commentateurs pour la seconde partie du show.<\/p>\n\n\n\n<p><strong>Will Ospreay vs Lio Rush&nbsp;<em>accompagn\u00e9 d&rsquo;Action Andretti<\/em><\/strong><\/p>\n\n\n\n<p>\u00c0 la fin du combat, Rush se lance du coin, mais Ospreay le bloque avec un Cutter. Ospreay enchaine avec son Springboard Cutter et le couvre, mais il r\u00e9siste. Ospreay se pr\u00e9pare pour son Hidden Blade, mais Andretti lui attrape la jambe. Ospreay lance Rush sur Andretti en ringside et se lance sur les deux en bas du ring ! Ospreay ram\u00e8ne Rush sur le ring et le prend une prise, mais Rush le bloque avec un DDT. Rush enchaine avec un Frog Splash et le couvre, mais il r\u00e9siste. Andretti passe une chaine d&rsquo;acier \u00e0 Rush, mais l&rsquo;arbitre le voit et lui enl\u00e8ve la chaise. Ospreay en profite pour faire un Styles Clash \u00e0 Rush pour le compte de trois.<\/p>\n\n\n\n<p><em>Gagnant : Will Ospreay<\/em><\/p>\n\n\n\n<p>&#8211; Apr\u00e8s le combat, Ospreay c\u00e9l\u00e8bre sa victoire, mais Andretti l&rsquo;attaque dans le dos ! Andretti et Rush font un Neck Breaker \u00e0 deux sur Ospreay. La musique d&rsquo;Adam Page se lance et il arrive sur le ring, mais Rush et Andretti prennent la fuite. Ospreay remercie Page et quitte le ring.<\/p>\n\n\n\n<p>&#8211; Adam Hangman Page prend le micro, et dit que si Will Ospreay va surveiller ses arri\u00e8res, lui aussi va le faire pour Ospreay.\u00a0Mais il veut clarifier une chose. Il est capable de se d\u00e9brouiller seul et il n&rsquo;a pas besoin de Swerve Strickland. Il ne veut pas de l&rsquo;aide de l&rsquo;homme qui met de c\u00f4t\u00e9 la s\u00e9curit\u00e9 pour sa propre gloire. Page dit qu&rsquo;il ne va jamais accepter et il n&rsquo;aura jamais besoin d&rsquo;aide venant de Swerve Strickland. Mais il va battre Jon Moxley \u00e0 All In et soulever le championnat pour nous tous. All In est une soir\u00e9e pour nous tous et ce sera son moment ! Jon Moxley arrive sur le ring, les deux font un face \u00e0 face. Wheeler Yuta, Marina Shafir et Claudio Castagnoli arrivent en ringside pour encercler le ring, mais Will Ospreay revient avec des chaises. Moxley quitte le ring et fait signe \u00e0 ses partenaires de le suivre.<\/p>\n\n\n\n<p>&#8211; En coulisses, Lexie est avec la Famille Don Callis pour avoir leur r\u00e9ponse. Don Callis dit qu&rsquo;il a d\u00e9j\u00e0 accept\u00e9 le challenge d&rsquo;Adam Cole. Mais ce n&rsquo;est pas termin\u00e9, car Bandido lui a co\u00fbt\u00e9 beaucoup trop d&rsquo;argent. Alors Bandido doit s&rsquo;allier aux Outrunners et ils vont les affronter. Il a recrut\u00e9 Hechicero pour l&rsquo;\u00e9v\u00e9nement. Hechicero dit qu&rsquo;il est dans la Famille. Callis dit qu&rsquo;ils vont botter des culs ce soir.<\/p>\n\n\n\n<p><strong>Atlantis Jr et Templario vs FTR\u00a0<em>(Cash Wheeler et Dax Harwood) acc  de Stokely Hathaway<\/em><\/strong><\/p>\n\n\n\n<p>\u00c0 la fin du combat, FTR veut faire un Shatter Machine, mais Atlantis bloque la prise avec un Superkick. Templario fait un Roll Up \u00e0 Wheeler, mais il r\u00e9siste. Ils sont des Superkicks \u00e0 Wheeler. Atlantis monte sur le coin, mais Harwood le repousse au sol. Templario frappe Harwood pour le repousser. Templario veut faire une Suplex \u00e0 Wheeler, mais Harwood lui attrape un pied pour le faire chuter et Wheeler le couvre pour la victoire.<\/p>\n\n\n\n<p><em>Gagnants : FTR<\/em><\/p>\n\n\n\n<p>&#8211; Apr\u00e8s le combat, Stokely Hathaway prend le micro. Hathaway dit qu&rsquo;il a quelque chose d&rsquo;important \u00e0 nous dire. FTR a encore gagn\u00e9, l&rsquo;\u00e9quipe avec le plus de victoires de l&rsquo;histoire de l&rsquo;AEW. C&rsquo;est l&rsquo;\u00e9quipe avec le plus de victoires. Peu importe d&rsquo;o\u00f9 on vient, tout le monde tombe face \u00e0 FTR. Harwood veut parler, mais il est trop hu\u00e9. Harwood dit que Denver vient de perdre sa chance de l&rsquo;entendre. FTR quitte.<\/p>\n\n\n\n<p>&#8211; De retour, on pr\u00e9sente une vid\u00e9o sur les d\u00e9buts de Thekla.<\/p>\n\n\n\n<p><strong>Konosuke Takeshita, Hechicero et Kyle Fletcher&nbsp;<em>accompagn\u00e9 de Don Callis<\/em>&nbsp;vs Outrunners<em>&nbsp;(Truth Magnum et Turbo Floyd)<\/em>&nbsp;et Bandido<\/strong><\/p>\n\n\n\n<p>\u00c0 la fin du combat, Fletcher et Takeshita font des prises sur les Outrunners et terminent avec des Brain Busters pour le compte de trois.<\/p>\n\n\n\n<p><strong><em>Gagnants :\u00a0Konosuke Takeshita, Hechicero et Kyle Fletcher<\/em><\/strong><\/p>\n\n\n\n<p>&#8211; En coulisses, Penelope Ford et Megan Bayne attaquent Anna Jay. Elles am\u00e8nent Anna Jay sur la sc\u00e8ne pour pr\u00e9parer une prise, mais\u00a0Tay Melo fait son retour pour les stopper. La s\u00e9curit\u00e9 arrive pour s\u00e9parer tout le monde.<\/p>\n\n\n\n<p>&#8211; De retour, en coulisses, on retrouve Anthony Bowens et Billy Gunn. Bowens dit que ce mois-ci est le mois officiel Pride (de la fiert\u00e9) dans l&rsquo;univers du catch. Il a aussi pour id\u00e9e d&rsquo;affronter Kyle Fletcher pour Summer Blockbuster, c&rsquo;est une bonne id\u00e9e pour lancer les festivit\u00e9s.<\/p>\n\n\n\n<p>&#8211; Ricochet prend place avec les commentateurs pour le prochain match.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>ROH World Television Championship &#8211; 4-Way Match<\/strong><\/p>\n\n\n\n<p><strong>Sammy Guevara vs Lee Johnson\u00a0<em>accompagn\u00e9 de Blake Christian<\/em>\u00a0vs AR Fox vs Nick Wayne \u00a9\u00a0<em>accompagn\u00e9 de Christian Cage et Maman Wayne<\/em><\/strong><\/p>\n\n\n\n<p>\u00c0 la fin du combat, Fox se lance en bas du ring sur les trois adversaires. Fox ram\u00e8ne Wayne sur le ring et monte sur le coin pour un Swenton, mais Wayne le bloque avec ses genoux. Wayne enchaine avec un Superkick et un Brain Buster pour le compte de trois.<\/p>\n\n\n\n<p><em>Gagnant : Nick Wayne<\/em><\/p>\n\n\n\n<p><strong>Thekla vs Lady Frost<\/strong><\/p>\n\n\n\n<p>\u00c0 la fin du combat,&nbsp;Frost charge Thekla, mais Thekla la cogne. Thekla enchaine avec un Spear et un Death Trap pour faire taper Frost.<\/p>\n\n\n\n<p><em>Gagnante : Thekla\u00a0<\/em><\/p>\n\n\n\n<p>&#8211; Apr\u00e8s le combat, Thekla c\u00e9l\u00e8bre sa victoire et reprend sa soumission sur Frost. Queen Aminata arrive sur le ring et Thekla prend la fuite.<\/p>\n\n\n\n<p>&#8211; De retour, en coulisses, Queen Aminata dit qu&rsquo;\u00e0 chaque fois qu&rsquo;une nouvelle arrive \u00e0 l&rsquo;AEW elle veut se faire un nom. Elle est la seule reine africaine ici. En Afrique elle \u00e9crase les araign\u00e9es. Alors la semaine prochaine elle propose Aminata contre Thekla.<\/p>\n\n\n\n<p>&#8211; C&rsquo;est le moment de la grande annonce de Tony Khan.\u00a0Tony Schiavone fait l&rsquo;annonce en disant que Kenny Omega va affronter Kazuchika Okada dans un \u00a0\u00bbWinner Takes All\u00a0\u00bb \u00e0 AEW All In Texas.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>8-Man Tag Team Match<\/strong><\/p>\n\n\n\n<p><strong>Rocky Romero, Trent Beretta, Josh Alexander et Lance Archer vs Daniel Garcia, Roderick Strong, Kyle O&rsquo;Reilly et Adam Cole<\/strong><\/p>\n\n\n\n<p>\u00c0 la fin du combat, Cole fait un Superkick \u00e0 Romero qui le charge. Archer veut intervenir, mais Cole lui fait un Superkick. Cole fait un BOOM \u00e0 Romero pour le compte de trois.<\/p>\n\n\n\n<p><em>Gagnants : Daniel Garcia, Roderick Strong, Kyle O&rsquo;Reilly et Adam Cole<\/em><\/p>\n\n\n\n<p>&#8211; Le show sw termine avec une c\u00e9l\u00e9bration des gagnants.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p class=\"has-text-align-center has-medium-font-size\"><a href=\"https:\/\/www.jdx.info\/lutte\/2025\/06\/04\/reprise-video-pour-le-aew-dynamite-du-4-juin-2025-special-fyter-fest\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Pour voir Fyter Fest, cliquez ici<\/strong><\/a><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-info-lutte wp-block-embed-info-lutte\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"HKofyr4WNb\"><a href=\"https:\/\/www.jdx.info\/lutte\/2025\/06\/04\/reprise-video-pour-le-aew-dynamite-du-4-juin-2025-special-fyter-fest\/\">Reprise Vid\u00e9o pour le AEW Dynamite du 4 Juin 2025 Sp\u00e9cial Fyter Fest !<\/a><\/blockquote><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"\u00ab\u00a0Reprise Vid\u00e9o pour le AEW Dynamite du 4 Juin 2025 Sp\u00e9cial Fyter Fest !\u00a0\u00bb &#8212; Info-Lutte\" src=\"https:\/\/www.jdx.info\/lutte\/2025\/06\/04\/reprise-video-pour-le-aew-dynamite-du-4-juin-2025-special-fyter-fest\/embed\/#?secret=Swju0tgp8R#?secret=HKofyr4WNb\" data-secret=\"HKofyr4WNb\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Cette semaine la All Elite Wrestling pr\u00e9sente un show sp\u00e9cial de 4 heures sous le nom de AEW Fyter Fest. AEW Dynamite et AEW Collision sont combin\u00e9s en un soir cette semaine pour ce show sp\u00e9cial, il n&rsquo;y aura pas de AEW Collision ce samedi 7 juin. AEW Dynamite Denver, Colorado, 4 juin 2025Les commentateurs&#8230;<\/p>\n","protected":false},"author":37048,"featured_media":118531,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38,24,50,30,21],"tags":[],"ppma_author":[297],"class_list":["post-118530","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aew","category-aew-impact-njpw-roh","category-dynamite","category-ex-wwe","category-resultats"],"authors":[{"term_id":297,"user_id":37048,"is_guest":0,"slug":"mattante","display_name":"Mattias Antoinette","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/db141441570c9bdee0787662393889dfbc3d6c721d3318f2402846725b7b664e?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/118530","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/37048"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=118530"}],"version-history":[{"count":7,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/118530\/revisions"}],"predecessor-version":[{"id":118542,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/118530\/revisions\/118542"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/118531"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=118530"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=118530"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=118530"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=118530"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}