{"id":117791,"date":"2025-05-20T13:11:00","date_gmt":"2025-05-20T17:11:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=117791"},"modified":"2025-05-20T13:24:50","modified_gmt":"2025-05-20T17:24:50","slug":"deux-autres-qualifies-pour-le-money-in-the-bank-roxanne-perez-signe-a-raw-et-gagne-zoey-stark-blessee-et-plus","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2025\/05\/20\/deux-autres-qualifies-pour-le-money-in-the-bank-roxanne-perez-signe-a-raw-et-gagne-zoey-stark-blessee-et-plus\/","title":{"rendered":"Deux Autres Qualifi\u00e9s pour le Money in the Bank, Roxanne Perez signe \u00e0 RAW et gagne, Zoey Stark bless\u00e9e, et plus !"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">&#8211; Les matchs de qualification pour les matchs d&rsquo;\u00e9chelles au Money in the Bank, ont continu\u00e9\u00a0lors de WWE RAW du 19 mai 2025. Durant le show rouge, deux matchs de qualification f\u00e9minins ont eu lieu dans la ville de Greenbay en Caroline du Sud. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Premi\u00e8rement,\u00a0<strong>Roxanne Perez<\/strong> la nouvelle recrue de RAW, a remport\u00e9 son match\u00a0face \u00e0 Becky Lynch et Natalya. \u00c0 la fin de ce match, Lyra Valkyria est intervenue en d\u00e9faveur de Becky Lynch. Perez, nouvelle membre du roster de RAW, a profit\u00e9 de la situation pour l&#8217;emporter.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pour le second match, c&rsquo;est<strong>\u00a0Rhea Ripley <\/strong>qui a battu et Kairi Sane et Zoey Stark<strong>\u00a0<\/strong>pour obtenir la troisi\u00e8me place dans le Money in the Bank f\u00e9minin. Roxanne Perez et Rhea Ripley rejoignent ainsi Alexa Bliss. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Deux autres places sont encore disponibles.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8211; Comme malheureusement mentionn\u00e9 ci-haut,\u00a0<strong>Zoey Stark<\/strong> a subi une blessure grave \u00e0 un genou\u00a0durant ce match et a d\u00fb rejoindre les coulisses avec l&rsquo;aide du soigneur sportif. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pour info, le genou de Zoey Stark s&rsquo;est mal repli\u00e9 et elle n&rsquo;a pas r\u00e9ussi \u00e0 se relever. Le soigneur sportif de la WWE est rapidement intervenu pour la relever et l&rsquo;amener dans les coulisses afin de lui donner les soins appropri\u00e9s. Un m\u00e9decin sur place l&rsquo;a examiner en coulisse mais nous n&rsquo;avons pas plus de d\u00e9tails en ce moment. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8211; Si vendredi dernier lors SmackDown, on apprenait que Giulia rejoignait officiellement le roster de Nick Aldis. Maintenant, c&rsquo;est \u00e0 Roxanne Perez de rejoindre le roster principal g\u00e9r\u00e9 par Adam Pearce.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Juste avant RAW du 19 mai 2025, le GM de RAW a eu une rencontre avec <strong>Roxanne Perez<\/strong> afin de lui offrir un contrat dans son show. Roxanne Perez a imm\u00e9diatement sign\u00e9 le contrat en disant qu&rsquo;elle a h\u00e2te de montrer \u00e0 tout le monde de RAW pourquoi elle est la \u00a0\u00bbprodige\u00a0\u00bb.<\/p>\n\n\n\n<center><blockquote class=\"twitter-tweet\" data-media-max-width=\"560\"><p lang=\"en\" dir=\"ltr\">.<a href=\"https:\/\/twitter.com\/ScrapDaddyAP?ref_src=twsrc%5Etfw\">@ScrapDaddyAP<\/a> MAKES IT OFFICIAL!<a href=\"https:\/\/twitter.com\/roxanne_wwe?ref_src=twsrc%5Etfw\">@roxanne_wwe<\/a> has joined the <a href=\"https:\/\/twitter.com\/hashtag\/WWERaw?src=hash&amp;ref_src=twsrc%5Etfw\">#WWERaw<\/a> roster! Monday nights just got even better!  <a href=\"https:\/\/t.co\/6GAhv2rkx5\">pic.twitter.com\/6GAhv2rkx5<\/a><\/p>&mdash; WWE (@WWE) <a href=\"https:\/\/twitter.com\/WWE\/status\/1924602841429114950?ref_src=twsrc%5Etfw\">May 19, 2025<\/a><\/blockquote> <script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/center>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>&#8211; Les matchs de qualification pour les matchs d&rsquo;\u00e9chelles au Money in the Bank, ont continu\u00e9\u00a0lors de WWE RAW du 19 mai 2025. Durant le show rouge, deux matchs de qualification f\u00e9minins ont eu lieu dans la ville de Greenbay en Caroline du Sud. Premi\u00e8rement,\u00a0Roxanne Perez la nouvelle recrue de RAW, a remport\u00e9 son match\u00a0face&#8230;<\/p>\n","protected":false},"author":609,"featured_media":117793,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[46,4,43,23],"tags":[],"ppma_author":[295],"class_list":["post-117791","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-money-in-the-bank","category-news","category-raw-wwe","category-wwe"],"authors":[{"term_id":295,"user_id":609,"is_guest":0,"slug":"rodrigo","display_name":"Rodrigue Tousignant","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/51fe284bb6dbe8a6b4c2bf998ad658f4a9cd24b7e58f15ec85888070c7340ce6?s=96&d=mm&r=g","author_category":"","first_name":"Rodrigue","last_name":"Tousignant","user_url":"http:\/\/Info-Lutte.com","job_title":"","description":"Il me fait plaisir de venir aider Jason qui tien Info-Lutte \u00e0 bout de bras depuis presque 20 ans. \r\n\r\nBien que je me suis pas journaliste cela a toujours \u00e9t\u00e9 mon r\u00eave donc je ferai de mon mieux avec la bonne formation qu'il me donne pour vous donner le meilleur des informations du catch."}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/117791","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/609"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=117791"}],"version-history":[{"count":1,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/117791\/revisions"}],"predecessor-version":[{"id":117794,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/117791\/revisions\/117794"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/117793"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=117791"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=117791"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=117791"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=117791"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}