{"id":117451,"date":"2025-05-13T20:12:00","date_gmt":"2025-05-14T00:12:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=117451"},"modified":"2025-05-16T14:23:43","modified_gmt":"2025-05-16T18:23:43","slug":"resultats-et-video-pour-le-wwe-nxt-du-13-mai-2025","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2025\/05\/13\/resultats-et-video-pour-le-wwe-nxt-du-13-mai-2025\/","title":{"rendered":"R\u00e9sultats et Vid\u00e9o pour le WWE NXT du 13 Mai 2025 !"},"content":{"rendered":"\n<ul class=\"wp-block-list\">\n<li><strong><a href=\"https:\/\/www.jdx.info\/lutte\/2025\/05\/13\/reprise-pour-le-wwe-nxt-du-13-mai-2025\/\" target=\"_blank\" rel=\"noreferrer noopener\">Pour voir NXT, cliquez ici.<\/a><\/strong><\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>WWE NXT Orlando, Floride, 13 mai 2025 <\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8211; Le WWE NXT, d\u00e9bute sur une vid\u00e9o\u00a0des \u00e9v\u00e9nements de mardi dernier\u00a0lorsque Myles Borne a remport\u00e9 la Battle Royal pour devenir aspirant face \u00e0 Oba Femi.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8211; Les commentateurs nous souhaitent la bienvenue et le No Quarter Catch Crew arrive sur le ring.&nbsp;<strong>Myles Borne<\/strong>&nbsp;dit que mardi dernier il a pris le monde par surprise. Il \u00e9tait le dernier homme debout face \u00e0 des catcheurs de NXT, Evolve et ailleurs, et maintenant il va \u00e0 Battleground. Il n&rsquo;\u00e9tait surement pas notre premier choix, mais c&rsquo;est OK, il est habitu\u00e9. Il fait face \u00e0 un handicap, il est partiellement sourd. \u00c7a affecte la fa\u00e7on qu&rsquo;il s&rsquo;exprime.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Borne dit que mardi dernier lorsqu&rsquo;il a \u00e9limin\u00e9 Ethan Page et Shawn Spears, il a entendu les fans devenir fou. Il ne veut pas \u00eatre seulement reconnu comme le gars sourd. Il veut \u00eatre jug\u00e9 par ses habilit\u00e9s et non par son handicap. Tout ceux avec un handicap veulent \u00eatre jug\u00e9s ainsi. \u00c0 Battleground il est le sous-estim\u00e9, mais il va se battre pour tous les enfants dans la m\u00eame situation que lui et prouver que tout le monde peut atteindre le succ\u00e8s. Le 25 mai il est pr\u00eat \u00e0 surprendre le monde entier une nouvelle fois. Il sera notre nouveau champion de NXT.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La musique de Ethan Page se lance et il arrive. Ethan Page dit que \u00e7a suffit cette histoire sentimentale. Borne est peut-\u00eatre pire que Ricky Saints avec son histoire. Il a donn\u00e9 une dose de r\u00e9alit\u00e9 \u00e0 Saints et il va lui donner la m\u00eame. Myles Borne a gagn\u00e9 un Battle Royal sur un coup de chance. La foule chante que Borne ne peut pas entendre. Page dit que les fans ont surement raison et il d\u00e9\u00e7u de ne voir aucun sous-titre ici. Il va le dire lentement pour que Borne puisse lire ses l\u00e8vres, Borne ne peut pas battre Femi. Borne n&rsquo;est pas de son niveau ou du niveau de Femi. Borne veut prouver qu&rsquo;il m\u00e9rite cette chance pour le titre, alors il devrait mettre sa chance d&rsquo;aspirant contre lui ce soir.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Charlie Dempsey dit que c&rsquo;est une le\u00e7on d&rsquo;apprentissage pour Myles Borne.\u00a0Quoi de meilleur que d&rsquo;affronter un ancien champion de NXT ? Ce sera le combat parfait pour Borne et il pourrait faire taire ceux qui doutent en lui. Borne dit que Dempsey a raison, il accepte.\u00a0Ava arrive sur la sc\u00e8ne et invite tout le monde \u00e0 r\u00e9fl\u00e9chir. Ava dit qu&rsquo;elle ne sait pas si c&rsquo;est la bonne chose \u00e0 faire pour Borne, mais elle voit que Borne veut se prouver ce soir. Alors elle va l&rsquo;accepter, le match Page contre Borne aura lieu plus tard car Dempsey doit affronter Femi maintenant.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Charlie Dempsey&nbsp;<em>accompagn\u00e9 du No Quarter Catch Crew<\/em>&nbsp;vs Oba Femi<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c0 la fin du combat, Femi charge Dempsey contre le coin \u00e0 plusieurs reprises. Femi enchaine avec un Blue Thunder Bomb. Femi termine avec sa Powerbomb pour le compte de trois sur Dempsey.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Gagnant : Oba Femi<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8211; En coulisses, Karmen Petrovic et Thea Hail discutent ensemble. Elles doivent Tatum Paxley qui est en col\u00e8re et casse ses jouets de poup\u00e9es.\u00a0Paxley dit qu&rsquo;elle n&rsquo;a plus rien, elle a tout perdu et elle perdu ses amies. Paxley dit que Thea Hail va aussi se faire quitter par ses amies.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8211; En coulisses, Ricky Saints retrouve Ethan Page. Saints dit que maintenant Page doit aussi ruiner le moment de Myles Borne. On dirait que Page aime vraiment profiter du moment des autres. Page dit que c&rsquo;est son plaisir personnel voler le moment des autres. Il y a un match \u00e0 NXT Battleground qui a besoin de lui et ensuite ils pourront ramener l&rsquo;Ego \u00e0 NXT et Saints pourra \u00eatre son bon second.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8211; En vid\u00e9o avant le match, Wes Lee d\u00e9clare que c&rsquo;est le moment de planter le dernier clou dans le cerceuil de D&rsquo;Angelo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Tony D&rsquo;Angelo vs Wes Lee\u00a0<em>acc de Tyriek Igwe et Tyson Dupont<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c0 la fin du combat, D&rsquo;Angelo bloque le Cardiac Kick de Lee en Spear. D&rsquo;Angelo se pr\u00e9pare pour une prise, mais Channing Lorenzo d\u00e9barque sur le TitanTron. Lorenzo dit qu&rsquo;il est devant la maison de Rizzo. Lee en profite pour faire son Cardiac Kick \u00e0 D&rsquo;Angelo pendant qu&rsquo;il est distrait pour le compte de trois.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Gagnant : Wes Lee<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8211; Apr\u00e8s le combat, Lorenzo dit qu&rsquo;il va aller rendre visite \u00e0 Rizzo. D&rsquo;Angelo quitte le ring rapidement pour possiblement aller venir en aide \u00e0 Rizzo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8211; La\u00a0championne <strong>Stephanie Vaque<\/strong>r\u00a0arrive sur le ring. Vaquer dit que Jordynne Grace est devenue son aspirante pour Battleground. Elle a du respect envers Grace. Elle \u00e9tait au sommet de la TNA. Et maintenant Grace veut atteindre le sommet de NXT. Vaquer commence \u00e0 parler en espagnol, mais Jacy Jayne et Fallon Henley arrivent sur le ring.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Henley dit que \u00e7a doit \u00eatre bien d&rsquo;\u00eatre Vaquer, tout le monde l&rsquo;aime. Vaquer est au sommet depuis son arriv\u00e9e. Oui Vaquer est unique et c&rsquo;est ce qui va rendre sa chute encore meilleure. Jayne dit qu&rsquo;elle ne sait pas c&rsquo;est quoi de remporter le titre Nord-Am\u00e9ricain. Mais Vaquer a battu Henley pour le titre. Henley lui demande c&rsquo;est quoi son point. Jayne dit que le r\u00e8gne de Vaquer ne va pas durer longtemps. NXT est l&rsquo;univers de Fatal Influence et Vaquer ne m\u00e9rite pas sa place. La musique de Jordynne Grace se lance et elle arrive sur le ring.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Grace dit que Henley et Jayne n&rsquo;arrivent pas \u00e0 s&rsquo;entendre, alors comment elles osent venir parler du titre de NXT ici. Elle vient seulement ici pour s&rsquo;assurer pour prot\u00e9ger son adversaire. Jayne dit que Grace et Vaquer ont fait le tour du monde, mais pendant ce temps c&rsquo;est Fatal Influence qui menait la division de NXT et elles m\u00e9ritent de prendre leur place au sommet. Vaquer dit que Grace a \u00e9chou\u00e9 la premi\u00e8re fois et elle va \u00e9chouer encore. Grace dit qu&rsquo;en un an elle a beaucoup appris et elle va battre Vaquer, ce n&rsquo;est pas Fatal Influence qui va l&rsquo;arr\u00eater. Elle n&rsquo;a aucun probl\u00e8me de battre Fatal Influence ce soir et elle va s&rsquo;assurer que Vaquer arrive \u00e0 Battleground en un morceau. Jayne dit que la gagnante de Battleground n&rsquo;importe pas, car Fatal Influence sera l\u00e0 pour battre la championne.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8211; En coulisses, Myles Borne demande \u00e0 Charlie Dempsey s&rsquo;il va bien. Dempsey est au bout de sa vie, mais il dit qu&rsquo;il va bien. Borne dit \u00e0 Dempsey de ne pas venir en ringside pour son match, il va g\u00e9rer.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8211; En coulisses,\u00a0<strong>Bubba Ray<\/strong> et <strong>Undertaker\u00a0<\/strong>sont avec Tyra Mae Steele et Zena Sterling de WWE LFG. Bubba f\u00e9licite les deux pour leur performance \u00e0 WWE LFG. Les deux ont gagn\u00e9 le droit d&rsquo;\u00eatre ici et les deux ont gagn\u00e9 le droit de s&rsquo;affronter en finale de WWE LFG. Mais seulement une des deux aura la chance de gagner un contrat \u00e0 NXT. Et la gagnante aura assur\u00e9ment une grande cible sur leur dos. Izzi Dame et Nikkita Lyons arrivent pour rappeler que c&rsquo;est leur vestiaire ici. Lola Vice et Lash Legend arrivent en disant que si Sterling et Steele veulent leur voler leur place, elles vont souhaiter rester \u00e0 WWE LFG.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8211; Sur le parking ext\u00e9rieur, Tony D&rsquo;Angelo embarque dans sa voiture, son chauffeur l&rsquo;am\u00e8ne vers Rizzo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Myles Borne vs Ethan Page<\/strong><br><em>Si Ethan Page gagne, il aura la place d&rsquo;aspirant de Borne.<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c0 la fin du combat, Borne et Page s&rsquo;affrontent sur le coin. Page pr\u00e9pare une prise, mais Borne le repousse et lui fait une Clothesline du coin. Page \u00e9vite une PowerSlam et porte un coup de pied \u00e0 Borne. Page le prend pour son finisher, Borne le bloque et lui fait ensuite un Drop Kick. Borne enchaine avec un compte rapide pour le compte de trois !<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Gagnant : Myles Borne<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8211; En vid\u00e9o sur X, Sean Legacy de Evolve dit qu&rsquo;il a bien senti l&rsquo;\u00e9nergie de NXT au Battle Royal. C&rsquo;est le genre d&rsquo;\u00e9nergie qu&rsquo;il am\u00e8ne \u00e0 Evolve chaque semaine. Alors si Je&rsquo;Von Evans veut recr\u00e9er la magie qu&rsquo;ils ont commenc\u00e9 \u00e0 Battleground, ce serait un honneur.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8211; En coulisses, Ashante Adonis avise Je&rsquo;Von Evans qu&rsquo;il est trop une star pour se pr\u00e9occupe d&rsquo;un gars indy. Evans lui dit de g\u00e9rer ses blondes et lui va faire ce qu&rsquo;il fait. Adonis dit que Evans a fait un main event \u00e0 Stand and Deliver, alors le gars indy ne le m\u00e9rite pas. Evans dit que la sc\u00e8ne indy a de bons gars comme Legacy. Adonis dit qu&rsquo;il n&rsquo;a aucun probl\u00e8me de l&rsquo;affronter. Ricky Saints \u00e9coutait la discussion et dit qu&rsquo;il va aller voir Ava pour offrir un match de titre au gagnant.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8211; Tony D&rsquo;Angelo arrive \u00e0 la maison d&rsquo;Adriana Rizzo. Channing Lorenzo le frappe dans le dos avec une tige d&rsquo;acier. Lorenzo dit qu&rsquo;il a \u00e9tudi\u00e9 Lorenzo pendant longtemps. Et le voil\u00e0 sans aucune famille et d\u00e9sesp\u00e9r\u00e9.\u00a0Il a humili\u00e9 D&rsquo;Angelo par choix \u00e0 Stand and Deliver et \u00e0 Battleground il va mettre un termine \u00e0 la Famille D&rsquo;Angelo pour de bon.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Thea Hail vs Tatum Paxley<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c0 la fin du combat, Hail applique son Arm Bar sur Paxley. Paxley fait tout pour r\u00e9sister et lui met un doigt dans l&rsquo;oeil, l&rsquo;arbitre arr\u00eate le match.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Gagnante : Thea Hail\u00a0par <strong>DQ<\/strong><\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8211; Apr\u00e8s le combat, Paxley a perdu le contr\u00f4le et veut encore attaquer l&rsquo;oeil de Hail. Des officiels arrivent pour stopper Paxley.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8211; En coulisses, Kelani Jordan, Zaria et Sol Ruca sont avec Kelani Jordan. Jordan demande c&rsquo;\u00e9tait quoi le Spear de Zaria contre la barricade. Ruca dit qu&rsquo;elle ne savait pas que \u00e7a allait arriver, elle s&rsquo;excuse. Zaria dit qu&rsquo;elles n&rsquo;ont pas besoin de s&rsquo;excuser, elle gagn\u00e9 par le compte de trois. Spear contre la barricade ou non, le r\u00e9sultat ne change pas.\u00a0Jordan propose un rematch \u00e0 Zaria et si elle gagne elle sera aspirante pour le titre Nord-Am\u00e9ricain. Ruca accepte.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8211; Les commentateurs confirment que Tony D&rsquo;Angelo va affronter Channing Lorenzo\u00a0\u00e0 Battleground.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8211; En coulisses, on retrouve\u00a0Trick Williams et Joe Hendry avec Ava pour leur signature de contrat pour Battleground. Ava pr\u00e9sente leur match. Williams dit que Hendry lui a pris son opportunit\u00e9, alors il va lui prendre ce lui importe le plus, le titre TNA. Dimanche prochain ils iront \u00e0 Battleground et c&rsquo;est sa maison. Hendry dit qu&rsquo;il aime prendre des risques, mais Williams aime toujours se plaindre. Ava ram\u00e8ne tout le monde au calme et les invite \u00e0 signer.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hendry dit que la TNA n&rsquo;a jamais \u00e9t\u00e9 aussi importante car \u00e0 chaque jour il se r\u00e9veille avec comme objectif d&rsquo;\u00eatre le meilleur champion. Il d\u00e9fend le titre \u00e0 la TNA et contre un catcheur de NXT. Pour la premi\u00e8re fois le titre TNA sera en jeu sur un PLE WWE, c&rsquo;est \u00e9norme. Williams dit que c&rsquo;est \u00e9norme car c&rsquo;est lui dans le match. Hendry est une star des r\u00e9seaux sociaux, mais lui il est plus grand que Hendry et la TNA. Dimanche prochain il va prendre la gloire de Hendry, son titre et sa division. Williams signe le contrat. Hendry dit que personne n&rsquo;a plus de confiance que Williams. Oui Williams a fait le main event de Stand and Deliver deux fois de suite, mais c&rsquo;est le match le plus important de sa carri\u00e8re. Williams est \u00e0 la crois\u00e9e des chemins. Williams va perdre contre le champion TNA et maintenant Williams n&rsquo;aura plus de chemin vers l&rsquo;or. Hendry dit que c&rsquo;est Williams qui va d\u00e9couvrir c&rsquo;est quoi perdre sa gloire. Hendry signe le contrat.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8211; En coulisses, Hank et Tank arr\u00eatent Josh Briggs. Hank dit qu&rsquo;ils se sentent mal pour Briggs qui a perdu son meilleur ami et son partenaire. Briggs dit qu&rsquo;il \u00e9tait comme son fr\u00e8re. Il \u00e9tait en col\u00e8re des d\u00e9faites, mais il n&rsquo;a jamais voulu le pousser vers la sortie. Hank dit qu&rsquo;ils sont l\u00e0 pour lui. Shawn Spears arrive et dit que si Briggs avait bien profit\u00e9 du moment, son ami serait peut-\u00eatre encore ici. Tank dit que ce n&rsquo;est pas le temps pour \u00e7a. Spears dit que Briggs est un cancer pour les relations si on regarde aussi Brooks Jensen. Briggs dit qu&rsquo;il sait comment s&rsquo;all\u00e9ger l&rsquo;esprit contre Spears.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8211; En coulisses, Ava demande \u00e0 Kale Dixon et Uriah Connors pourquoi ils veulent autant leur parler. Dixon dit que ChaseU est de retour en force et c&rsquo;est le moment de donner leur chance. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Connors r\u00e9plique qu&rsquo;ils veulent remettre ChaseU sur la carte en affrontant n&rsquo;importe qui. Ava dit qu&rsquo;ils auront leur premier match la semaine prochaine. Andre Chase arrive et il est content. Connors demande qui sera les adversaires.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ava conclue en disant que ce sera OTM qui fait leur retour.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8211; La WWE annonce un concert de Joe Hendry et un rap de Trick Williams mardi dernier prochain. Aussi : Jordan vs Zaria en rematch, et Je&rsquo;Von Evans vs Sean Legacy vs Ashante Adonis.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Fallon Henley et Jacy Jayne vs Jordynne Grace et Stephanie Vaquer<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c0 la fin du combat, Jayne repousse Vaquer en bas du ring. Jayne et Henley veulent faire une prise \u00e0 deux, mais Grace repousse les deux. Elle chasse Henley du ring avec un Headbutt et enchaine avec son Beast Mode pour le compte de trois sur Jayne.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Gagnantes : Jordynne Grace et Stephanie Vaquer<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8211; Apr\u00e8s le combat, Vaquer et Grace font un face \u00e0 face.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8211; Les commentateurs pr\u00e9sentent\u00a0la carte de Battleground.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8211; En coulisses, on voit que\u00a0Ethan Page a attaqu\u00e9 Ricky Saints. Le show se termine ainsi.<\/p>\n\n\n\n<p class=\"has-text-align-center has-medium-font-size wp-block-paragraph\"><strong><a href=\"https:\/\/www.jdx.info\/lutte\/2025\/05\/13\/reprise-pour-le-wwe-nxt-du-13-mai-2025\/\" target=\"_blank\" rel=\"noreferrer noopener\">Pour voir NXT, cliquez ici.<\/a><\/strong><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-info-lutte wp-block-embed-info-lutte\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"pdoofK8TB3\"><a href=\"https:\/\/www.jdx.info\/lutte\/2025\/05\/13\/reprise-pour-le-wwe-nxt-du-13-mai-2025\/\">Reprise pour le WWE NXT du 13 Mai 2025 !<\/a><\/blockquote><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"\u00ab\u00a0Reprise pour le WWE NXT du 13 Mai 2025 !\u00a0\u00bb &#8212; Info-Lutte\" src=\"https:\/\/www.jdx.info\/lutte\/2025\/05\/13\/reprise-pour-le-wwe-nxt-du-13-mai-2025\/embed\/#?secret=ySaoPVzYEe#?secret=pdoofK8TB3\" data-secret=\"pdoofK8TB3\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>WWE NXT Orlando, Floride, 13 mai 2025 &#8211; Le WWE NXT, d\u00e9bute sur une vid\u00e9o\u00a0des \u00e9v\u00e9nements de mardi dernier\u00a0lorsque Myles Borne a remport\u00e9 la Battle Royal pour devenir aspirant face \u00e0 Oba Femi. &#8211; Les commentateurs nous souhaitent la bienvenue et le No Quarter Catch Crew arrive sur le ring.&nbsp;Myles Borne&nbsp;dit que mardi dernier il&#8230;<\/p>\n","protected":false},"author":37048,"featured_media":117452,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[85,21,23],"tags":[],"ppma_author":[297],"class_list":["post-117451","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nxt","category-resultats","category-wwe"],"authors":[{"term_id":297,"user_id":37048,"is_guest":0,"slug":"mattante","display_name":"Mattias Antoinette","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/db141441570c9bdee0787662393889dfbc3d6c721d3318f2402846725b7b664e?s=96&d=mm&r=g","author_category":"","first_name":"Mattias","last_name":"Antoinette","user_url":"http:\/\/info-catch.com","job_title":"","description":"Une seule personne, deux t\u00eates \u00e0 claques"}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/117451","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/37048"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=117451"}],"version-history":[{"count":1,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/117451\/revisions"}],"predecessor-version":[{"id":117453,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/117451\/revisions\/117453"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/117452"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=117451"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=117451"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=117451"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=117451"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}