{"id":116923,"date":"2025-05-05T10:26:00","date_gmt":"2025-05-05T14:26:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=116923"},"modified":"2025-05-05T15:14:43","modified_gmt":"2025-05-05T19:14:43","slug":"karl-anderson-fete-plus-de-500-jours-de-sobriete-jai-limpression-davoir-a-nouveau-22-ans","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2025\/05\/05\/karl-anderson-fete-plus-de-500-jours-de-sobriete-jai-limpression-davoir-a-nouveau-22-ans\/","title":{"rendered":"Karl Anderson f\u00eate plus de 500 jours de sobri\u00e9t\u00e9 : \u00ab J\u2019ai l\u2019impression d\u2019avoir \u00e0 nouveau 22 ans"},"content":{"rendered":"\n<p>Karl Anderson est peut-\u00eatre connu pour en avoir \u00e9lev\u00e9 quelques-uns avec les Good Brothers, mais ces jours-ci, il porte un toast \u00e0 quelque chose de tr\u00e8s diff\u00e9rent : la sobri\u00e9t\u00e9.<\/p>\n\n\n\n<p>Lors d\u2019un r\u00e9cent \u00e9pisode de\u00a0Talk N Shop, le lutteur v\u00e9t\u00e9ran a r\u00e9v\u00e9l\u00e9 qu\u2019il n\u2019avait pas consomm\u00e9 d\u2019alcool depuis plus d\u2019un an. Tout en saluant les auditeurs, Anderson a fi\u00e8rement partag\u00e9 qu\u2019il \u00e9tait sobre depuis plus de 500 jours et qu\u2019il se sentait mieux que jamais.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u00ab La mitrailleuse, c\u2019est comme 500 jours : sobre, glaciale. Je me sens bien. Niveau sup\u00e9rieur, ne pas boire de bi\u00e8re. Je me sens bien. Ma sant\u00e9 est \u00e0 travers le toit. <\/p>\n\n\n\n<p>J\u2019\u00e9tais l\u2019un des meilleurs lutteurs de toute fa\u00e7on, je n\u2019ai jamais \u00e9t\u00e9 cr\u00e9dit\u00e9 pour cela. J\u2019\u00e9tais l\u2019un des meilleurs lutteurs de tous les temps et j\u2019avais la gueule de bois la moiti\u00e9 du temps. Maintenant que je n\u2019ai plus jamais la gueule de bois, j\u2019ai l\u2019impression d\u2019avoir \u00e0 nouveau 22 ans. C\u2019est un de tournage.\u201d<\/p>\n<\/blockquote>\n\n\n\n<p>Actuellement \u00e0 l\u2019\u00e9cart du jeu alors qu\u2019il se remet d\u2019une op\u00e9ration pour une d\u00e9chirure de la coiffe des rotateurs et un labrum partiellement d\u00e9chir\u00e9, Anderson n\u2019est pas sur le ring depuis qu\u2019il a subi l\u2019intervention en novembre. Le temps de r\u00e9cup\u00e9ration a \u00e9t\u00e9 estim\u00e9 \u00e0 six \u00e0 neuf mois.<\/p>\n\n\n\n<p>Plus t\u00f4t cette ann\u00e9e, Anderson et son partenaire de longue date, Luke Gallows, ont \u00e9t\u00e9 lib\u00e9r\u00e9s de la WWE. Les deux hommes devraient sortir un \u00e9pisode de Talk N Shop ce jeudi 8 mai, o\u00f9 ils d\u00e9taillent tout ce qui s\u2019est pass\u00e9 lors de leurs d\u00e9parts de la WWE.<\/p>\n\n\n\n<center><iframe allow=\"autoplay *; encrypted-media *; fullscreen *; clipboard-write\" frameborder=\"0\" height=\"450\" style=\"width:100%;max-width:660px;overflow:hidden;border-radius:10px;\" sandbox=\"allow-forms allow-popups allow-same-origin allow-scripts allow-storage-access-by-user-activation allow-top-navigation-by-user-activation\" src=\"https:\/\/embed.podcasts.apple.com\/us\/podcast\/talkn-shop\/id1504940209\"><\/iframe><\/center>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Karl Anderson est peut-\u00eatre connu pour en avoir \u00e9lev\u00e9 quelques-uns avec les Good Brothers, mais ces jours-ci, il porte un toast \u00e0 quelque chose de tr\u00e8s diff\u00e9rent : la sobri\u00e9t\u00e9. Lors d\u2019un r\u00e9cent \u00e9pisode de\u00a0Talk N Shop, le lutteur v\u00e9t\u00e9ran a r\u00e9v\u00e9l\u00e9 qu\u2019il n\u2019avait pas consomm\u00e9 d\u2019alcool depuis plus d\u2019un an. Tout en saluant les&#8230;<\/p>\n","protected":false},"author":665,"featured_media":116947,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24,30,4],"tags":[],"ppma_author":[289],"class_list":["post-116923","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aew-impact-njpw-roh","category-ex-wwe","category-news"],"authors":[{"term_id":289,"user_id":665,"is_guest":0,"slug":"line","display_name":"Line Edmond","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/852de09636413c90cdaa278312f9ea5bc4396768745424755cb63d99a05989d0?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/116923","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/665"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=116923"}],"version-history":[{"count":2,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/116923\/revisions"}],"predecessor-version":[{"id":116948,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/116923\/revisions\/116948"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/116947"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=116923"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=116923"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=116923"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=116923"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}