{"id":116588,"date":"2025-04-27T20:02:00","date_gmt":"2025-04-28T00:02:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=116588"},"modified":"2025-04-30T14:30:10","modified_gmt":"2025-04-30T18:30:10","slug":"resultats-et-video-pour-le-ppv-rebellion-2025-de-la-tna","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2025\/04\/27\/resultats-et-video-pour-le-ppv-rebellion-2025-de-la-tna\/","title":{"rendered":"R\u00e9sultats et Vid\u00e9o pour le PPV Rebellion 2025 de la TNA !"},"content":{"rendered":"\n<p>La TNA pr\u00e9sentait son PPV Rebellion ce dimanche 27 avril 2025, depuis le Galen Center \u00e0 Los Angeles, Californie. <\/p>\n\n\n\n<p>Le show est disponible sur TNA+, sinon vous pouvez voir le show ici m\u00eame en <a href=\"https:\/\/www.jdx.info\/lutte\/2025\/04\/27\/reprise-video-pour-le-tna-impact-wrestling-2025\/\" target=\"_blank\" rel=\"noreferrer noopener\">cliquant ici<\/a>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Pr\u00e9-Show<\/strong><\/h2>\n\n\n\n<p><strong>Fatal Influence  NXT (Jacy Jayne, Fallon Henley &amp; Jazmyn Nyx) vs L\u00e9i Ying Lee, Xia Brookside &amp; Rosemary<\/strong><\/p>\n\n\n\n<p>\u00c0 la fin du match, Rosemary donne un poing am\u00e9ricain \u00e0 Brookside, mais cette derni\u00e8re ne sait pas quoi en faire. Elle perd du temps et l\u2019arbitre la voit avec dans les mains. Elle rend le poing am\u00e9ricain \u00e0 Rosemary, mais Jayne en profite pour faire chuter Rosemary du ring et faire une Clothesline \u00e0 Brookside pour le compte de trois.<\/p>\n\n\n\n<p><em>Gagnantes&nbsp;: Fatal Influence<\/em><\/p>\n\n\n\n<p>&#8211; On apprend que JDC n\u2019est pas pr\u00e9sent ce soir, ce qui signifie que Moose devra prendre part \u00e0 deux matchs, l\u2019un pour d\u00e9fendre son titre X-Division dans un Ultimate-X et l\u2019autre dans un 6-Man Tag Team contre Ace Austin et les Rascalz.<\/p>\n\n\n\n<p><strong>Open Challenge<\/strong><br>Elijah vs Shane Haste<\/p>\n\n\n\n<p>\u00c0 la fin du match, Elijah fait un running knee \u00e0 Haste. Il encha\u00eene avec un Highwayman\u2019s Farewell pour le compte de trois.<\/p>\n\n\n\n<p><em>Gagnant&nbsp;: Elijah<\/em><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Carte Principale<\/strong><\/h2>\n\n\n\n<p><strong>TNA X-Division Championship \u2013 Ultimate X-Match<\/strong><br>Moose \u00a9 <em>accompagn\u00e9 d\u2019Alisha Edwards<\/em>&nbsp;vs Matt Cardona vs KC Navarro&nbsp;<em>accompagn\u00e9 d\u2019AJ Francis<\/em>&nbsp;vs Sidney Akeem vs Leon Slater vs El Hijo del Vikingo<\/p>\n\n\n\n<p>\u00c0 la fin du match, tous les catcheurs sont en ringside. Leon Slater est seul dans le ring. Il monte sur la structure, mais plut\u00f4t que d\u2019aller chercher le titre, il d\u00e9cide de grimper sur le point le plus haut dans le coin pour faire un Swanton 450 sur les autres catcheurs en sautant d\u2019environ 5 m\u00e8tres&nbsp;! Il parvient \u00e0 se relever et \u00e0 d\u00e9crocher le titre, mais il faut ensuite qu\u2019il descende pour valider la victoire. Lorsqu\u2019il saute pour revenir sur le ring, Moose lui fait un Spear et r\u00e9cup\u00e8re le championnat qui lui avait gliss\u00e9 des mains. De fait, Moose conserve son championnat, bien qu\u2019il semble que Slater ait touch\u00e9 le ring avant le Spear&#8230;<\/p>\n\n\n\n<p><em>Gagnant&nbsp;: Moose <\/em><\/p>\n\n\n\n<p><strong>TNA Knockouts Tag Team Championship &#8211; Fatal 4-Way Match<\/strong><br>Ash &amp; Heather by Elegance&nbsp;accompagn\u00e9es du concierge personnel&nbsp;\u00a9 vs Spitfire (Dani Luna &amp; Jody Threat) vs Gigi Dolin &amp; Tatum Paxley vs Lash Legend &amp; Jakara Jackson<\/p>\n\n\n\n<p>\u00c0 la fin du match, Ash by Elegance est en mauvaise posture. Elle se situe sur la troisi\u00e8me corde et Gigi Dolin, Jody Threat et Lash Legend veulent la faire tomber. Magie Lee intervient en retenant la jambe d\u2019Ash, ce qui lui permet de ne pas subir la prise de Legend qui envoie Dolin et Threat s\u2019\u00e9craser sur le ring&nbsp;! Ash by Elegance peut ensuite placer son Rarified Air sur Threat pour le compte de trois&nbsp;!<\/p>\n\n\n\n<p><em>Gagnantes&nbsp;: Ash &amp; Heather by Elegance \u00a9<\/em><\/p>\n\n\n\n<p><strong>The System (Moose, Eddie Edwards &amp; Brian Myers) vs The Rascalz (Trey Miguel &amp; Zachary Wentz) &amp; Ace Austin&nbsp;<\/strong><em>acc<\/em><em> de Sean Waltman<\/em><\/p>\n\n\n\n<p>\u00c0 la fin du match, le System est mal en point. Alisha Edwards rentre dans le ring pour d\u00e9ranger les Rascalz et Austin. Waltman vient confronter Alisha. Elle lui donne une gifle et Waltman riposte avec le X-Factor&nbsp;! Pendant que l\u2019arbitre s\u2019occupe d\u2019Alisha, Waltman continue de faire le m\u00e9nage sous une ovation monstre. Miguel et Austin font un suicide dive pour garder Edwards et Myers en dehors du ring. Wentz contre un Spear de Moose en X-Factor&nbsp;! Wentz poursuit avec un UFO Cutter pour remporter le match en portant le tomb\u00e9 sur Moose&nbsp;!<\/p>\n\n\n\n<p><strong>Gagnants&nbsp;: The Rascalz &amp; Ace Austin<\/strong><\/p>\n\n\n\n<p><strong>TNA International Championship<\/strong><br>Steve Maclin \u00a9 vs Eric Young&nbsp;<em>acc  de la Northern Armory<\/em><\/p>\n\n\n\n<p>\u00c0 la fin du match, Maclin fait un psycho knee sur Young. Le challenger tente un compte rapide, mais il se fait contrer lui-m\u00eame par un compte rapide qui permet \u00e0 Maclin de conserver.<\/p>\n\n\n\n<p><em>Gagnant&nbsp;: Steve Maclin <\/em><\/p>\n\n\n\n<p>&#8211; Apr\u00e8s le match, Icarus et Williams, qui s\u2019\u00e9taient fait expulser, reviennent pour s\u2019en prendre \u00e0 Maclin. Young prend une cha\u00eene, la place autour du cou de Maclin et l\u2019\u00e9trangle et le laissant suspendu aux cordes.<\/p>\n\n\n\n<p><strong>Falls Count Anywhere Match<\/strong><br>Mike Santana vs Mustafa Ali<\/p>\n\n\n\n<p>\u00c0 la fin du match, les Great Hands interviennent, mais Santana parvient facilement \u00e0 les maitriser et il les attache avec des menottes dans le coin du ring. Tasha Steelz entre \u00e9galement dans le ring, mais Santana n\u2019h\u00e9site pas et lui fait une Powerbomb directement \u00e0 travers une table en ringside&nbsp;! De retour dans le ring, Ali donne un coup dans le cr\u00e2ne de Santana avec une batte entour\u00e9e de barbel\u00e9s&nbsp;! Santana commence \u00e0 saigner abondamment de la t\u00eate, mais il contre Ali et lui fait un Spin The Block pour la victoire&nbsp;!<\/p>\n\n\n\n<p><em>Gagnant&nbsp;: Mike Santana<\/em><\/p>\n\n\n\n<p>&#8211; Gia Miller pr\u00e9sente la&nbsp;nouvelle signature Knockouts de la TNA, Indi Hartwell, l&rsquo;ancienne partenaire de Candie LeRae \u00e0 la WWE.<\/p>\n\n\n\n<p><strong>TNA Knockouts Championship <\/strong><br>Masha Slamovich \u00a9 vs Tessa Blanchard<\/p>\n\n\n\n<p>\u00c0 la fin du match, Blanchard place sont Buzzsaw, mais Slamovich se d\u00e9gage&nbsp;! La championne se bat pour revenir et coince Blanchard dans un armbar, qui n\u2019a d\u2019autre choix que de taper et abandonner.<\/p>\n\n\n\n<p><em>Gagnante&nbsp;: Masha Slamovich <\/em><\/p>\n\n\n\n<p><strong>TNA Tag Team Championship <\/strong><br>The Hardys (Matt &amp; Jeff Hardy) \u00a9 vs The Nemeths (Nic &amp; Ryan Nemeth)<\/p>\n\n\n\n<p>\u00c0 la fin du match, Matt Hardy se bat avec Ryan Nemeth en ringside. Il sort une chaise du ring et la place devant lui dans le but de faire retomber Ryan Nemeth dessus, mais il est contr\u00e9 et Ryan Nemeth le fait s\u2019\u00e9craser sur la chaise&nbsp;! Lorsque Ryan revient vers le ring, l\u2019arbitre qui n\u2019avait rien vu le retient pour pas qu\u2019il n\u2019intervienne puisque Nic Nemeth est l\u2019homme l\u00e9gal. Pendant ce temps, Nic fait un Low blow \u00e0 Jeff Hardy&nbsp;! Il fait ensuite son Danger Zone et passe le relai \u00e0 Ryan qui s\u2019empresse de faire le tomb\u00e9 sur Jeff Hardy pour remporter les championnats par \u00e9quipe&nbsp;!<\/p>\n\n\n\n<p><em>Gagnants Nouveaux champions&nbsp;: The Nemeths <\/em><\/p>\n\n\n\n<p><strong>TNA World Championship \u2013 3-Way Match<\/strong><br>Joe Hendry \u00a9 vs Frankie Kazarian vs Ethan Page<\/p>\n\n\n\n<p>\u00c0 la fin du match, Joe Hendry fait passer Kazarian \u00e0 travers une table en ringside avec un AA. Lorsque le champion revient dans le ring, Ethan Page l\u2019y attendait pr\u00eat \u00e0 le frapper avec le championnat de la TNA. Hendry esquive mais finit par subir un Cutter de Page sur le titre de la TNA&nbsp;! Le champion se d\u00e9gage in extremis. Joe Hendry reprend l\u2019avantage et encha\u00eene Fallaway Slam et Standing Ovation sur Ethan Page pour conserver son titre&nbsp;!<\/p>\n\n\n\n<p><em>Gagnant&nbsp;: Joe Hendry \u00a9<\/em><\/p>\n\n\n\n<p>Apr\u00e8s le match, Trick Williams de NXT attaque Joe Hendry&nbsp;! Il fait un Trick Shot pour mettre le champion KO. L\u2019\u00e9mission se conclut par une c\u00e9l\u00e9bration de Trick Williams.<\/p>\n\n\n\n<p class=\"has-text-align-center has-medium-font-size\"><a href=\"https:\/\/www.jdx.info\/lutte\/2025\/04\/27\/reprise-video-pour-le-tna-impact-wrestling-2025\/\"><strong>Pour voir le PPV Rebellion<\/strong><\/a><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-info-lutte wp-block-embed-info-lutte\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"DfFSf0mHdP\"><a href=\"https:\/\/www.jdx.info\/lutte\/2025\/04\/27\/reprise-video-pour-le-tna-impact-wrestling-2025\/\">Reprise Vid\u00e9o pour le TNA Impact Wrestling 2025 !<\/a><\/blockquote><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"\u00ab\u00a0Reprise Vid\u00e9o pour le TNA Impact Wrestling 2025 !\u00a0\u00bb &#8212; Info-Lutte\" src=\"https:\/\/www.jdx.info\/lutte\/2025\/04\/27\/reprise-video-pour-le-tna-impact-wrestling-2025\/embed\/#?secret=CWnA0YK5Te#?secret=DfFSf0mHdP\" data-secret=\"DfFSf0mHdP\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>La TNA pr\u00e9sentait son PPV Rebellion ce dimanche 27 avril 2025, depuis le Galen Center \u00e0 Los Angeles, Californie. Le show est disponible sur TNA+, sinon vous pouvez voir le show ici m\u00eame en cliquant ici. Pr\u00e9-Show Fatal Influence NXT (Jacy Jayne, Fallon Henley &amp; Jazmyn Nyx) vs L\u00e9i Ying Lee, Xia Brookside &amp; Rosemary&#8230;<\/p>\n","protected":false},"author":55,"featured_media":116593,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24,30,85,21,41],"tags":[],"ppma_author":[288],"class_list":["post-116588","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aew-impact-njpw-roh","category-ex-wwe","category-nxt","category-resultats","category-tna-impact"],"authors":[{"term_id":288,"user_id":55,"is_guest":0,"slug":"mark-green","display_name":"Watch Wrestling","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/48aa7229968e08b18e4ac74ae48666f742d5f4460d3a972818733f8de3e505c2?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/116588","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=116588"}],"version-history":[{"count":3,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/116588\/revisions"}],"predecessor-version":[{"id":116617,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/116588\/revisions\/116617"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/116593"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=116588"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=116588"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=116588"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=116588"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}