{"id":116360,"date":"2025-04-23T19:54:00","date_gmt":"2025-04-23T23:54:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=116360"},"modified":"2025-04-25T23:09:25","modified_gmt":"2025-04-26T03:09:25","slug":"resultats-pour-le-aew-dynamite-du-23-avril-2025","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2025\/04\/23\/resultats-pour-le-aew-dynamite-du-23-avril-2025\/","title":{"rendered":"R\u00e9sultats Pour le AEW Dynamite du 23 Avril 2025 !"},"content":{"rendered":"\n<ul class=\"wp-block-list\">\n<li> <strong><a href=\"https:\/\/www.jdx.info\/lutte\/2025\/04\/23\/reprive-video-pour-le-aew-dynamite-du-23-avril-2025\/\" target=\"_blank\" rel=\"noreferrer noopener\">Pour voir Dynamite, cliquez ici<\/a><\/strong><\/li>\n<\/ul>\n\n\n\n<p><strong>AEW Dynamite Nouvelle-Orl\u00e9ans, Louisiane, 23 avril 2025<\/strong><br>Les commentateurs sont Ian Riccaboni, Taz et Excalibur.<\/p>\n\n\n\n<p>&#8211; Le AEW Dynamite d\u00e9bute avec Tony Schiavone sur le ring et il nous souhaite la bienvenue au rappeur\u00a0<strong>Master P<\/strong> qui souhaite la bienvenue \u00e0 AEW Dynamite. Master P dit qu&rsquo;il est heureux de nous pr\u00e9senter les nouveaux champions Trios AEW, The Opps. <\/p>\n\n\n\n<p>Samoa Joe, Katsuyori Shibata et Powerhouse Hobbs arrivent sur le ring sous une ovation. Joe dit que c&rsquo;est bien d&rsquo;\u00eatre ici ce soir car The Opps sont ici pour c\u00e9l\u00e9brer. Mais avant il doit remercier Master P pour son accueil dans leur ville et tout ce qu&rsquo;il fait pour les jeunes de la ville. Master P dit qu&rsquo;il a pass\u00e9 de Master P \u00e0 coach P pour aider les jeunes car il aime la Nouvelle-Orl\u00e9ans. Samoa Joe dit que c&rsquo;est ici le meilleur endroit pour c\u00e9l\u00e9brer. La musique des Death Riders se lance et Marina Shafir arrive seule sur le ring. Wheeler Yuta, Claudio Castagnoli et Jon Moxley arrivent de l&rsquo;autre c\u00f4t\u00e9 pour attaquer The Opss dans le dos !<\/p>\n\n\n\n<p>Master P se retrouve seul sur le ring face aux Death Riders. Moxley s&rsquo;approche de Master P, mais Samoa Joe revient pour lui appliquer un Coquina Clutch pendant que Master P donne des coups sur Moxley en m\u00eame temps. Joe fait dormir Moxley. Les Young Bucks et Okada arrivent sur le ring avec une chaise pour frapper Joe et l&rsquo;attaquer ! Les Bucks veulent aider Moxley \u00e0 se relever, mais Shafir sort Moxley du ring rapidement.<\/p>\n\n\n\n<p>La musique de Swerve Strickland se lance et il arrive sur le ring avec une cha\u00eene d&rsquo;acier. Les Bucks, Okada et les Death Riders s&rsquo;\u00e9chapper du ring. La musique de Kenny Omega se lance et il arrive sur la sc\u00e8ne pour bloquer le chemin aux Bucks. Les Bucks arrivent \u00e0 s&rsquo;\u00e9chapper par la foule.\u00a0<\/p>\n\n\n\n<p>Samoa Joe prend le micro et dit que Moxley le voulait, alors maintenant il l&rsquo;a. Il va \u00e9trangler Jon Moxley et lui prendre son titre mondial AEW !<\/p>\n\n\n\n<p>&#8211; En coulisses, Renee Paquette est avec le clan de Christian Cage pour avoir leur commentaire sur Nick Wayne le champion le plus jeune de l&rsquo;histoire de la ROH. Cage dit que les f\u00e9licitations devraient revenir \u00e0 lui. Cage prend le titre \u00e0 Wayne. Cage dit que sans lui, Wayne ne serait pas le champion. C&rsquo;est lui qui a forc\u00e9 Nick Wayne pour le pousser \u00e0 ses limites et sortir son meilleur c\u00f4t\u00e9 qu&rsquo;il connaissait depuis longtemps. Ils font bien fiers de lui, d&rsquo;ailleurs lui et sa m\u00e8re ont c\u00e9l\u00e9br\u00e9 fort toute la nuit.\u00a0Cage dit que lorsque Wayne \u00e9coute de belles choses arrivent. Wayne dit que Cage gagne des titres lorsqu&rsquo;il suit le plan. Cage redonne le titre \u00e0 Wayne. Cage dit qu&rsquo;il aime sa famille.<\/p>\n\n\n\n<p><strong>Ricochet vs Mark Briscoe<\/strong><\/p>\n\n\n\n<p>\u00c0 la fin du combat, Briscoe se lance en Flip sur Ricochet en bas du ring. Briscoe le ram\u00e8ne sur le ring et lui fait une Clothesline pour le couvrir, mais il r\u00e9siste. Briscoe veut faire un Jay Driller, Ricochet le repousse contre le coin. Ricochet veut faire un compte rapide, mais Briscoe le renverse en sa faveur pour la victoire !<\/p>\n\n\n\n<p><em>Gagnant : Mark Briscoe<\/em><\/p>\n\n\n\n<p>&#8211; Apr\u00e8s le combat, Briscoe c\u00e9l\u00e8bre sa victoire, mais Ricochet n&rsquo;est pas content. Ricochet le frappe avec une chaise ! Ricochet sort ses ciseaux, mais Kevin Knight arrive. Knight frappe Ricochet et lui prend ses ciseaux, Ricochet prend la fuite.<\/p>\n\n\n\n<p>&#8211; De retour suite \u00e0 la pause, Tony Schiavone est sur le ring et pr\u00e9sente<strong>\u00a0FTR<\/strong>, mais Stokely Hathaway arrive. Hathaway dit qu&rsquo;il y a un changement de plan pour cette interview. Hathaway nous pr\u00e9sente FTR qui arrive sur le ring. Hathaway dit qu&rsquo;il veut attaquer le sujet. FTR a \u00e9t\u00e9 suspendu pour avoir \u00e9t\u00e9 accus\u00e9 de toucher Tony Schiavone. C&rsquo;est ironique alors que Adam Page a br\u00fbl\u00e9 une maison. Ricochet vient chaque semaine aux shows avec des ciseaux. Et Jon Moxley a fait des actes de terrorismes, kidnapping et autres. Des gens qui sont \u00e0 l&rsquo;AEW sans aucune punition, c&rsquo;est injuste. Hathaway dit qu&rsquo;il est l\u00e0 pour g\u00e9rer \u00e7a. Il va faire effacer cette suspension de leur palmar\u00e8s et il va s&rsquo;attaquer \u00e0 l&rsquo;amende. Maintenant si quelqu&rsquo;un veut parler avec FTR, il faut parler avec lui.\u00a0\u00c0 partir de maintenant, il est le nouvel agent de la meilleure \u00e9quipe, FTR. Hathaway invite Schiavone \u00e0 faire son boulot, Schiavone passe le micro \u00e0 Cash Wheeler.<\/p>\n\n\n\n<p>Wheeler dit que ce n&rsquo;\u00e9tait pas une d\u00e9cision facile avec Daniel Garcia. Mais Garcia a pris sa propre d\u00e9cision, c&rsquo;est 2.0 qui s&rsquo;est mis devant eux, c&rsquo;est 2.0 qui a demand\u00e9 de se battre. Mais il ne pense pas que 2.0 \u00e9tait vraiment pr\u00eat de se battre. Mais ils ont arr\u00eat\u00e9 lorsque Garcia l&rsquo;a demand\u00e9 comme ils sont amis, mais voil\u00e0 que Garcia a d\u00e9cid\u00e9 des abandonner. C&rsquo;est termin\u00e9 de faire passer les autres avant eux, maintenant ils vont se prioriser. Dax Harwood dit qu&rsquo;il y a quelques l\u00e9gendes ici ce soir. Il y a les Rock and Roll Express en ringside. FTR invite le duo sur le ring et ils arrivent sur le ring. Harwood dit que Rock and Roll Express a eu une carri\u00e8re l\u00e9gendaire. Quel est leur plus grand match ? Ricky Morton allait r\u00e9pondre, mais Harwood lui enl\u00e8ve le micro. Harwood dit que le Midnight Express \u00e9tait meilleur que les Rock and Roll Express, il faut le dire. Harwood dit que c&rsquo;est 40 ans le duo des Rock and Roll Express, s&rsquo;il regarde les deux ont dirait qu&rsquo;ils ont pass\u00e9 plus de 100 ans. Ricky Morton lui prend le micro et dit que FTR ne pourra pas les humilier ainsi ce soir.<\/p>\n\n\n\n<p>Hathaway ram\u00e8ne tout le monde au sol. Hathaway dit qu&rsquo;ils ont un nouveau tee-shirt et ils veulent leur offrir. Hathaway lance le tee-shirt sur eux pour que FTR attaque Ricky Morton et Robert Gibson ! FTR fait un Pile Driver \u00e0 deux \u00e0 Morton ! Undisputed Kingdom arrive sur le ring, mais FTR prend la fuite.<\/p>\n\n\n\n<p><strong>Young Bucks&nbsp;<em>(Matthew et Nicholas Jackson)<\/em>&nbsp;vs Mike Bailey et Kevin Knight<\/strong><\/p>\n\n\n\n<p>\u00c0 la fin du combat, Bailey et Knight font un High Low sur Nicholas. Bailey se lance en Springboard Moonsault sur Matthews en ringside pendant que Knight fait un Springboard Splash \u00e0 Nicholas pour le couvrir, mais il r\u00e9siste. Bailey fait un Knee Drop \u00e0 Nicholas. Knight enchaine avec son Splash et le couvre, mais Matthew repousse Bailey sur Knight pour stopper le compte. Ensuite, Bailey veut se lance en Moonsault sur les Bucks en ringside, mais ils attrapent Bailey. Ils font leur Meltzer Driver \u00e0 deux sur Bailey en ringside ! Les Bucks veulent faire un EVP Trigger sur Knight, mais Knight \u00e9vite le coup et porte un double coup de pieds et un Double DDT sur Bucks. Knight se pr\u00e9pare pour un saut, mais Ricochet lui attrape la jambe. Les Bucks bloquent le saut de Knight et lui font un EVP Trigger pour le compte de trois.<\/p>\n\n\n\n<p><em>Gagnants : Young Bucks<\/em><\/p>\n\n\n\n<p>&#8211; En coulisses, Renee Paquette est avec Toni Storm pour avoir ses commentaires sur le tournoi Owen Hart. Storm souhaite bonne chance aux deux catcheuses ce soir. Toni Storm lance un Open Challenge pour Collision samedi si quelqu&rsquo;un veut l&rsquo;affronter. Queen Aminata arrive et dit qu&rsquo;elle accepte l&rsquo;offre.<\/p>\n\n\n\n<p>&#8211; Le&nbsp;<strong>Hurt Syndicate<\/strong>&nbsp;arrive sur le ring. MVP dit qu&rsquo;ils ont une annonce \u00e0 faire. Au nom du standard de l&rsquo;excellence Shelton Benjamin et du tout puissant Bobby Lashley, ils sont le Hurt Syndicate et ils blessent des gens. Ils sont tellement fort que tous les adversaires ne reviennent pas apr\u00e8s leur match. Les Gates of Agony disaient aimer se faire blesser, mais c&rsquo;\u00e9tait stupide. On va plus revoir les Gates of Agony dans un avenir proche. MVP passe le micro \u00e0 Lashley qui veut parler, mais une voiture arrive sur le parking. On voit sur le TitanTron MJF sortir de sa voiture et il arrive sur le ring. MJF dit qu&rsquo;on sait tous que le Hurt Syndicate s&rsquo;est bien amus\u00e9 la semaine derni\u00e8re. S&rsquo;ils veulent bien s&rsquo;amuser pour tout le reste de leur vie, il a seulement besoin de trois pouces vers le haut. MVP dit qu&rsquo;ils vont le refaire encore une fois. MVP l\u00e8ve le pouce. Benjamin l\u00e8ve aussi le pouce ! MJF est heureux. Benjamin dit qu&rsquo;il n&rsquo;a pas lev\u00e9 son pouce pour une montre, il a lev\u00e9 son pouce \u00e0 cause de MVP, MJF ne doit pas l&rsquo;oublier.<\/p>\n\n\n\n<p>MJF dit qu&rsquo;on aime tous MVP, il comprend. On aime aussi notre bon ami Bob. MJF dit que c&rsquo;est le moment de la r\u00e9ponse. Lashley h\u00e9site. MJF dit qu&rsquo;il pense savoir la r\u00e9ponse de Lashley, il veut lui dire une chose avant. S&rsquo;il rejoint le Hurt Syndicate, ils auront tout le respect et tout l&rsquo;or. Oui Lashley am\u00e8ne beaucoup, mais il am\u00e8ne autre chose. Il connait cet endroit meilleur que tout le monde, il sait comment gagner mieux que tout le monde.\u00a0Lashley le laisse entrer dans le clan, ils ne vont pas diriger seulement la AEW, ce sera tout le catch. Il est pr\u00eat d&rsquo;admettre qu&rsquo;il a \u00e9t\u00e9 arrogant avec le rejet de Lashley, mais il est pr\u00eat \u00e0 dire qu&rsquo;il est d\u00e9sol&#8230; il est d\u00e9sol\u00e9 ! MJF dit qu&rsquo;il peut donner sa belle voiture \u00e0 Lashley aussi si Lashley lui donne un pouce vers le haut. Lashley dit qu&rsquo;il veut aller regarder la voiture avant.\u00a0MJF et le Hurt Syndicate se dirigent dans les coulisses pour aller sur le parking.<\/p>\n\n\n\n<p>&#8211; Dans le stationnement car parking c&rsquo;est en anglais, int\u00e9rieur de l&rsquo;ar\u00e9na, MVP et le Hurt Syndicate arrive. MJF lui fait le tour de la voiture sportive.\u00a0Lashley prend les cl\u00e9s pour regarder l&rsquo;int\u00e9rieur. Lashley avance un peu avec la voiture. MJF lui dit de faire le pouce vers le haut avant. Lashley fait le pouce vers le cas et se casse avec la voiture avec Benjamin\u00a0!<\/p>\n\n\n\n<p>&#8211; De retour, en coulisses, Renee Paquette demande&nbsp;<strong>\u00e0 Adam Page<\/strong>&nbsp;ses commentaires sur la demi-finale contre Kyle Fletcher. Adam Page dit qu&rsquo;au moment o\u00f9 il va voir Fletcher va il va l&rsquo;enterrer. MJF arrive et dit qu&rsquo;il voulait f\u00e9liciter Adam Page sur sa nouvelle coupe de cheveux comme s&rsquo;il a rencontr\u00e9 sa femme \u00e0 un anniversaire. Adam Page dit qu&rsquo;il est dans une interview, MJF devrait retourner dans sa voiture s&rsquo;il n&rsquo;a rien d&rsquo;intelligent \u00e0 dire. MJF dit que Page est bien dr\u00f4le. Il a une blague sur Adam Page aussi, Page entre dans le tournoi Owen Hart seulement pour regarder MJF qui va passer par la porte arri\u00e8re pour devenir World Champion. Page dit qu&rsquo;il ne sait pas comment le Hurt Syndicate peut lui redonner un match de titre. Mais apr\u00e8s Revolution, MJF a compris qu&rsquo;il ne peut pas gagner de match. MJF dit que Page est un idiot, donc c&rsquo;est normal que Page ne comprend pas cette histoire du Hurt Syndicate. Page veut parler de la d\u00e9faite, mais ils sont 1-1. Page se pense un dur \u00e0 cuire car il est dans le tournoi Owen Hart. Mais si Adam Page atteint la finale, il va encore tomber sous la pression.<\/p>\n\n\n\n<p><strong>Will Ospreay et Brody King vs Konosuke Takeshita et Josh Alexander<em>&nbsp;accompagn\u00e9 de Don Callis et Lance Archer<\/em><\/strong><\/p>\n\n\n\n<p>\u00c0 la fin du combat, Takeshita et Alexander font un Double Rolling Elbow sur King pour le couvrir, mais il r\u00e9siste \u00e0 deux. Takeshita enchaine avec un Running Knee sur King. Alexander compl\u00e8te avec son C4 sur King pour le compte de trois.<\/p>\n\n\n\n<p><em>Gagnants : Konosuke Takeshita et Josh Alexander<\/em><\/p>\n\n\n\n<p>&#8211; Apr\u00e8s le combat, Takeshita et Alexander attaquent encore King. Will Ospreay veut lui venir en aide, mais Archer fait un ChokeSlam \u00e0 Ospreay. La musique de Kyle Fletcher se lance et il arrive sur le ring. Fletcher veut s&rsquo;amuser avec Ospreay, mais Adam Hangman Page arrive. Page s&rsquo;approche du ring, mais Trent Beretta et Rocky Romero arrivent pour l&rsquo;attaquer dans le dos. C&rsquo;est 6 contre 1 sur Page. Fletcher termine avec un Brain Buster sur Page.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>Demie Finale : Tournoi Owen Hart <\/strong><br>Jamie Hayter vs Kris Statlander<\/p>\n\n\n\n<p>\u00c0 la fin du combat, Statlanter monte sur le coin, mais Hayter se rel\u00e8ve et la frappe. Hayter veut faire une Superplex, mais Statlander la repousse en bas du ring. Statlander se lance du coin, mais Hayter la bloque avec une Clothesline. Hayter enchaine avec une seconde Clothesline pour le compte de trois.<\/p>\n\n\n\n<p><em>Gagnante : Jamie Hayter<\/em><\/p>\n\n\n\n<p>C&rsquo;est officiel, Mercedes Mon\u00e9 et Jamie Hayter vont s&rsquo;affronter dans la finale du tournoi Owen Hart \u00e0 Double or Nothing.<\/p>\n\n\n\n<p>Mercedes Mon\u00e9 arrive sur la sc\u00e8ne pour faire un face \u00e0 face avec Hayter. Le show se termine ainsi.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p class=\"has-text-align-center has-medium-font-size\"><strong><a href=\"https:\/\/www.jdx.info\/lutte\/2025\/04\/23\/reprive-video-pour-le-aew-dynamite-du-23-avril-2025\/\" target=\"_blank\" rel=\"noreferrer noopener\">Pour voir Dynamite, cliquez ici<\/a><\/strong><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-info-lutte wp-block-embed-info-lutte\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"LvsL3Rn7li\"><a href=\"https:\/\/www.jdx.info\/lutte\/2025\/04\/23\/reprive-video-pour-le-aew-dynamite-du-23-avril-2025\/\">Reprive Vid\u00e9o pour le AEW Dynamite du 23 Avril 2025 !<\/a><\/blockquote><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"\u00ab\u00a0Reprive Vid\u00e9o pour le AEW Dynamite du 23 Avril 2025 !\u00a0\u00bb &#8212; Info-Lutte\" src=\"https:\/\/www.jdx.info\/lutte\/2025\/04\/23\/reprive-video-pour-le-aew-dynamite-du-23-avril-2025\/embed\/#?secret=w9Cg5rFrxX#?secret=LvsL3Rn7li\" data-secret=\"LvsL3Rn7li\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>AEW Dynamite Nouvelle-Orl\u00e9ans, Louisiane, 23 avril 2025Les commentateurs sont Ian Riccaboni, Taz et Excalibur. &#8211; Le AEW Dynamite d\u00e9bute avec Tony Schiavone sur le ring et il nous souhaite la bienvenue au rappeur\u00a0Master P qui souhaite la bienvenue \u00e0 AEW Dynamite. Master P dit qu&rsquo;il est heureux de nous pr\u00e9senter les nouveaux champions Trios AEW,&#8230;<\/p>\n","protected":false},"author":37048,"featured_media":116361,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38,24,30,93,21],"tags":[],"ppma_author":[297],"class_list":["post-116360","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aew","category-aew-impact-njpw-roh","category-ex-wwe","category-nxt-ex-wwe","category-resultats"],"authors":[{"term_id":297,"user_id":37048,"is_guest":0,"slug":"mattante","display_name":"Mattias Antoinette","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/db141441570c9bdee0787662393889dfbc3d6c721d3318f2402846725b7b664e?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/116360","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/37048"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=116360"}],"version-history":[{"count":1,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/116360\/revisions"}],"predecessor-version":[{"id":116362,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/116360\/revisions\/116362"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/116361"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=116360"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=116360"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=116360"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=116360"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}