{"id":115323,"date":"2025-04-10T19:59:00","date_gmt":"2025-04-10T23:59:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=115323"},"modified":"2025-04-13T15:30:37","modified_gmt":"2025-04-13T19:30:37","slug":"resultats-et-vide-pour-le-tna-impact-wrestling-du-10-avril-2025","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2025\/04\/10\/resultats-et-vide-pour-le-tna-impact-wrestling-du-10-avril-2025\/","title":{"rendered":"R\u00e9sultats et Vid\u00e9 pour le TNA Impact Wrestling du 10 Avril 2025 !"},"content":{"rendered":"\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.jdx.info\/lutte\/2025\/04\/10\/reprise-video-pour-le-tna-impact-wrestling-du-10-avril-2025\/\"><strong>Pour voir Impact, cliquez ici.<\/strong><\/a><\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">1. Ouverture et Promos d&rsquo;Accueil<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Introduction par Ethan Page :<\/strong><br>Ethan Page ouvre le show en d\u00e9clarant fi\u00e8rement son retour \u00e0 TNA, rappelant qu\u2019il a fait ses premi\u00e8res armes ici et qu\u2019il est l\u2019un des plus longs d\u00e9tenteurs du TNA World Tag Team Championship.\n<ul class=\"wp-block-list\">\n<li><strong>Dialogue marquant :<\/strong><br>Il pr\u00e9cise qu\u2019il n\u2019est pas l\u00e0 pour ressasser le pass\u00e9 et qu\u2019\u00e0 Rebellion il deviendra TNA World Champion. Il ajoute avoir d\u00e9j\u00e0 battu Joe Hendry, affirmant avoir \u00ab\u00a0d\u00e9crypt\u00e9\u00a0\u00bb son jeu.<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><strong>Intervention de Kazarian :<\/strong><br>Kazarian fait irruption pour remettre en cause la pr\u00e9tention d\u2019Ethan Page, le traitant de \u00ab\u00a0feeble-minded idiot\u00a0\u00bb et rappelant qu\u2019il est le \u00ab King of TNA \u00bb.<\/li>\n\n\n\n<li><strong>Apparition de Santino Marella :<\/strong><br>Il intervient pour \u00e9voquer Joe Hendry et mentionne que les discussions sur \u00ab\u00a0Unbreakable\u00a0\u00bb et \u00ab\u00a0Rebellion\u00a0\u00bb auront des r\u00e9percussions pour tous.<\/li>\n<\/ul>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h2 class=\"wp-block-heading\">2. Segment Backstage<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Backstage avec Gia Miller et Steve Maclin :<\/strong><br>Gia est vue avec Steve Maclin. Ce dernier affiche son intention de \u00ab\u00a0taguer, baguer et empiler les corps\u00a0\u00bb.<\/li>\n\n\n\n<li><strong>Mention d\u2019Eric Young et The System :<\/strong><br>Eric Young pr\u00e9cise que The System interviendra pour soutenir Maclin, bien que Maclin d\u00e9clare ne pas avoir besoin de renforts.<\/li>\n<\/ul>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h2 class=\"wp-block-heading\">3. Match 1 \u2013 Mustafa Ali vs. Ace Austin<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>D\u00e9roul\u00e9 du match :<\/strong><br>Le match d\u00e9bute avec Ace Austin distrait par The Great Hands, permettant \u00e0 Mustafa Ali de prendre l\u2019avantage gr\u00e2ce \u00e0 une combinaison de dropkicks, de rolling neckbreakers et d\u2019actions a\u00e9roport\u00e9es.\n<ul class=\"wp-block-list\">\n<li>Austin r\u00e9agit avec des comp\u00e9tences telles que le Click Click Boom, la Monkey Flip ainsi qu\u2019un Suicide Dive pour tenter de renverser Ali.<\/li>\n\n\n\n<li>En cours de combat, Ali encha\u00eene plusieurs attaques (schoolboy, clotheslines, move en ext\u00e9rieur) et, profitant des interf\u00e9rences, l\u2019action d\u00e9g\u00e9n\u00e8re.<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><strong>Issue et r\u00e9sultat :<\/strong>\n<ul class=\"wp-block-list\">\n<li>Ace Austin remporte le match par <strong>disqualification<\/strong> suite aux interventions ext\u00e9rieures\u202f: alors qu\u2019Austin est \u00e9tabli dans un coin par The Great Hands, Ali tente d\u2019utiliser une chaise en acier.<\/li>\n\n\n\n<li>Apr\u00e8s le match, alors qu\u2019Ace reste dans le coin, l\u2019agitation provoqu\u00e9e par les interf\u00e9rences (l\u2019arriv\u00e9e de Santana qui arrache la chaise des mains d\u2019Ali) force ce dernier \u00e0 se retirer avec Order 4, quittant la sc\u00e8ne dans sa voiture conduite par Santana.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h2 class=\"wp-block-heading\">4. Match 2 \u2013 Moose vs. Cody Deaner pour le X-Division Championship<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Contexte pr\u00e9-match :<\/strong>\n<ul class=\"wp-block-list\">\n<li>Moose et Cody Deaner s\u2019affrontent dans un 8-man tag qui se transforme en match pour le titre de la X-Division.<\/li>\n\n\n\n<li>JDC offre \u00e0 Cody Deaner un poste de \u201clackey\u201d au sein de The System, mais celui-ci d\u00e9clare que ce choix reviendra au public et qu\u2019il pr\u00e9f\u00e9rerait obtenir un match pour le titre.<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><strong>D\u00e9roul\u00e9 du match :<\/strong>\n<ul class=\"wp-block-list\">\n<li>Moose domine Cody Deaner, utilisant notamment des powerbombs et esquivant les tentatives de contre.<\/li>\n\n\n\n<li>Cody s\u2019\u00e9chappe hors du ring \u00e0 plusieurs reprises et l\u2019horloge signalant \u00ab 2 minutes \u00bb expire.<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><strong>R\u00e9sultat :<\/strong>\n<ul class=\"wp-block-list\">\n<li><strong>Moose<\/strong> remporte le match par <strong>spear<\/strong> et conserve le TNA X-Division Championship.<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><strong>Apr\u00e8s-match :<\/strong>\n<ul class=\"wp-block-list\">\n<li>The System attaque Cody Deaner, mais l\u2019intervention des Rascalz permet de contrer cet assaut.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h2 class=\"wp-block-heading\">5. Match 3 \u2013 The Rascalz vs. JDC et Brian Myers<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>D\u00e9roul\u00e9 :<\/strong>\n<ul class=\"wp-block-list\">\n<li>Le match met en sc\u00e8ne des \u00e9changes intenses : Wentz, membre des Rascalz, applique le Bronco Buster sur JDC, puis Myers entre en sc\u00e8ne pour effectuer un Side Russian Leg Sweep sur Miguel.<\/li>\n\n\n\n<li>L\u2019action se caract\u00e9rise par de nombreux tags, des prises collectives comme les superkicks et suicide dives \u00e0 l\u2019ext\u00e9rieur du ring.<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><strong>R\u00e9sultat :<\/strong>\n<ul class=\"wp-block-list\">\n<li><strong>JDC et Brian Myers<\/strong> remportent le match par <strong>pinfall<\/strong> apr\u00e8s une s\u00e9rie d\u2019\u00e9changes coordonn\u00e9s.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h2 class=\"wp-block-heading\">6. Match 4 \u2013 Triple Threat : A.J. Francis vs. Mance Warner vs. Sami Callihan<\/h2>\n\n\n\n<p><em>(Match du TNA International Championship Tournament)<\/em><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>D\u00e9roul\u00e9 et \u00e9changes :<\/strong>\n<ul class=\"wp-block-list\">\n<li>Le match s\u2019organise en triple menace avec des attaques rapides : Sami Callihan frappe Francis, tandis qu\u2019A.J. Francis contre les assauts de Mance Warner.<\/li>\n\n\n\n<li>Des moments forts incluent l\u2019usage de la chaise en acier par Mance, des big boots d\u2019A.J. Francis et des man\u0153uvres de Sami, qui, \u00e0 un moment, passe un pouce \u00e0 Mance au niveau de l\u2019\u0153il.<\/li>\n\n\n\n<li>Le match est ponctu\u00e9 par une lutte pour d\u00e9faire simultan\u00e9ment ses adversaires, avec notamment un TFL (move de Francis) d\u00e9cisif.<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><strong>R\u00e9sultat :<\/strong>\n<ul class=\"wp-block-list\">\n<li><strong>A.J. Francis<\/strong> d\u00e9croche la victoire, se qualifiant pour la finale du tournoi du TNA International Championship.<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><strong>Suite backstage :<\/strong>\n<ul class=\"wp-block-list\">\n<li>Sami Callihan, dans une interview backstage avec Santino Marella, \u00e9voque une altercation impliquant Steph de Lander (qui lui aurait jet\u00e9 du caf\u00e9 br\u00fblant au visage, endommageant sa r\u00e9tine) et r\u00e9clame un Barbed Wire Massacre \u00e0 Unbreakable contre Mance Warner.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h2 class=\"wp-block-heading\">7. Match 5 \u2013 Ryan Nemeth vs. Leon Slater<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>D\u00e9roul\u00e9 :<\/strong>\n<ul class=\"wp-block-list\">\n<li>Leon Slater prend rapidement l\u2019ascendant en frappant Ryan Nemeth dans le coin, encha\u00eenant des chops et des lariats.<\/li>\n\n\n\n<li>Nemeth tente une r\u00e9ponse avec un DDT et m\u00eame la r\u00e9cup\u00e9ration d\u2019une chaise, mais l\u2019intervention des Hardy Boyz s\u2019impose.<\/li>\n\n\n\n<li>Les Hardy Boyz, apr\u00e8s avoir retir\u00e9 la chaise et effectu\u00e9 des mouvements d\u00e9cisifs (Twist of Fate et Swanton 450), permettent \u00e0 Slater de sceller le match.<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><strong>R\u00e9sultat :<\/strong>\n<ul class=\"wp-block-list\">\n<li><strong>Leon Slater<\/strong> remporte le match par <strong>pinfall<\/strong>.<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><strong>Apr\u00e8s-match :<\/strong>\n<ul class=\"wp-block-list\">\n<li>Les Hardy Boyz c\u00e9l\u00e8brent leur victoire en rejoignant Slater dans le ring.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h2 class=\"wp-block-heading\">8. Match 6 \u2013 Eddie Edwards vs. Steve Maclin<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>D\u00e9roul\u00e9 du match :<\/strong>\n<ul class=\"wp-block-list\">\n<li>Steve Maclin entame fort en ass\u00e9nant un basement clothesline, mais Eddie Edwards r\u00e9agit en r\u00e9pondant avec un Blue Thunder Bomb.<\/li>\n\n\n\n<li>Plusieurs s\u00e9quences d\u2019\u00e9changes de coups, incluant Thesz Press et Olympic Slam, se succ\u00e8dent.<\/li>\n\n\n\n<li>Alisha intervient \u00e0 plusieurs reprises en distrayant Maclin, permettant \u00e0 Edwards de poser ses assauts.<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><strong>Climax et r\u00e9sultat :<\/strong>\n<ul class=\"wp-block-list\">\n<li>Malgr\u00e9 plusieurs tentatives de Maclin pour stopper Edwards (avec notamment une mise en place pour un Crosshairs), Eddie Edwards parvient \u00e0 obtenir la victoire par <strong>pinfall<\/strong>.<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><strong>Post-match :<\/strong>\n<ul class=\"wp-block-list\">\n<li>Eric Young fait son entr\u00e9e avec The Northern Armory et, dans un geste symbolique, jette son masque dans le ring \u00e0 Maclin avant de quitter la sc\u00e8ne.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h2 class=\"wp-block-heading\">9. Segment de Cl\u00f4ture \u2013 Promos et D\u00e9clarations de Joe Hendry<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Joe Hendry prend la parole :<\/strong>\n<ul class=\"wp-block-list\">\n<li>Hendry annonce qu\u2019il a subi une grave blessure \u00e0 la coiffe rotator cuff et d\u00e9clare que, malgr\u00e9 les recommandations m\u00e9dicales de ne pas concourir, il d\u00e9fendra le TNA World Championship \u00e0 Rebellion.<\/li>\n\n\n\n<li>Il affirme que s\u2019il ne peut pas d\u00e9fendre le titre, il ne m\u00e9rite m\u00eame pas de le porter.<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><strong>Intervention de Kazarian :<\/strong>\n<ul class=\"wp-block-list\">\n<li>Kazarian arrive pour critiquer Joe Hendry, insinuant que ce dernier ne sera m\u00eame pas capable de marcher et qu\u2019il ne pourra pas rivaliser avec \u00ab le king of TNA \u00bb.<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><strong>Cl\u00f4ture du show :<\/strong>\n<ul class=\"wp-block-list\">\n<li>Hendry annonce qu\u2019\u00e0 Unbreakable, un match par \u00e9quipes aura lieu opposant Kazarian et Tessa Blanchard \u00e0 Masha Slamovich et lui-m\u00eame.<\/li>\n\n\n\n<li>Le show se conclut sur ces provocations, invitant les fans \u00e0 suivre la suite de la saga.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h2 class=\"wp-block-heading\">Conclusion<\/h2>\n\n\n\n<p>Le TNA IMPACT du 10 avril 2025 a \u00e9t\u00e9 riche en action, en promos percutantes et en rebondissements :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Ethan Page revient en force avec des d\u00e9clarations ambitieuses, tandis que Kazarian et Santino Marella viennent le contrer.<\/li>\n\n\n\n<li>Plusieurs matchs, dont le triple threat du tournoi international et le duel pour le X-Division Championship, ont offert des s\u00e9quences dynamiques et de fortes \u00e9motions.<\/li>\n\n\n\n<li>Un segment final avec Joe Hendry ouvre la voie \u00e0 une confrontation majeure \u00e0 Unbreakable, laissant pr\u00e9sager des enjeux importants pour le TNA World Championship.<\/li>\n<\/ul>\n\n\n\n<p>Ce r\u00e9sum\u00e9 refl\u00e8te l&rsquo;ordre du show, en soulignant \u00e0 la fois les r\u00e9sultats de chaque rencontre et les dialogues qui annoncent la suite de la story TNA.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p class=\"has-text-align-center has-medium-font-size\"><a href=\"https:\/\/www.jdx.info\/lutte\/2025\/04\/10\/reprise-video-pour-le-tna-impact-wrestling-du-10-avril-2025\/\"><strong>Pour voir Impact, cliquez ici.<\/strong><\/a><\/p>\n\n\n\n<figure class=\"wp-block-embed aligncenter is-type-wp-embed is-provider-info-lutte wp-block-embed-info-lutte\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"fLVZ0SZZeU\"><a href=\"https:\/\/www.jdx.info\/lutte\/2025\/04\/10\/reprise-video-pour-le-tna-impact-wrestling-du-10-avril-2025\/\">Reprise Vid\u00e9o pour le TNA Impact Wrestling du 10 Avril 2025 !<\/a><\/blockquote><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"\u00ab\u00a0Reprise Vid\u00e9o pour le TNA Impact Wrestling du 10 Avril 2025 !\u00a0\u00bb &#8212; Info-Lutte\" src=\"https:\/\/www.jdx.info\/lutte\/2025\/04\/10\/reprise-video-pour-le-tna-impact-wrestling-du-10-avril-2025\/embed\/#?secret=ZAMnHuGtD2#?secret=fLVZ0SZZeU\" data-secret=\"fLVZ0SZZeU\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n\n\n\n<p class=\"has-small-font-size\"><em>* Sources : WrestlingHeadlines.com (transcription compl\u00e8te par Matt Boone)<\/em><\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>1. Ouverture et Promos d&rsquo;Accueil 2. Segment Backstage 3. Match 1 \u2013 Mustafa Ali vs. Ace Austin 4. Match 2 \u2013 Moose vs. Cody Deaner pour le X-Division Championship 5. Match 3 \u2013 The Rascalz vs. JDC et Brian Myers 6. Match 4 \u2013 Triple Threat : A.J. Francis vs. Mance Warner vs. Sami Callihan&#8230;<\/p>\n","protected":false},"author":609,"featured_media":115324,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24,84,30,187,93,21,41],"tags":[],"ppma_author":[295],"class_list":["post-115323","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aew-impact-njpw-roh","category-ecw","category-ex-wwe","category-legends","category-nxt-ex-wwe","category-resultats","category-tna-impact"],"authors":[{"term_id":295,"user_id":609,"is_guest":0,"slug":"rodrigo","display_name":"Rodrigue Tousignant","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/51fe284bb6dbe8a6b4c2bf998ad658f4a9cd24b7e58f15ec85888070c7340ce6?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/115323","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/609"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=115323"}],"version-history":[{"count":1,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/115323\/revisions"}],"predecessor-version":[{"id":115325,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/115323\/revisions\/115325"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/115324"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=115323"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=115323"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=115323"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=115323"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}